{"id":98130,"date":"2022-09-09T17:36:51","date_gmt":"2022-09-09T15:36:51","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/almanacco-navale-del-xxi-secolo-giuliano-da-fr-9788862887595\/"},"modified":"2026-03-14T02:22:00","modified_gmt":"2026-03-14T01:22:00","slug":"almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/","title":{"rendered":"almanacco navale del xxi secolo"},"content":{"rendered":"<p>Dopo il 1945, gli Stati Uniti possedevano quella che di gran lunga era la maggiore potenza navale del mondo: la US Navy, vera erede della Royal Navy, con la quale Londra aveva dominato i mari per quasi 250 anni. La grande flotta giapponese e la Marina Tedesca non esistevano pi&ugrave;, spazzate via dagli eventi bellici e politici, mentre quelle italiana e francese sopravvivevano sulle rovine delle ambizioni degli anni Venti e Trenta, al pari della mal bilanciata Marina Sovietica. Vi erano anche realt&agrave; pi&ugrave; piccole ma importanti, come quelle olandese e svedese, mentre di l&igrave; a poco sarebbero nate marine presto provate in guerra come quelle indiana e israeliana.<\/p>\n<p><strong>Questo Almanacco fotografa la rivoluzione degli assetti marittimi mondiali dopo la Seconda Guerra Mondiale<\/strong>; un saggio storico dal taglio <strong>divulgativo <\/strong>capace di fornire <strong>sintetici e completi dati tecnici.<\/strong> L&#8217;autore descrive le <strong>evoluzioni tecnologiche e operative<\/strong>, analizzando Marina per Marina in ordine alfabetico, dall&#8217;Albania allo Yemen. Grande spazio &egrave; dedicato alla Marina Italiana e alle principali marine mondiali quali Stati Uniti e Cina, seguite da Gran Bretagna, Francia, Giappone, Russia, India, Australia, Sud Corea, Germania, Brasile, Spagna, Turchia. Vi sono indicazioni sull&#8217;<strong>attuale struttura<\/strong>, sui <strong>programmi futuri<\/strong>, sull&#8217;<strong>esperienza operativa<\/strong> di questi decenni.<\/p>\n<p>Un volume che tratta anche delle marine che non esistono pi&ugrave;, come quelle delle defunte Germania Est e Iugoslavia, ma anche di quella etiope, rimasta senza sbocco sul mare, e dei pi&ugrave; recenti sviluppi riguardanti il conflitto ucraino attualmente in corso.<\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>dalla guerra fredda alla crisi ucraina<\/p>\n<p class=\"autore\"><span>Author: <\/span>giuliano da fr\u00e8<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Casa Editrice Odoya<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862887595<\/p>\n","protected":false},"featured_media":131074,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3053],"product_tag":[],"class_list":{"0":"post-98130","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-from-1945-onwards","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>almanacco navale del xxi secolo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"almanacco navale del xxi secolo\" \/>\n<meta property=\"og:description\" content=\"Subtitle: dalla guerra fredda alla crisi ucrainaAuthor: giuliano da fr\u00e8Publisher: Casa Editrice OdoyaISBN: 9788862887595\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:22:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"516\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;42,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\\\/\",\"name\":\"almanacco navale del xxi secolo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3.jpg\",\"datePublished\":\"2022-09-09T15:36:51+00:00\",\"dateModified\":\"2026-03-14T01:22:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3.jpg\",\"width\":516,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"almanacco navale del xxi secolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"42.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862887595\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"almanacco navale del xxi secolo - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"almanacco navale del xxi secolo","og_description":"Subtitle: dalla guerra fredda alla crisi ucrainaAuthor: giuliano da fr\u00e8Publisher: Casa Editrice OdoyaISBN: 9788862887595","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:22:00+00:00","og_image":[{"width":516,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;42,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/","name":"almanacco navale del xxi secolo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3.jpg","datePublished":"2022-09-09T15:36:51+00:00","dateModified":"2026-03-14T01:22:00+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3.jpg","width":516,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/almanacco-navale-del-xxi-secolo-giuliano-da-fre-9788862887595\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"almanacco navale del xxi secolo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"42.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788862887595","product_condition":"new"},"df_price":42,"df_sale_price":"","df_regular_price":42,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/almanaco-navale-del-xxi-secolo-dalla-guerra-fredda-alla-crisi-ucraina-da-fre-3-221x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/98130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=98130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/131074"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=98130"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=98130"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=98130"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=98130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}