{"id":98089,"date":"2022-10-14T13:53:20","date_gmt":"2022-10-14T11:53:20","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/"},"modified":"2026-03-14T02:19:29","modified_gmt":"2026-03-14T01:19:29","slug":"stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/","title":{"rendered":"stella e&#8230; il diritto di splendere"},"content":{"rendered":"<p><em>Ogni diritto &egrave; un dovere: &egrave; un dovere rispettarlo, &egrave; un dovere goderne a pieno ed &egrave; un dovere difenderlo!<\/em><\/p>\n<p>In questa esilarante avventura <strong>Stella Marina<\/strong> si trover&agrave; di fronte ad <strong>un&rsquo;importante scelta: combattere o scappare<\/strong>?<\/p>\n<p><em>Stella e&hellip;il diritto di splendere<\/em>, seguito di <em>Stella Marina la scuola<\/em>, &egrave; un&rsquo;avventura da <strong>leggere<\/strong>, <strong>colorare <\/strong>e soprattutto da &ldquo;<strong>giocare<\/strong>&rdquo; per imparare quali siano i diritti dei bambini!<\/p>\n<p>Comprese <strong>28 carte illustrate<\/strong> con cui giocare e imparare i <strong>diritti dei bambini<\/strong>!<\/p>\n<p>Et&agrave;: <strong>5+<\/strong><\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>paola curia &#8211; illustrazioni di monica bauleo<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>saremo alberi editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791280465955<\/p>\n","protected":false},"featured_media":124266,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2929,2614],"product_tag":[],"class_list":{"0":"post-98089","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-3-6-years-games","7":"product_cat-illustrated-books-and-fiction","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>stella e... il diritto di splendere - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"stella e... il diritto di splendere\" \/>\n<meta property=\"og:description\" content=\"Author: paola curia - illustrazioni di monica bauleoPublisher: saremo alberi editoreISBN: 9791280465955\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/stella-e-il-diritto-di-splendere-curia-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"546\" \/>\n\t<meta property=\"og:image:height\" content=\"715\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\\\/\",\"name\":\"stella e... il diritto di splendere - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/stella-e-il-diritto-di-splendere-curia-3.jpg\",\"datePublished\":\"2022-10-14T11:53:20+00:00\",\"dateModified\":\"2026-03-14T01:19:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/stella-e-il-diritto-di-splendere-curia-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/stella-e-il-diritto-di-splendere-curia-3.jpg\",\"width\":546,\"height\":715},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"stella e&#8230; il diritto di splendere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791280465955\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"stella e... il diritto di splendere - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"stella e... il diritto di splendere","og_description":"Author: paola curia - illustrazioni di monica bauleoPublisher: saremo alberi editoreISBN: 9791280465955","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:19:29+00:00","og_image":[{"width":546,"height":715,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/stella-e-il-diritto-di-splendere-curia-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/","name":"stella e... il diritto di splendere - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/stella-e-il-diritto-di-splendere-curia-3.jpg","datePublished":"2022-10-14T11:53:20+00:00","dateModified":"2026-03-14T01:19:29+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/stella-e-il-diritto-di-splendere-curia-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/stella-e-il-diritto-di-splendere-curia-3.jpg","width":546,"height":715},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/stella-e-il-diritto-di-splendere-paola-curia-illustrazioni-di-monica-bauleo-9791280465955\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"stella e&#8230; il diritto di splendere"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791280465955","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/stella-e-il-diritto-di-splendere-curia-3-229x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/98089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=98089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/124266"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=98089"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=98089"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=98089"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=98089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}