{"id":97799,"date":"2023-03-02T17:15:32","date_gmt":"2023-03-02T16:15:32","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/"},"modified":"2026-03-14T02:04:32","modified_gmt":"2026-03-14T01:04:32","slug":"dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/","title":{"rendered":"dallo stretto di gibilterra alle baleari &#8211; da cadice a barcellona &#8211; da capo spartel a djidjelli n. 431 (1972)"},"content":{"rendered":"<p>Carta nautica dell&rsquo;Istituto Idrografico della Marina Italiana edita nel 1940. L&rsquo;esemplare a nostra disposizione &egrave; stato ristampato e aggiornato nel 1976.<\/p>\n<p>Annotazioni sparse a matita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 113,5&#215;74<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>istituto idrografico della marina (IIM)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>IDRO431MOD<\/p>\n","protected":false},"featured_media":75754,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2461],"product_tag":[],"class_list":{"0":"post-97799","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-modern-antiques","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>dallo stretto di gibilterra alle baleari - da cadice a barcellona - da capo spartel a djidjelli n. 431 (1972) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dallo stretto di gibilterra alle baleari - da cadice a barcellona - da capo spartel a djidjelli n. 431 (1972)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 113,5x74Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO431MOD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:04:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1121\" \/>\n\t<meta property=\"og:image:height\" content=\"741\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;140,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\\\/\",\"name\":\"dallo stretto di gibilterra alle baleari - da cadice a barcellona - da capo spartel a djidjelli n. 431 (1972) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1.jpg\",\"datePublished\":\"2023-03-02T16:15:32+00:00\",\"dateModified\":\"2026-03-14T01:04:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1.jpg\",\"width\":1121,\"height\":741},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"dallo stretto di gibilterra alle baleari &#8211; da cadice a barcellona &#8211; da capo spartel a djidjelli n. 431 (1972)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"140.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"IDRO431MOD\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"dallo stretto di gibilterra alle baleari - da cadice a barcellona - da capo spartel a djidjelli n. 431 (1972) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"dallo stretto di gibilterra alle baleari - da cadice a barcellona - da capo spartel a djidjelli n. 431 (1972)","og_description":"Subtitle: cm 113,5x74Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO431MOD","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:04:32+00:00","og_image":[{"width":1121,"height":741,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;140,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/","name":"dallo stretto di gibilterra alle baleari - da cadice a barcellona - da capo spartel a djidjelli n. 431 (1972) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1.jpg","datePublished":"2023-03-02T16:15:32+00:00","dateModified":"2026-03-14T01:04:32+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1.jpg","width":1121,"height":741},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/dallo-stretto-di-gibilterra-alle-baleari-da-cadice-a-barcellona-da-capo-spartel-a-djidjelli-n-431-1972-idro431mod\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"dallo stretto di gibilterra alle baleari &#8211; da cadice a barcellona &#8211; da capo spartel a djidjelli n. 431 (1972)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"140.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"IDRO431MOD","product_condition":"new"},"df_price":140,"df_sale_price":"","df_regular_price":140,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/dallo-stretto-di-gibilterra-alle-baleari-n-431-1-300x198.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/97799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=97799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/75754"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=97799"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=97799"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=97799"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=97799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}