{"id":97536,"date":"2023-05-24T18:01:57","date_gmt":"2023-05-24T16:01:57","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/educare-al-mare-aa-vv-9788881074785\/"},"modified":"2026-03-14T01:52:19","modified_gmt":"2026-03-14T00:52:19","slug":"educare-al-mare-aa-vv-9788881074785","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/","title":{"rendered":"educare al mare"},"content":{"rendered":"<p><strong>A cura di Enrico Squarcina.<\/strong><\/p>\n<p>Il nostro pianeta si chiama Terra ma, nonostante il perdurante atteggiamento terracentrico degli umani, la vita su di esso dipende in gran parte dal mare. Proprio per questo l&rsquo;Assemblea Generale delle Nazioni Unite ha promulgato per la decade 2021-2030 il&nbsp;<em>Decennio delle scienze oceaniche per lo sviluppo sostenibile<\/em>&nbsp;il cui scopo &egrave; quello di stimolare la ricerca scientifica sulla parte liquida del pianeta e di divulgarne la conoscenza. <strong>Promuovere la conoscenza del mare<\/strong> significa permettere a un vasto pubblico di farlo proprio in modo cognitivo e affettivo, <strong>stimolare il senso di cittadinanza oceanica <\/strong>che ci fa sentire responsabili nei confronti di quella che &egrave; la parte pi&ugrave; estesa e al tempo stesso la meno conosciuta della superficie terrestre. <strong>Si tratta non solo di conoscere ma di educare<\/strong>. Il presente volume propone al lettore una serie di contributi che illustrano <strong>esempi di politiche educative<\/strong>, tra cui quelle possibili attraverso <strong>lo sport<\/strong>, l&rsquo;analisi dell&rsquo;efficacia di alcuni<strong> metodi didattici<\/strong>, la possibilit&agrave; di utilizzare <strong>strumenti nati con finalit&agrave; ludiche<\/strong> per<strong> scopi formativi e divulgativi <\/strong>e il resoconto di <strong>esperienze educative<\/strong> significative. Ci&ograve; che li unisce, infine, non &egrave; solo l&rsquo;essere riferiti al mare, ma anche lo spirito autoriflessivo e critico che li anima.<\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>riflessioni, esperienze e progetti per un&#8217;appropriazione cognitiva, affettiva e critica degli spazi oceanici<\/p>\n<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni angelo guerini e associati<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788881074785<\/p>\n","protected":false},"featured_media":125926,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2977,2983],"product_tag":[],"class_list":{"0":"post-97536","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-environment-and-ecology","7":"product_cat-literary-essays","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>educare al mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"educare al mare\" \/>\n<meta property=\"og:description\" content=\"Subtitle: riflessioni, esperienze e progetti per un&#039;appropriazione cognitiva, affettiva e critica degli spazi oceaniciAuthor: aa.vv.Publisher: edizioni angelo guerini e associatiISBN: 9788881074785\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:52:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"778\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/educare-al-mare-aa-vv-9788881074785\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/educare-al-mare-aa-vv-9788881074785\\\/\",\"name\":\"educare al mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/educare-al-mare-aa-vv-9788881074785\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/educare-al-mare-aa-vv-9788881074785\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2.jpg\",\"datePublished\":\"2023-05-24T16:01:57+00:00\",\"dateModified\":\"2026-03-14T00:52:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/educare-al-mare-aa-vv-9788881074785\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/educare-al-mare-aa-vv-9788881074785\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/educare-al-mare-aa-vv-9788881074785\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2.jpg\",\"width\":500,\"height\":778},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/educare-al-mare-aa-vv-9788881074785\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"educare al mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788881074785\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"educare al mare - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"educare al mare","og_description":"Subtitle: riflessioni, esperienze e progetti per un'appropriazione cognitiva, affettiva e critica degli spazi oceaniciAuthor: aa.vv.Publisher: edizioni angelo guerini e associatiISBN: 9788881074785","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:52:19+00:00","og_image":[{"width":500,"height":778,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,50","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/","name":"educare al mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2.jpg","datePublished":"2023-05-24T16:01:57+00:00","dateModified":"2026-03-14T00:52:19+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2.jpg","width":500,"height":778},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/educare-al-mare-aa-vv-9788881074785\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"educare al mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.50","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788881074785","product_condition":"new"},"df_price":16.5,"df_sale_price":"","df_regular_price":16.5,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/educare-al-mare-riflessioni-esperienze-e-progetti-angelo-guerini-2-193x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/97536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=97536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/125926"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=97536"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=97536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=97536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=97536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}