{"id":97492,"date":"2023-06-09T11:54:32","date_gmt":"2023-06-09T09:54:32","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/"},"modified":"2026-03-14T01:50:15","modified_gmt":"2026-03-14T00:50:15","slug":"il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/","title":{"rendered":"il primo viaggio intorno al mondo di antonio pigafetta"},"content":{"rendered":"<p>Salito come un illustre sconosciuto a bordo della formidabile <em>Trinidad<\/em> di <strong>Ferdinando Magellano<\/strong>, in tre soli anni, dal 1519 al 1522, il vicentino Antonio Pigafetta si guadagn&ograve; la fiducia del navigatore portoghese e la fama, divenendo uno dei pi&ugrave; illustri viaggiatori della storia. Nella sua <em>Relazione del primo viaggio intorno al mondo<\/em>, egli annot&ograve; nei dettagli <strong>le scoperte, le battaglie, gli ammutinamenti e le tempeste<\/strong> che dovette affrontare la flotta di Magellano <strong>durante la prima circumnavigazione del globo<\/strong>.<\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la pi\u00f9 grande avventura di sempre<\/p>\n<p class=\"autore\"><span>Author: <\/span>camillo manfroni<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni theoria<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788854982130<\/p>\n","protected":false},"featured_media":153921,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2961,2805,3013],"product_tag":[],"class_list":{"0":"post-97492","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chronicles-logbooks-and-travel-reports","7":"product_cat-logbooks-and-travel-reports","8":"product_cat-everything-else-books-navigation-history-exploration","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il primo viaggio intorno al mondo di antonio pigafetta - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il primo viaggio intorno al mondo di antonio pigafetta\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la pi\u00f9 grande avventura di sempreAuthor: camillo manfroniPublisher: edizioni theoriaISBN: 9788854982130\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:50:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\\\/\",\"name\":\"il primo viaggio intorno al mondo di antonio pigafetta - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria.jpg\",\"datePublished\":\"2023-06-09T09:54:32+00:00\",\"dateModified\":\"2026-03-14T00:50:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria.jpg\",\"width\":500,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il primo viaggio intorno al mondo di antonio pigafetta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788854982130\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il primo viaggio intorno al mondo di antonio pigafetta - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"il primo viaggio intorno al mondo di antonio pigafetta","og_description":"Subtitle: la pi\u00f9 grande avventura di sempreAuthor: camillo manfroniPublisher: edizioni theoriaISBN: 9788854982130","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:50:15+00:00","og_image":[{"width":500,"height":744,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/","name":"il primo viaggio intorno al mondo di antonio pigafetta - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria.jpg","datePublished":"2023-06-09T09:54:32+00:00","dateModified":"2026-03-14T00:50:15+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria.jpg","width":500,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-9788854982130\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il primo viaggio intorno al mondo di antonio pigafetta"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788854982130","product_condition":"new"},"df_price":16,"df_sale_price":"","df_regular_price":16,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-primo-viaggio-intorno-al-mondo-di-antonio-pigafetta-camillo-manfroni-edizioni-theoria-202x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/97492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=97492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/153921"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=97492"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=97492"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=97492"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=97492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}