{"id":97425,"date":"2023-06-29T15:22:52","date_gmt":"2023-06-29T13:22:52","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/"},"modified":"2026-03-14T01:47:22","modified_gmt":"2026-03-14T00:47:22","slug":"storia-dei-velieri-felix-llauge-dausa-ldm1688044970","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/","title":{"rendered":"storia dei velieri"},"content":{"rendered":"<p><strong>Rara copia della prima edizione di Giovanni De Vecchi Editore del 1974 in buono stato di conservazione. In-4, legatura editoriale con copertina rigida in similpelle blu con impressioni oro al piatto anteriore e al dorso; sovraccoperta in carta plastificata (con numerosi strappi ai tagli e fortemente ingiallita in quarta) illustrata a colori con alette; con risguardi gialli illustrati in bianco (con etichetta coeva della Libreria Puccini a coprire il prezzo al risguardo posteriore); 256 pp. (con sporadiche sottolineature in evidenziatore giallo nel testo), con numerosissime illustrazioni in nero e in giallo nel testo e alcune tavole a colori fuori testo.<\/strong><\/p>\n<p><strong>Traduzione e prefazione di Dino Riva.<\/strong><\/p>\n<p><strong>Copertina a cura di Daniele Usellini.<\/strong><\/p>\n<p>Dalla prefazione:&nbsp;<em>[&#8230;] <\/em><em>Guerre e scoperte. Avventure sui mari. Fantomatici mostri con smisurate candide braccia che le divinit&agrave; dell&#8217;acque e dei venti spingono a traguardi contrastati: qui la dura, snervante ma pacifica tenzone per aprire nuove strade di comunicazione, allargare i commerci, proporre rinnovati interessi di fede e lavoro all&#8217;umanit&agrave;; l&agrave; l&#8217;impatto bestiale di legni, armi e animi tesi a cruentemente annullarsi.<\/em><\/p>\n<p><em>Felix Llaug&eacute; appunta sagacemente questi contrasti e, non celando certo la sua origine mediterranea, indulge da innamorato del mare e da acuto ricercatore a squarci di cronaca, in alcune circostanze violentemente sconcertanti, dove alla vela si sostituisce protagonista l&#8217;uomo, angolato nei risvolti pi&ugrave; deleteri delle esplosioni della sua anima.<\/em><\/p>\n<p><em>Direi proprio che pi&ugrave; che di storia e sviluppo di un mezzo utile all&#8217;uomo, l&#8217;excursus di Felix Llaug&eacute; sia intriso delle passioni che troppo spesso hanno ottenebrato ogni civile progresso. Per tutto l&#8217;arco: dai popoli del mare che nella seconda met&agrave; del II millennio a. C. invadono l&#8217;Egitto e distruggono l&#8217;impero ittita agli uomini, trafficanti o navigatori, della Lega Anseatica che impongono il loro dominio in vastissime nuove terre; dai protostorici pelasgi e caldei agli equipaggi dell&#8217;Invincibile Armata; dalla potenza marittima della Grecia alle scorrerie vichinghe; dalle scoperte di Colombo alle imprese dei legni lanciati sulle vie del t&egrave; o dell&#8217;oppio, accanto a triremi, nao, caracche, galee, vascelli, giunche, caravelle, clipper, sono sempre i sentimenti, anzi i vizi dell&#8217;uomo a far da mattatori sulla scena dei mari al punto di proporci la figura di un protagonista non tanto abile&nbsp;<\/em>portatore&nbsp;<em>o&nbsp;<\/em>sfileggiatore<em> di rande, gabbie e velacci quanto manovratore astuto, se non subdolo, del destino dei suoi simili. [&#8230;]<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>felix llauge dausa<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>de vecchi (dve italia spa)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1688044970<\/p>\n","protected":false},"featured_media":133239,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2606,3071,2741],"product_tag":[],"class_list":{"0":"post-97425","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-encyclopedias-atlases-and-handbooks","7":"product_cat-history-of-seafaring","8":"product_cat-navigation-history","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>storia dei velieri - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"storia dei velieri\" \/>\n<meta property=\"og:description\" content=\"Author: felix llauge dausaPublisher: de vecchi (dve italia spa)ISBN: LDM1688044970\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:47:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"618\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;40,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\\\/\",\"name\":\"storia dei velieri - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3.jpg\",\"datePublished\":\"2023-06-29T13:22:52+00:00\",\"dateModified\":\"2026-03-14T00:47:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3.jpg\",\"width\":618,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"storia dei velieri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"40.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1688044970\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"storia dei velieri - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"storia dei velieri","og_description":"Author: felix llauge dausaPublisher: de vecchi (dve italia spa)ISBN: LDM1688044970","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:47:22+00:00","og_image":[{"width":618,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;40,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/","name":"storia dei velieri - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3.jpg","datePublished":"2023-06-29T13:22:52+00:00","dateModified":"2026-03-14T00:47:22+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3.jpg","width":618,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-dei-velieri-felix-llauge-dausa-ldm1688044970\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"storia dei velieri"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"40.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1688044970","product_condition":"new"},"df_price":40,"df_sale_price":"","df_regular_price":40,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storia-dei-velieri-felix-llauge-dausa-giovanni-de-vecchi-editore-3-265x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/97425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=97425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/133239"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=97425"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=97425"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=97425"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=97425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}