{"id":97421,"date":"2023-06-29T16:11:31","date_gmt":"2023-06-29T14:11:31","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/"},"modified":"2026-03-14T01:47:13","modified_gmt":"2026-03-14T00:47:13","slug":"un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/","title":{"rendered":"un oceano di sogni"},"content":{"rendered":"<p><strong>Un oceano di sogni riunisce in un solo volume i due libri che raccontano l&#8217;indimenticabile storia di Simone Bianchetti<\/strong>, che realizz&ograve; il proprio sogno di bambino fino a &laquo;toccare il muro del cielo&raquo;: <strong><em>&#8220;I colori dell&#8217;oceano&#8221;<\/em><\/strong> (dello stesso Bianchetti con Fabio Pozzo) e <strong><em>&#8220;Ho sposato l&#8217;oceano&#8221;<\/em><\/strong>, il toccante ricordo di sua moglie Inbar Meytsar.<\/p>\n<p>Mare, vela, tempeste, bonacce, amore e grandi imprese, dalle prime uscite in barca per andare a scuola al giro del mondo in solitaria.<\/p>\n<p>Dall&#8217;introduzione di Cino Ricci: &laquo;&ldquo;Tu sei il Bukowski della vela&rdquo;, gli dicevo. &ldquo;Devi restare cos&igrave;&rdquo;. Perch&eacute; era quella la sua forza. E, purtroppo, anche la sua debolezza. Non ne ho incontrati molti, nella mia vita, di uomini come Simone Bianchetti. Speciali, ed &egrave; per questo che a distanza di vent&#8217;anni dalla sua morte continuiamo a ricordarlo, a parlarne, a immaginare cosa avrebbe fatto, a raccontarci le sue gesta. E a chiederci chi fosse davvero. Io, che l&#8217;ho conosciuto bene, penso fosse anzitutto un sognatore. E poi, un grande marinaio. Ma non un velista nel senso pi&ugrave; moderno del termine. Per diventarlo, sarebbe dovuto cambiare come uomo. E non so se ce l&#8217;avrebbe fatta. Temo di no. Ma se ci fosse riuscito, sono sicuro che noi ci avremmo perso qualcosa, perch&eacute; lui ci affascinava proprio per come era.&raquo;<\/p>\n<p>Dalla Postfazione di Sir Robin Knox-Johnston: &laquo;Dalle frustranti calme equatoriali ai venti urlanti e agli acquosi Himalaya dei Quaranta ruggenti dell&#8217;Oceano del Sud. Navigare da soli intorno al globo &egrave; l&#8217;esperienza velica estrema. &Egrave; come raggiungere la sommit&agrave; dell&#8217;Everest da soli, senza nessuna squadra d&#8217;appoggio.&raquo;<\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la storia del &#8220;bukowski della vela&#8221;, una leggenda della navigazione<\/p>\n<p class=\"autore\"><span>Author: <\/span>simone bianchetti &#8211; inbar meytsar e fabio pozzo<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>tea &#8211; tascabili editori associati<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788850266913<\/p>\n","protected":false},"featured_media":161352,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815,2803],"product_tag":[],"class_list":{"0":"post-97421","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anthologies-and-letters","7":"product_cat-biography-and-memories","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>un oceano di sogni - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"un oceano di sogni\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la storia del &quot;bukowski della vela&quot;, una leggenda della navigazioneAuthor: simone bianchetti - inbar meytsar e fabio pozzoPublisher: tea - tascabili editori associatiISBN: 9788850266913\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:47:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/oceano-di-sogni-bianchetti-meytsar-pozzo-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"759\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;24,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\\\/\",\"name\":\"un oceano di sogni - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/oceano-di-sogni-bianchetti-meytsar-pozzo-2.jpg\",\"datePublished\":\"2023-06-29T14:11:31+00:00\",\"dateModified\":\"2026-03-14T00:47:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/oceano-di-sogni-bianchetti-meytsar-pozzo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/oceano-di-sogni-bianchetti-meytsar-pozzo-2.jpg\",\"width\":500,\"height\":759},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"un oceano di sogni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788850266913\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"un oceano di sogni - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"un oceano di sogni","og_description":"Subtitle: la storia del \"bukowski della vela\", una leggenda della navigazioneAuthor: simone bianchetti - inbar meytsar e fabio pozzoPublisher: tea - tascabili editori associatiISBN: 9788850266913","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:47:13+00:00","og_image":[{"width":500,"height":759,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/oceano-di-sogni-bianchetti-meytsar-pozzo-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;24,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/","name":"un oceano di sogni - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/oceano-di-sogni-bianchetti-meytsar-pozzo-2.jpg","datePublished":"2023-06-29T14:11:31+00:00","dateModified":"2026-03-14T00:47:13+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/oceano-di-sogni-bianchetti-meytsar-pozzo-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/oceano-di-sogni-bianchetti-meytsar-pozzo-2.jpg","width":500,"height":759},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-oceano-di-sogni-simone-bianchetti-inbar-meytsar-e-fabio-pozzo-9788850266913\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"un oceano di sogni"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"24.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788850266913","product_condition":"new"},"df_price":24,"df_sale_price":"","df_regular_price":24,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/oceano-di-sogni-bianchetti-meytsar-pozzo-2-198x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/97421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=97421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/161352"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=97421"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=97421"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=97421"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=97421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}