{"id":96905,"date":"2019-05-22T15:23:00","date_gmt":"2019-05-22T13:23:00","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/"},"modified":"2026-03-14T04:10:04","modified_gmt":"2026-03-14T03:10:04","slug":"a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/","title":{"rendered":"a piedi sul mare nel levante ligure"},"content":{"rendered":"<p>Diego Vaschetto torna a cimentarsi con le escursioni in Liguria, questa volta proponendo un&#8217;inedita selezione di itinerari nel Levante, da Bogliasco a Lerici. Escursioni mai scontate, spesso poco o mai pubblicate, tutte di straordinario valore panoramico, in alcuni dei tratti di costa pi&ugrave; spettacolari e celebrati del Mediterraneo.<\/p>\n<p>Le dirute scogliere di Tramonti, solcate da vie scalinate di vertiginosa bellezza, e i millenari sentieri che percorrono il Golfo del Tigullio, le Cinque Terre pi&ugrave; nascoste e le scogliere tra Levanto, Moneglia e Sestri, le bellezze appartate di Framura e i segreti del Golfo Paradiso, Zoagli e i suoi sentieri di mezza montagna con straordinarie visioni sul mare, l&#8217;immediato entroterra di Camogli e le estreme propaggini della citt&agrave; di Genova. Itinerari per tutti, realizzabili in giornata o anche in poche ore e, soprattutto, in ogni periodo dell&#8217;anno. Sempre con il mare negli occhi.<\/p>\n<p>Una guida completa e originale: cartine, livelli di difficolt&agrave;, tempi di percorrenza, periodo consigliato e un ricchissimo e inedito apparato iconografico. Per ciascun percorso, approfondimenti storici, artistici e naturalistici offrono al lettore l&#8217;opportunit&agrave; di conoscere meglio i luoghi visitati.<\/p>\n<p>A piedi sul mare. A due passi dalle spiagge della Liguria.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>escursioni imperdibili a due passi dal mare<\/p>\n<p class=\"autore\"><span>Author: <\/span>diego vaschetto<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni del capricorno<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788877074232<\/p>\n","protected":false},"featured_media":160833,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2638],"product_tag":[],"class_list":{"0":"post-96905","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ligury","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>a piedi sul mare nel levante ligure - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"a piedi sul mare nel levante ligure\" \/>\n<meta property=\"og:description\" content=\"Subtitle: escursioni imperdibili a due passi dal mareAuthor: diego vaschettoPublisher: edizioni del capricornoISBN: 9788877074232\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T03:10:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/a-piedi-sul-mare-levante-ligure-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"414\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;13,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\\\/\",\"name\":\"a piedi sul mare nel levante ligure - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/a-piedi-sul-mare-levante-ligure-3.jpg\",\"datePublished\":\"2019-05-22T13:23:00+00:00\",\"dateModified\":\"2026-03-14T03:10:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/a-piedi-sul-mare-levante-ligure-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/a-piedi-sul-mare-levante-ligure-3.jpg\",\"width\":414,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"a piedi sul mare nel levante ligure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"13.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788877074232\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"a piedi sul mare nel levante ligure - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"a piedi sul mare nel levante ligure","og_description":"Subtitle: escursioni imperdibili a due passi dal mareAuthor: diego vaschettoPublisher: edizioni del capricornoISBN: 9788877074232","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T03:10:04+00:00","og_image":[{"width":414,"height":598,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/a-piedi-sul-mare-levante-ligure-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;13,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/","name":"a piedi sul mare nel levante ligure - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/a-piedi-sul-mare-levante-ligure-3.jpg","datePublished":"2019-05-22T13:23:00+00:00","dateModified":"2026-03-14T03:10:04+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/a-piedi-sul-mare-levante-ligure-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/a-piedi-sul-mare-levante-ligure-3.jpg","width":414,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/a-piedi-sul-mare-nel-levante-ligure-diego-vaschetto-9788877074232\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"a piedi sul mare nel levante ligure"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"13.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788877074232","product_condition":"new"},"df_price":13,"df_sale_price":"","df_regular_price":13,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/a-piedi-sul-mare-levante-ligure-3-208x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/96905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=96905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/160833"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=96905"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=96905"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=96905"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=96905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}