{"id":96795,"date":"2019-07-12T13:13:14","date_gmt":"2019-07-12T11:13:14","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corf-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/"},"modified":"2026-03-14T04:05:49","modified_gmt":"2026-03-14T03:05:49","slug":"777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/","title":{"rendered":"777 il portolano &#8211; dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos"},"content":{"rendered":"<p style=\"text-align: justify\">I Portolani 777 sono progettati recuperando l&rsquo;idea che stava alla base delle antiche &ldquo;carte portolaniche&rdquo;, unendo insieme carte geografiche, piani nautici e descrizione del luogo d&rsquo;approdo. Il diportista ha, cos&igrave;, tra le mani uno strumento autorevole, completo e utile per navigare in tranquillit&agrave; e trascorrere al meglio la crociera.<\/p>\n<p style=\"text-align: justify\">All&rsquo;interno della guida troverete informazioni su:<\/p>\n<ul>\n<li style=\"text-align: justify\">carte nautiche<\/li>\n<li style=\"text-align: justify\">ormeggi<\/li>\n<li style=\"text-align: justify\">ancoraggi in rada<\/li>\n<li style=\"text-align: justify\">informazioni dettagliate e utili per la vostra navigazione<\/li>\n<li style=\"text-align: justify\">contatti utili e informazioni dettagliate sul sito web dedicato<\/li>\n<li style=\"text-align: justify\">infoline (assistenza, suggerimenti e consigli)<\/li>\n<li style=\"text-align: justify\">cenni storici e curiosit&agrave; sulle principali citt&agrave; e localit&agrave;<\/li>\n<li style=\"text-align: justify\">itinerari di terra<\/li>\n<li style=\"text-align: justify\">QR Code (video-tutorial o immagini satellitari che consentono la visita virtuale del porto o dell&rsquo;ancoraggio prima di arrivare)<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>le vie del mare 21<\/p>\n<p class=\"autore\"><span>Author: <\/span>dario silvestro  marco sbrizzi  piero magnabosco<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni magnamare<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862000550<\/p>\n","protected":false},"featured_media":100946,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2709],"product_tag":[],"class_list":{"0":"post-96795","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bird","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>777 il portolano - dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"777 il portolano - dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos\" \/>\n<meta property=\"og:description\" content=\"Subtitle: le vie del mare 21Author: dario silvestro marco sbrizzi piero magnaboscoPublisher: edizioni magnamareISBN: 9788862000550\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T03:05:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\\\/\",\"name\":\"777 il portolano - dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3.jpg\",\"datePublished\":\"2019-07-12T11:13:14+00:00\",\"dateModified\":\"2026-03-14T03:05:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3.jpg\",\"width\":424,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"777 il portolano &#8211; dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862000550\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"777 il portolano - dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"777 il portolano - dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos","og_description":"Subtitle: le vie del mare 21Author: dario silvestro marco sbrizzi piero magnaboscoPublisher: edizioni magnamareISBN: 9788862000550","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T03:05:49+00:00","og_image":[{"width":424,"height":600,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;29,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/","name":"777 il portolano - dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3.jpg","datePublished":"2019-07-12T11:13:14+00:00","dateModified":"2026-03-14T03:05:49+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3.jpg","width":424,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-dal-confine-albanese-al-golfo-di-ambracia-isole-diapontie-corfu-paxos-e-antipaxos-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000550\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"777 il portolano &#8211; dal confine albanese al golfo di ambracia, isole diapontie, corf\u00f9, paxos e antipaxos"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"29.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788862000550","product_condition":"new"},"df_price":29.9,"df_sale_price":"","df_regular_price":29.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-portolano-confine-albanese-golfo-ambracia-isole-diapontie-corfu-paxos-antipaxos-3-212x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/96795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=96795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/100946"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=96795"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=96795"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=96795"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=96795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}