{"id":96619,"date":"2019-11-11T14:41:15","date_gmt":"2019-11-11T13:41:15","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/"},"modified":"2026-03-14T03:59:37","modified_gmt":"2026-03-14T02:59:37","slug":"sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/","title":{"rendered":"sulla cresta dell&#8217;onda"},"content":{"rendered":"<p>Un viaggio avvincente nella nautica italiana a partire dagli Anni Cinquanta attraverso le vicende dei suoi protagonisti. Una storia che ripercorre le tappe che hanno condotto l&rsquo;Italia a occupare i primi posti nella classifica mondiale dei produttori di megayacht.<\/p>\n<p>Nella seconda parte del libro, un focus particolare &egrave; dedicato al pi&ugrave; importante protagonista, il Gruppo Azimut-Benetti che, a detta dei suoi stessi competitor, ha portato all&#8217;eccellenza la nautica italiana cos&igrave; come quest&rsquo;ultima ha trascinato verso l&rsquo;alto la nautica mondiale.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la nautica italiana dagli anni cinquanta &#8211; una storia nella storia: azimut-benetti<\/p>\n<p class=\"autore\"><span>Author: <\/span> marila guadagnini &#8211; paolo vitelli &#8211; giovanna vitelli<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Mondadori Electa<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788891826985<\/p>\n","protected":false},"featured_media":149614,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3009],"product_tag":[],"class_list":{"0":"post-96619","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-other-publications-boat-yards-and-designers","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>sulla cresta dell&#039;onda - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sulla cresta dell&#039;onda\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la nautica italiana dagli anni cinquanta - una storia nella storia: azimut-benettiAuthor: marila guadagnini - paolo vitelli - giovanna vitelliPublisher: Mondadori ElectaISBN: 9788891826985\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:59:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"392\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;35,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\\\/\",\"name\":\"sulla cresta dell'onda - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4.jpg\",\"datePublished\":\"2019-11-11T13:41:15+00:00\",\"dateModified\":\"2026-03-14T02:59:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4.jpg\",\"width\":392,\"height\":575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sulla cresta dell&#8217;onda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"35.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788891826985\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"sulla cresta dell'onda - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"sulla cresta dell'onda","og_description":"Subtitle: la nautica italiana dagli anni cinquanta - una storia nella storia: azimut-benettiAuthor: marila guadagnini - paolo vitelli - giovanna vitelliPublisher: Mondadori ElectaISBN: 9788891826985","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:59:37+00:00","og_image":[{"width":392,"height":575,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;35,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/","name":"sulla cresta dell'onda - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4.jpg","datePublished":"2019-11-11T13:41:15+00:00","dateModified":"2026-03-14T02:59:37+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4.jpg","width":392,"height":575},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/sulla-cresta-dell-onda-marila-guadagnini-paolo-vitelli-giovanna-vitelli-9788891826985\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"sulla cresta dell&#8217;onda"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"35.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788891826985","product_condition":"new"},"df_price":35,"df_sale_price":"","df_regular_price":35,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/sulla-cresta-dell-onda-nautica-italiana-guadagnini-vitelli-4-205x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/96619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=96619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/149614"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=96619"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=96619"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=96619"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=96619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}