{"id":96201,"date":"2020-07-09T13:59:30","date_gmt":"2020-07-09T11:59:30","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/777-il-portolano-sicilia-da-marsala-a-cefal-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/"},"modified":"2026-03-14T03:44:53","modified_gmt":"2026-03-14T02:44:53","slug":"777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/","title":{"rendered":"777 il portolano &#8211; sicilia: da marsala a cefal\u00f9, isole egadi e ustica"},"content":{"rendered":"<p>I Portolani 777 sono progettati recuperando l&rsquo;idea che stava alla base delle antiche &#8220;carte portolaniche&#8221;, unendo insieme carte geografiche, piani nautici e descrizione del luogo d&rsquo;approdo.<\/p>\n<p>Il diportista ha cos&igrave; tra le mani uno strumento autorevole, completo e utile per navigare in tranquillit&agrave; e trascorrere al meglio la crociera.<\/p>\n<p>I nostri punti di forza sono:<\/p>\n<p>&bull; aver visitato tutti gli ormeggi, gli ancoraggi ed il territorio circostante;<br \/>&bull; avere una rete di inviati sul territorio che effettuano rilievi, controlli e verifiche;<br \/>&bull; presentare itinerari di terra e una selezione dei principali servizi utili al diportista;<br \/>&bull; offrire un servizio di infoline per assistenza.<\/p>\n<p>L&rsquo;obbiettivo &egrave; quello di essere vicini ai nostri lettori e di fornire informazioni sempre aggiornate e veritiere.<\/p>\n<p>Edizione: 2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>le vie del mare 27<\/p>\n<p class=\"autore\"><span>Author: <\/span>dario silvestro  marco sbrizzi  piero magnabosco<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni magnamare<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862000918<\/p>\n","protected":false},"featured_media":100768,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2693],"product_tag":[],"class_list":{"0":"post-96201","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-topo-8","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>777 il portolano - sicilia: da marsala a cefal\u00f9, isole egadi e ustica - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"777 il portolano - sicilia: da marsala a cefal\u00f9, isole egadi e ustica\" \/>\n<meta property=\"og:description\" content=\"Subtitle: le vie del mare 27Author: dario silvestro marco sbrizzi piero magnaboscoPublisher: edizioni magnamareISBN: 9788862000918\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:44:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\\\/\",\"name\":\"777 il portolano - sicilia: da marsala a cefal\u00f9, isole egadi e ustica - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3.jpg\",\"datePublished\":\"2020-07-09T11:59:30+00:00\",\"dateModified\":\"2026-03-14T02:44:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3.jpg\",\"width\":500,\"height\":708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"777 il portolano &#8211; sicilia: da marsala a cefal\u00f9, isole egadi e ustica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862000918\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"777 il portolano - sicilia: da marsala a cefal\u00f9, isole egadi e ustica - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"777 il portolano - sicilia: da marsala a cefal\u00f9, isole egadi e ustica","og_description":"Subtitle: le vie del mare 27Author: dario silvestro marco sbrizzi piero magnaboscoPublisher: edizioni magnamareISBN: 9788862000918","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:44:53+00:00","og_image":[{"width":500,"height":708,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;29,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/","name":"777 il portolano - sicilia: da marsala a cefal\u00f9, isole egadi e ustica - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3.jpg","datePublished":"2020-07-09T11:59:30+00:00","dateModified":"2026-03-14T02:44:53+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3.jpg","width":500,"height":708},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-e-ustica-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000918\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"777 il portolano &#8211; sicilia: da marsala a cefal\u00f9, isole egadi e ustica"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"29.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788862000918","product_condition":"new"},"df_price":29.9,"df_sale_price":"","df_regular_price":29.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-il-portolano-sicilia-da-marsala-a-cefalu-isole-egadi-ustica-magnamare-3-212x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/96201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=96201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/100768"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=96201"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=96201"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=96201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=96201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}