{"id":96151,"date":"2020-07-23T16:48:58","date_gmt":"2020-07-23T14:48:58","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/"},"modified":"2026-03-14T03:42:25","modified_gmt":"2026-03-14T02:42:25","slug":"777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/","title":{"rendered":"777 il portolano &#8211; liguria, da ventimiglia a bocca di magra &#8211; corsica, da calvi a bastia"},"content":{"rendered":"<p>I Portolani 777 sono progettati recuperando l&rsquo;idea che stava alla base delle antiche &ldquo;carte portolaniche&rdquo;, unendo insieme carte geografiche, piani nautici e descrizione del luogo d&rsquo;approdo.<br \/>Il diportista ha cos&igrave; tra le mani uno strumento autorevole, completo e utile per navigare in tranquillit&agrave; e trascorrere al meglio la crociera.<\/p>\n<p>I nostri punti di forza sono:<\/p>\n<p>&bull; Aver visitato tutti gli ormeggi, gli ancoraggi ed il territorio circostante<br \/>&bull; Avere una rete di inviati sul territorio che effettuano rilievi, controlli e verifiche<br \/>&bull; Presentare itinerari di terra e una selezione dei principali servizi utili al diportista<br \/>&bull; Offrire un servizio di infoline per assistenza<\/p>\n<p>L&rsquo;obiettivo &egrave; quello di essere vicini ai nostri lettori e di fornire informazioni sempre aggiornate e veritiere.<\/p>\n<p style=\"text-align: justify\">Edizione: 2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>le vie del mare 25<\/p>\n<p class=\"autore\"><span>Author: <\/span>dario silvestro  marco sbrizzi  piero magnabosco<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni magnamare<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862000901<\/p>\n","protected":false},"featured_media":100954,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2705,2699],"product_tag":[],"class_list":{"0":"post-96151","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-coe","7":"product_cat-thyrrenian-and-ligurian-seas","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>777 il portolano - liguria, da ventimiglia a bocca di magra - corsica, da calvi a bastia - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"777 il portolano - liguria, da ventimiglia a bocca di magra - corsica, da calvi a bastia\" \/>\n<meta property=\"og:description\" content=\"Subtitle: le vie del mare 25Author: dario silvestro marco sbrizzi piero magnaboscoPublisher: edizioni magnamareISBN: 9788862000901\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:42:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-liguria-corsica-le-vie-del-mare-25-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\\\/\",\"name\":\"777 il portolano - liguria, da ventimiglia a bocca di magra - corsica, da calvi a bastia - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-liguria-corsica-le-vie-del-mare-25-3.jpg\",\"datePublished\":\"2020-07-23T14:48:58+00:00\",\"dateModified\":\"2026-03-14T02:42:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-liguria-corsica-le-vie-del-mare-25-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-liguria-corsica-le-vie-del-mare-25-3.jpg\",\"width\":500,\"height\":708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"777 il portolano &#8211; liguria, da ventimiglia a bocca di magra &#8211; corsica, da calvi a bastia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862000901\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"777 il portolano - liguria, da ventimiglia a bocca di magra - corsica, da calvi a bastia - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"777 il portolano - liguria, da ventimiglia a bocca di magra - corsica, da calvi a bastia","og_description":"Subtitle: le vie del mare 25Author: dario silvestro marco sbrizzi piero magnaboscoPublisher: edizioni magnamareISBN: 9788862000901","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:42:25+00:00","og_image":[{"width":500,"height":708,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-liguria-corsica-le-vie-del-mare-25-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;29,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/","name":"777 il portolano - liguria, da ventimiglia a bocca di magra - corsica, da calvi a bastia - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-liguria-corsica-le-vie-del-mare-25-3.jpg","datePublished":"2020-07-23T14:48:58+00:00","dateModified":"2026-03-14T02:42:25+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-liguria-corsica-le-vie-del-mare-25-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-liguria-corsica-le-vie-del-mare-25-3.jpg","width":500,"height":708},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-il-portolano-liguria-da-ventimiglia-a-bocca-di-magra-corsica-da-calvi-a-bastia-dario-silvestro-marco-sbrizzi-piero-magnabosco-9788862000901\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"777 il portolano &#8211; liguria, da ventimiglia a bocca di magra &#8211; corsica, da calvi a bastia"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"29.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788862000901","product_condition":"new"},"df_price":29.9,"df_sale_price":"","df_regular_price":29.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-liguria-corsica-le-vie-del-mare-25-3-212x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/96151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=96151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/100954"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=96151"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=96151"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=96151"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=96151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}