{"id":96074,"date":"2020-09-22T15:13:00","date_gmt":"2020-09-22T13:13:00","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/"},"modified":"2026-03-14T03:38:20","modified_gmt":"2026-03-14T02:38:20","slug":"lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/","title":{"rendered":"lungo le rotte del mare"},"content":{"rendered":"<p>Le mappe nautiche sono strumenti visivi pensati per trasmettere rapidamente una grande quantit&agrave; di informazioni. Indicano a un navigatore come tenere la rotta, segnalano ostacoli e possibili pericoli e, in molti casi, stimano le distanze. Per poter fare tutto questo impiegano un insieme di caratteristiche &nbsp;e simboli che si sono sviluppati nei secoli, diversi da quelli delle carte terrestri. In questo libro vi raccontiamo le affascinanti storie su come gli stili e le strutture delle carte nautiche sono cambiati. Le mappe venivano disegnate pensando non solo all&#8217;utilit&agrave;, ma anche all&#8217;estetica: potevano essere regali per patroni o istituzioni, o strumenti per mostrare a un pubblico di &#8220;osservatori della terraferma&#8221; i confini di un impero o le rotte dei suoi commerci. Potevano servire a trasmettere la potenza e la ricchezza di uno Stato o di una compagnia, sottolineando la centralit&agrave; della navigazione nella storia umana. Nel contesto europeo, che &egrave; l&#8217;oggetto del libro, nel corso di quasi un millennio la navigazione &egrave; passata dall&#8217;essere una pratica basata sull&#8217;esperienza e sull&#8217;intuizione al delinearsi come una disciplina dominata dalla matematica e dagli strumenti. Oggi &egrave; in atto un altro cambiamento, che vede come protagonista l&#8217;elettronica e l&#8217;analisi dei dati. Ma anche se sembrano cos&igrave; lontane dalle oro origini, persino le moderne carte dei nostri tempi discendono dai portolani nati nel Mediterraneo nel tardo Medioevo. Questo libro vi sveler&agrave; tutta la storia, un passo dopo l&#8217;altro.<\/p>\n<p>Edizione: 2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cartografia marina attraverso i secoli<\/p>\n<p class=\"autore\"><span>Author: <\/span>katherine parker  barry lawrence ruderman<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni white star<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788854046276<\/p>\n","protected":false},"featured_media":157689,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2569],"product_tag":[],"class_list":{"0":"post-96074","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-navigation-history-chartography","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>lungo le rotte del mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lungo le rotte del mare\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cartografia marina attraverso i secoliAuthor: katherine parker barry lawrence rudermanPublisher: edizioni white starISBN: 9788854046276\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lungo-le-rotte-del-mare-parker-ruderman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"506\" \/>\n\t<meta property=\"og:image:height\" content=\"588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;35,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\\\/\",\"name\":\"lungo le rotte del mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lungo-le-rotte-del-mare-parker-ruderman.jpg\",\"datePublished\":\"2020-09-22T13:13:00+00:00\",\"dateModified\":\"2026-03-14T02:38:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lungo-le-rotte-del-mare-parker-ruderman.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lungo-le-rotte-del-mare-parker-ruderman.jpg\",\"width\":506,\"height\":588},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"lungo le rotte del mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"35.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788854046276\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"lungo le rotte del mare - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"lungo le rotte del mare","og_description":"Subtitle: cartografia marina attraverso i secoliAuthor: katherine parker barry lawrence rudermanPublisher: edizioni white starISBN: 9788854046276","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:38:20+00:00","og_image":[{"width":506,"height":588,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lungo-le-rotte-del-mare-parker-ruderman.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;35,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/","name":"lungo le rotte del mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lungo-le-rotte-del-mare-parker-ruderman.jpg","datePublished":"2020-09-22T13:13:00+00:00","dateModified":"2026-03-14T02:38:20+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lungo-le-rotte-del-mare-parker-ruderman.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lungo-le-rotte-del-mare-parker-ruderman.jpg","width":506,"height":588},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lungo-le-rotte-del-mare-katherine-parker-barry-lawrence-ruderman-9788854046276\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"lungo le rotte del mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"35.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788854046276","product_condition":"new"},"df_price":35,"df_sale_price":"","df_regular_price":35,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lungo-le-rotte-del-mare-parker-ruderman-258x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/96074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=96074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/157689"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=96074"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=96074"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=96074"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=96074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}