{"id":95954,"date":"2020-12-06T15:12:17","date_gmt":"2020-12-06T14:12:17","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/"},"modified":"2026-03-14T03:32:16","modified_gmt":"2026-03-14T02:32:16","slug":"passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/","title":{"rendered":"passaggi tra le isole di sardegna &#8211; la maddalena &#8211; caprera &#8211; s. stefano n. 70 (1959)"},"content":{"rendered":"<p style=\"text-align:justify\">Carta nautica&nbsp;dell\u2019Istituto&nbsp;Idrografico della Marina Italiana edita nel&nbsp;1938. L\u2019esemplare a nostra disposizione \u00e8 stato ristampato e aggiornato nel 1959.<\/p>\n<p style=\"text-align:justify\">Piccole macchie sparse.<\/p>\n<p style=\"text-align:justify\">La superficie del foglio \u00e8 ricoperta da una patina di polvere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 79&#215;67<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>istituto idrografico della regia marina<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1607263935<\/p>\n","protected":false},"featured_media":48988,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2461],"product_tag":[],"class_list":{"0":"post-95954","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-modern-antiques","7":"product_shipping_class-packaging","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>passaggi tra le isole di sardegna - la maddalena - caprera - s. stefano n. 70 (1959) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"passaggi tra le isole di sardegna - la maddalena - caprera - s. stefano n. 70 (1959)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 79x67Manufacturer: istituto idrografico della regia marinaISBN: LDM1607263935\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:32:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2095\" \/>\n\t<meta property=\"og:image:height\" content=\"1814\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;120,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\\\/\",\"name\":\"passaggi tra le isole di sardegna - la maddalena - caprera - s. stefano n. 70 (1959) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959.jpg\",\"datePublished\":\"2020-12-06T14:12:17+00:00\",\"dateModified\":\"2026-03-14T02:32:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959.jpg\",\"width\":2095,\"height\":1814},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"passaggi tra le isole di sardegna &#8211; la maddalena &#8211; caprera &#8211; s. stefano n. 70 (1959)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"120.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1607263935\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"passaggi tra le isole di sardegna - la maddalena - caprera - s. stefano n. 70 (1959) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"passaggi tra le isole di sardegna - la maddalena - caprera - s. stefano n. 70 (1959)","og_description":"Subtitle: cm 79x67Manufacturer: istituto idrografico della regia marinaISBN: LDM1607263935","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:32:16+00:00","og_image":[{"width":2095,"height":1814,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;120,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/","name":"passaggi tra le isole di sardegna - la maddalena - caprera - s. stefano n. 70 (1959) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959.jpg","datePublished":"2020-12-06T14:12:17+00:00","dateModified":"2026-03-14T02:32:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959.jpg","width":2095,"height":1814},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/passaggi-tra-le-isole-di-sardegna-la-maddalena-caprera-s-stefano-n-70-1959-ldm1607263935\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"passaggi tra le isole di sardegna &#8211; la maddalena &#8211; caprera &#8211; s. stefano n. 70 (1959)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"120.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1607263935","product_condition":"new"},"df_price":120,"df_sale_price":"","df_regular_price":120,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/passaggi-isole-sardegna-la-maddalena-caprera-s-stefano-70-1959-300x260.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/95954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=95954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/48988"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=95954"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=95954"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=95954"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=95954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}