{"id":95921,"date":"2020-12-16T16:59:27","date_gmt":"2020-12-16T15:59:27","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/"},"modified":"2026-03-14T03:30:30","modified_gmt":"2026-03-14T02:30:30","slug":"alba-il-pesce-centenario-lara-hawthorne-9788878747364","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/","title":{"rendered":"alba il pesce centenario"},"content":{"rendered":"<p>Una cittadina affacciata sul mare blu e sotto, nell&rsquo;acqua, una citt&agrave; di corallo: &egrave; qui che vive Alba, una&nbsp;pesciolina arancione con la passione per perle, sassi, conchiglie. Ogni anno, per il suo compleanno, ha scelto&nbsp;qualcosa di speciale da regalarsi e la sua splendida collezione &egrave; cresciuta moltissimo. Ma, col tempo, Alba ha&nbsp;visto il suo mondo cambiare. L&rsquo;acqua &egrave; diventata sempre pi&ugrave; torbida e gli amati bellissimi oggetti ormai sono&nbsp;scomparsi, sostituiti da altri sconosciuti e dall&rsquo;aspetto poco rassicurante. Cos&igrave;, a poco a poco, tutti i suoi amici&nbsp;pesci sono andati via.&nbsp;Alba non ha pi&ugrave; nessuno con cui festeggiare il compleanno e non trova nulla per la sua collezione. &Egrave; triste, ma&nbsp;continua a cercare, fin quando, all&rsquo;improvviso&hellip; una perla! &Egrave; infilata dentro alla pi&ugrave; strana conchiglia mai&nbsp;vista: trasparente e allungata. Alba entra nell&rsquo;apertura, ma resta intrappolata, senza riuscire a liberarsi. La&nbsp;strana conchiglia si muove con la corrente, portando Alba con s&eacute;, finch&eacute; affiora in superficie. Creature giganti si&nbsp;muovono sull&rsquo;acqua, tra centinaia di oggetti pi&ugrave; piccoli, molto simili a quelli che hanno invaso la citt&agrave; di corallo.<\/p>\n<p>Una bambina, camminando lungo la spiaggia, trova una pesciolina che si muove appena, imprigionata in una&nbsp;bottiglia di plastica. Guardando la riva piena di cartacce, buste e bottiglie, capisce che tutto arriva dalla sua&nbsp;citt&agrave; e decide di fare qualcosa. Mostra&nbsp;a tutti la pesciolina che si dibatte debolmente nell&rsquo;involucro di plastica. L&rsquo;intera citt&agrave; capisce di dover&nbsp;cambiare abitudini e lavora per rimediare a quel disastro, finch&eacute; il mare torna a brillare.&nbsp;Solo allora la bambina saluta Alba, che torna nel suo mondo di corallo di nuovo pieno di vita e di luce.<\/p>\n<p>Et&agrave;: 3+<\/p>\n<p>Edizione: 2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>un pesce, una bambina, un mare da salvare<\/p>\n<p class=\"autore\"><span>Author: <\/span>lara hawthorne<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>lapis edizioni<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788878747364<\/p>\n","protected":false},"featured_media":77076,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2614],"product_tag":[],"class_list":{"0":"post-95921","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-illustrated-books-and-fiction","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>alba il pesce centenario - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"alba il pesce centenario\" \/>\n<meta property=\"og:description\" content=\"Subtitle: un pesce, una bambina, un mare da salvareAuthor: lara hawthornePublisher: lapis edizioniISBN: 9788878747364\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:30:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/alba-il-pesce-centenario-hawthorne-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\\\/\",\"name\":\"alba il pesce centenario - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/alba-il-pesce-centenario-hawthorne-2.jpg\",\"datePublished\":\"2020-12-16T15:59:27+00:00\",\"dateModified\":\"2026-03-14T02:30:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/alba-il-pesce-centenario-hawthorne-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/alba-il-pesce-centenario-hawthorne-2.jpg\",\"width\":500,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"alba il pesce centenario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788878747364\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"alba il pesce centenario - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"alba il pesce centenario","og_description":"Subtitle: un pesce, una bambina, un mare da salvareAuthor: lara hawthornePublisher: lapis edizioniISBN: 9788878747364","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:30:30+00:00","og_image":[{"width":500,"height":641,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/alba-il-pesce-centenario-hawthorne-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/","name":"alba il pesce centenario - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/alba-il-pesce-centenario-hawthorne-2.jpg","datePublished":"2020-12-16T15:59:27+00:00","dateModified":"2026-03-14T02:30:30+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/alba-il-pesce-centenario-hawthorne-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/alba-il-pesce-centenario-hawthorne-2.jpg","width":500,"height":641},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/alba-il-pesce-centenario-lara-hawthorne-9788878747364\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"alba il pesce centenario"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788878747364","product_condition":"new"},"df_price":14,"df_sale_price":"","df_regular_price":14,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/alba-il-pesce-centenario-hawthorne-2-234x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/95921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=95921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/77076"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=95921"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=95921"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=95921"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=95921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}