{"id":95864,"date":"2020-12-31T14:15:41","date_gmt":"2020-12-31T13:15:41","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/"},"modified":"2026-03-14T03:28:41","modified_gmt":"2026-03-14T02:28:41","slug":"i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/","title":{"rendered":"i porti d&#8217;italia n. 11 &#8211; porto ercole"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Raro esemplare della prima edizione di Vito Bianco Editore del 1962 in ottimo stato di conservazione. In-24, brossura illustrata a colori fortemente ingiallita, 28 pp.; con seconda e terza di copertina stampate a colori e tasca in carta applicata in terza, contenente una carta nautica della zona; con numerose illustrazioni e fotografie in nero nel testo e fuori testo.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>La carta nautica &egrave; piegata in 8 e stampata in nero in formato A3; riproduce parzialmente due carte nautiche dell&rsquo;Istituto Idrografico della Marina: al recto la n. 78 &ldquo;Porto Ercole&rdquo; e al verso la n. 100 &ldquo;Promontorio Argentario&rdquo;.<\/strong><\/p>\n<p style=\"text-align: justify\">&ldquo;I porti d&rsquo;Italia n. 11 &ndash; Porto Ercole&rdquo; &egrave; un piccolo portolano con informazioni utili ai naviganti (punti cospicui, navigazione notturna, pericoli, avvicinamento, correnti, venti, ingresso in porto, fondale, posti di ormeggio, autorit&agrave; marittime, servizi e attrezzature portuali), con l&rsquo;aggiunta di note turistiche, commerciali, sportive e storiche.<\/p>\n<p style=\"text-align: justify\">La parte finale del testo consiste in una breve agenda che riporta i radioservizi, i recapiti utili di interesse generale e alcune distanze su strada, su ferrovia e in miglia marine.<\/p>\n<p style=\"text-align: justify\">Fuori dal testo troviamo le inserzioni pubblicitarie di numerose attivit&agrave; commerciali, nautiche e turistiche della zona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>le guide del mare di vito bianco editore &#8211; roma<\/p>\n<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>vito bianco editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1609420537<\/p>\n","protected":false},"featured_media":123582,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2606,2461],"product_tag":[],"class_list":{"0":"post-95864","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-encyclopedias-atlases-and-handbooks","7":"product_cat-modern-antiques","8":"product_shipping_class-packaging","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>i porti d&#039;italia n. 11 - porto ercole - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"i porti d&#039;italia n. 11 - porto ercole\" \/>\n<meta property=\"og:description\" content=\"Subtitle: le guide del mare di vito bianco editore - romaAuthor: aa.vv.Publisher: vito bianco editoreISBN: LDM1609420537\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:28:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1089\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;5,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\\\/\",\"name\":\"i porti d'italia n. 11 - porto ercole - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2.jpg\",\"datePublished\":\"2020-12-31T13:15:41+00:00\",\"dateModified\":\"2026-03-14T02:28:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2.jpg\",\"width\":1089,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"i porti d&#8217;italia n. 11 &#8211; porto ercole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"5.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1609420537\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"i porti d'italia n. 11 - porto ercole - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"i porti d'italia n. 11 - porto ercole","og_description":"Subtitle: le guide del mare di vito bianco editore - romaAuthor: aa.vv.Publisher: vito bianco editoreISBN: LDM1609420537","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:28:41+00:00","og_image":[{"width":1089,"height":701,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;5,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/","name":"i porti d'italia n. 11 - porto ercole - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2.jpg","datePublished":"2020-12-31T13:15:41+00:00","dateModified":"2026-03-14T02:28:41+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2.jpg","width":1089,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-porti-d-italia-n-11-porto-ercole-aa-vv-ldm1609420537\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"i porti d&#8217;italia n. 11 &#8211; porto ercole"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"5.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1609420537","product_condition":"new"},"df_price":5,"df_sale_price":"","df_regular_price":5,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/i-porti-d-italia-n-11-porto-ercole-le-guide-del-mare-di-vito-bianco-editore-2-300x193.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/95864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=95864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/123582"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=95864"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=95864"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=95864"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=95864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}