{"id":95813,"date":"2021-02-05T14:41:40","date_gmt":"2021-02-05T13:41:40","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/"},"modified":"2026-03-14T03:25:59","modified_gmt":"2026-03-14T02:25:59","slug":"verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/","title":{"rendered":"verso samoa sulle tracce di stevenson"},"content":{"rendered":"<p>All&rsquo;alba di un giorno del mese di Ottobre del 1901 Marcel Schwob parte da Marsiglia su una nave diretta a Ceylon; da l&igrave; proseguir&agrave; per l&rsquo;Australia e, poi, per la Polinesia. &Egrave; diretto verso le Isole Samoa e, pi&ugrave; precisamente, ad Apia, la capitale dell&rsquo;isola di Upolu. Ma quale ragione conduceva uno scrittore cos&igrave; raffinato e cos&igrave; &ldquo;cittadino&rdquo;, anzi, implacabilmente parigino, ad affrontare, pur gravemente malato, un simile viaggio?<\/p>\n<p>Nel 1884, a diciassette anni, aveva letto per la prima volta un romanzo di Robert Louis Stevenson, <em>L&rsquo;isola del tesoro<\/em>, pubblicato l&rsquo;anno prima e subito tradotto in francese. Stevenson dunque irrompe nella sua vita sotto il segno dell&rsquo;avventura, riflesso di un mondo diverso e pi&ugrave; libero, perturbante e affascinante proprio per la sua distanza nel tempo e nello spazio. Dir&agrave; pi&ugrave; tardi, in un saggio dedicato proprio a Stevenson: &ldquo;Ricordo chiaramente la specie d&rsquo;emozione in cui mi gett&ograve; il primo libro di Stevenson che ho letto. Era <em>L&rsquo;isola del tesoro<\/em>&hellip; Capii allora che avevo subito il potere di un nuovo creatore di letteratura e che il mio spirito sarebbe stato ossessionato da immagini dai colori mai visti e da suoni non ancora ascoltati&rdquo;.<\/p>\n<p>Il lungo viaggio, tra mille difficolt&agrave;, lo port&ograve; a contatto prima con l&rsquo;Africa (Suez e Gibuti), che non gli piacque, poi con l&rsquo;Australia, che gli parve orribile e desolata, e, infine, con le isole dei Mari del Sud che, nelle lunghe lettere alla moglie, cominciano ad assumere un&rsquo;aria sinistra. Ma fu a Samoa, e precisamente ad Apia, che il viaggio, concludendosi, assunse per certi versi l&rsquo;aspetto di un beffardo tiro del destino: ammalatosi gravemente e sul punto di morire rest&ograve; a letto, dopo pochi giorni dall&rsquo;arrivo, e dopo aver fatto le visite di rito ai capi locali, esattamente come aveva fatto Stevenson circa dieci anni prima. Non riusc&igrave; a salire alla tomba. Lui, l&rsquo;ammiratore di Stevenson, il critico che aveva colto gli aspetti innovativi e aperti al futuro della sua narrativa, erroneamente indicata come rivolta ai ragazzi, non riusc&igrave; a compiere quel gesto che lo avrebbe riconciliato con il suo doppio.<br \/>A Samoa ha modo di conoscere le complicate vicende della Guerra Civile e il ruolo giocato dalle grandi potenze. E a Samoa la presenza di missionari di tutte le confessioni gli fa capire l&rsquo;opera di sistematica distruzione della civilt&agrave; indigena, talvolta, come aveva scritto Stevenson nelle pagine iniziali del suo <em>Nei mari del Sud<\/em>, in senso fisico attraverso estinzioni di massa, sempre attraverso l&rsquo;imposizione di usi e costumi stranieri. Quasi sicuramente non aveva letto n&eacute; conosciuto Conrad, il cui <em>Cuore di tenebra<\/em> era comparso nel 1899, ma sono molti i punti di contatto tra i due viaggi, quello nel cuore nero dell&rsquo;Africa e quello nel paradiso perduto delle isole dei Mari del Sud.<\/p>\n<p>Edizione: 2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>marcel schwob<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>tarka edizioni srl<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791280246028<\/p>\n","protected":false},"featured_media":122229,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805],"product_tag":[],"class_list":{"0":"post-95813","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>verso samoa sulle tracce di stevenson - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"verso samoa sulle tracce di stevenson\" \/>\n<meta property=\"og:description\" content=\"Author: marcel schwobPublisher: tarka edizioni srlISBN: 9791280246028\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:25:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/verso-samoa-sulle-tracce-di-stevenson-schwob-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"751\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\\\/\",\"name\":\"verso samoa sulle tracce di stevenson - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/verso-samoa-sulle-tracce-di-stevenson-schwob-1.jpg\",\"datePublished\":\"2021-02-05T13:41:40+00:00\",\"dateModified\":\"2026-03-14T02:25:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/verso-samoa-sulle-tracce-di-stevenson-schwob-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/verso-samoa-sulle-tracce-di-stevenson-schwob-1.jpg\",\"width\":500,\"height\":751},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"verso samoa sulle tracce di stevenson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791280246028\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"verso samoa sulle tracce di stevenson - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"verso samoa sulle tracce di stevenson","og_description":"Author: marcel schwobPublisher: tarka edizioni srlISBN: 9791280246028","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:25:59+00:00","og_image":[{"width":500,"height":751,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/verso-samoa-sulle-tracce-di-stevenson-schwob-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,50","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/","name":"verso samoa sulle tracce di stevenson - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/verso-samoa-sulle-tracce-di-stevenson-schwob-1.jpg","datePublished":"2021-02-05T13:41:40+00:00","dateModified":"2026-03-14T02:25:59+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/verso-samoa-sulle-tracce-di-stevenson-schwob-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/verso-samoa-sulle-tracce-di-stevenson-schwob-1.jpg","width":500,"height":751},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/verso-samoa-sulle-tracce-di-stevenson-marcel-schwob-9791280246028\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"verso samoa sulle tracce di stevenson"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791280246028","product_condition":"new"},"df_price":14.5,"df_sale_price":"","df_regular_price":14.5,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/verso-samoa-sulle-tracce-di-stevenson-schwob-1-200x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/95813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=95813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/122229"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=95813"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=95813"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=95813"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=95813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}