{"id":95529,"date":"2021-07-06T19:01:10","date_gmt":"2021-07-06T17:01:10","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/"},"modified":"2026-03-14T03:09:46","modified_gmt":"2026-03-14T02:09:46","slug":"777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/","title":{"rendered":"777 pilot book &#8211; sardinia &#8211; from stintino to cannigione, asinara island and la maddalena archipelago. corsica &#8211; from propriano to porto vecchio, ile cavallo and ile lavezzi"},"content":{"rendered":"<p>The <em>777<\/em> pilot book series has been prepared in the tradition of the ancient portolans (pilot charts), that used to include <strong>charts, chartlets and also de&shy;scriptions of harbours and shelters<\/strong>.<\/p>\n<p>As a result, users today have an <strong>au&shy;thoritative, comprehensive and use&shy;ful tool to navigate in safety<\/strong> whilst maximising enjoyment.<\/p>\n<p>The strengths underlined by the publisher are:<\/p>\n<ul>\n<li>personal inspection to all the <strong>moorings and anchorages and their surroundings<\/strong>;<\/li>\n<li>network of on-the-ground researchers to collect <strong>information and<\/strong> provide<strong> updates<\/strong>;<\/li>\n<li>suggestions of <strong>onshore itineraries and services useful to yachtsmen<\/strong>;<\/li>\n<li><strong>telephone helpline<\/strong> for assistance;<\/li>\n<li><strong>video tutorials of the main ports and anchorages<\/strong>.<\/li>\n<\/ul>\n<p>The goal is to accompany readers and provide them with <strong>faithful and up-to-date information<\/strong>.<\/p>\n<ul>\n<li><strong>160 Colour Pages<\/strong><\/li>\n<li><strong>55 General Charts<\/strong><\/li>\n<li><strong>165 Nautical Plans<\/strong><\/li>\n<\/ul>\n<p>Edition: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>sea routes 29<\/p>\n<p class=\"autore\"><span>Author: <\/span>dario silvestro &#8211; marco sbrizzi &#8211; piero magnabosco<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni magnamare<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862000659<\/p>\n","protected":false},"featured_media":100980,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2705,2691],"product_tag":[],"class_list":{"0":"post-95529","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-coe","7":"product_cat-oke","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>777 pilot book - sardinia - from stintino to cannigione, asinara island and la maddalena archipelago. corsica - from propriano to porto vecchio, ile cavallo and ile lavezzi - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"777 pilot book - sardinia - from stintino to cannigione, asinara island and la maddalena archipelago. corsica - from propriano to porto vecchio, ile cavallo and ile lavezzi\" \/>\n<meta property=\"og:description\" content=\"Subtitle: sea routes 29Author: dario silvestro - marco sbrizzi - piero magnaboscoPublisher: edizioni magnamareISBN: 9788862000659\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:09:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\\\/\",\"name\":\"777 pilot book - sardinia - from stintino to cannigione, asinara island and la maddalena archipelago. corsica - from propriano to porto vecchio, ile cavallo and ile lavezzi - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5.jpg\",\"datePublished\":\"2021-07-06T17:01:10+00:00\",\"dateModified\":\"2026-03-14T02:09:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5.jpg\",\"width\":500,\"height\":708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"777 pilot book &#8211; sardinia &#8211; from stintino to cannigione, asinara island and la maddalena archipelago. corsica &#8211; from propriano to porto vecchio, ile cavallo and ile lavezzi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862000659\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"777 pilot book - sardinia - from stintino to cannigione, asinara island and la maddalena archipelago. corsica - from propriano to porto vecchio, ile cavallo and ile lavezzi - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"777 pilot book - sardinia - from stintino to cannigione, asinara island and la maddalena archipelago. corsica - from propriano to porto vecchio, ile cavallo and ile lavezzi","og_description":"Subtitle: sea routes 29Author: dario silvestro - marco sbrizzi - piero magnaboscoPublisher: edizioni magnamareISBN: 9788862000659","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:09:46+00:00","og_image":[{"width":500,"height":708,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;29,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/","name":"777 pilot book - sardinia - from stintino to cannigione, asinara island and la maddalena archipelago. corsica - from propriano to porto vecchio, ile cavallo and ile lavezzi - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5.jpg","datePublished":"2021-07-06T17:01:10+00:00","dateModified":"2026-03-14T02:09:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5.jpg","width":500,"height":708},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/777-pilot-book-sardinia-from-stintino-to-cannigione-asinara-island-and-la-maddalena-archipelago-corsica-from-propriano-to-porto-vecchio-ile-cavallo-and-ile-lavezzi-dario-silvestro-marco-sbrizzi-piero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"777 pilot book &#8211; sardinia &#8211; from stintino to cannigione, asinara island and la maddalena archipelago. corsica &#8211; from propriano to porto vecchio, ile cavallo and ile lavezzi"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"29.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788862000659","product_condition":"new"},"df_price":29.9,"df_sale_price":"","df_regular_price":29.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/777-pilot-book-sardinia-la-maddalena-corsica-propriano-to-porto-vecchio-edizioni-magnamare-5-212x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/95529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=95529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/100980"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=95529"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=95529"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=95529"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=95529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}