{"id":95418,"date":"2021-10-18T16:39:31","date_gmt":"2021-10-18T14:39:31","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/"},"modified":"2026-03-14T03:02:51","modified_gmt":"2026-03-14T02:02:51","slug":"le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/","title":{"rendered":"le mappe degli infiniti mondi possibili (national geographic)"},"content":{"rendered":"<p>Da migliaia di anni si creano mappe per descrivere, ricordare e comprendere il mondo: lo si faceva in epoche remote incidendo pelli di animali, lo si fa oggi manipolando pixel. I due autori, stimati giornalisti e creatori del blog di successo del National Geographic &#8220;All over the World&#8221;, hanno deciso di condividere la loro passione con questo libro, accompagnandovi in un viaggio a ritroso nel tempo e avanti nel futuro, in un&#8217;esplorazione del mondo con gli occhi di chi lo guarda da terra ma anche dal cielo, il tutto grazie all&#8217;arte e alla scienza della cartografia.&nbsp;<\/p>\n<p>In queste pagine, ricche di insolite e originali mappe, vedrete la costa sudamericana che d&agrave; sul Pacifico come appariva in uno dei primi atlanti spagnoli con cui un pirata inglese del XVII Secolo si compr&ograve; la libert&agrave;. Esaminerete le mappe dettagliate realizzate subito dopo il terremoto di San Francisco del 1906: la chiave della nostra moderna comprensione delle scienze della Terra e della tettonica a placche. Conoscerete il paesaggio olfattivo di Kiev procedendo &#8220;a naso&#8221; su una mappa contemporanea capace di esplorare i mutevoli profumi della citt&agrave;.<\/p>\n<p>Grazie a centinaia di mappe e grafici accompagnate da spiegazioni approfondite di cartografi, studiosi e curatori di collezioni, questo volume sapr&agrave; conquistare tutti i lettori insaziabilmente curiosi di conoscere il nostro mondo e i tanti modi che abbiamo trovato per rappresentarlo.<\/p>\n<p>Edizione: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>betsy mason &#8211; greg miller<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>national geographic (edizioni white star)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788854049017<\/p>\n","protected":false},"featured_media":147498,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2569],"product_tag":[],"class_list":{"0":"post-95418","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-navigation-history-chartography","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>le mappe degli infiniti mondi possibili (national geographic) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"le mappe degli infiniti mondi possibili (national geographic)\" \/>\n<meta property=\"og:description\" content=\"Author: betsy mason - greg millerPublisher: national geographic (edizioni white star)ISBN: 9788854049017\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T02:02:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mappe-degli-infiniti-mondi-possibili-mason-miller-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"536\" \/>\n\t<meta property=\"og:image:height\" content=\"634\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;40,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\\\/\",\"name\":\"le mappe degli infiniti mondi possibili (national geographic) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mappe-degli-infiniti-mondi-possibili-mason-miller-3.jpg\",\"datePublished\":\"2021-10-18T14:39:31+00:00\",\"dateModified\":\"2026-03-14T02:02:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mappe-degli-infiniti-mondi-possibili-mason-miller-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mappe-degli-infiniti-mondi-possibili-mason-miller-3.jpg\",\"width\":536,\"height\":634},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"le mappe degli infiniti mondi possibili (national geographic)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"40.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788854049017\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"le mappe degli infiniti mondi possibili (national geographic) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"le mappe degli infiniti mondi possibili (national geographic)","og_description":"Author: betsy mason - greg millerPublisher: national geographic (edizioni white star)ISBN: 9788854049017","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T02:02:51+00:00","og_image":[{"width":536,"height":634,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mappe-degli-infiniti-mondi-possibili-mason-miller-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;40,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/","name":"le mappe degli infiniti mondi possibili (national geographic) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mappe-degli-infiniti-mondi-possibili-mason-miller-3.jpg","datePublished":"2021-10-18T14:39:31+00:00","dateModified":"2026-03-14T02:02:51+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mappe-degli-infiniti-mondi-possibili-mason-miller-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mappe-degli-infiniti-mondi-possibili-mason-miller-3.jpg","width":536,"height":634},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-mappe-degli-infiniti-mondi-possibili-national-geographic-betsy-mason-greg-miller-9788854049017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"le mappe degli infiniti mondi possibili (national geographic)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"40.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788854049017","product_condition":"new"},"df_price":40,"df_sale_price":"","df_regular_price":40,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mappe-degli-infiniti-mondi-possibili-mason-miller-3-254x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/95418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=95418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/147498"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=95418"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=95418"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=95418"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=95418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}