{"id":94482,"date":"2019-02-03T20:04:02","date_gmt":"2019-02-03T19:04:02","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/"},"modified":"2026-03-14T04:37:54","modified_gmt":"2026-03-14T03:37:54","slug":"refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/","title":{"rendered":"refola &#8211; giro del mondo a tappe dal mediterraneo a panama"},"content":{"rendered":"<p>Spesso chi sogna di girare il mondo in barca &egrave; assalito da dubbi sulla radicalit&agrave; di tale scelta. Si ha il desiderio di &#8220;mollare gli ormeggi&#8221;, ma allo stesso tempo affetti, responsabilit&agrave;, problemi materiali e altro ancora creano un&rsquo;invisibile rete che ci tiene saldamente legati a terra. Alessandro e Liliana hanno sciolto il dilemma con una mediazione: ogni anno navigano per sette-otto mesi e trascorrono i mesi restanti a casa, dedicandosi alla cura delle relazioni e allo studio degli itinerari successivi. Questa alternanza corrisponde di fatto alla stagionalit&agrave; meteorologica: si naviga il pi&ugrave; a lungo possibile nelle migliori condizioni e si lascia la barca in luoghi sicuri quando arriva la stagione del maltempo. &Egrave; questo il senso del giro del mondo a tappe, di cui questo libro racconta la prima tratta dal Mediterraneo a Panama. Protagonisti, oltre agli armatori, sono Refola, un Amel Super Maramu 2000, amici e parenti ospitati a bordo, ma soprattutto i luoghi, le difficolt&agrave; di navigazione, i molteplici problemi di manutenzione e di gestione che uno skipper deve affrontare ogni giorno. Lo scambio di informazioni e impressioni &egrave; una delle maggiori ricchezze che i velisti possono condividere. A tale scopo ancoraggi, porti e rotte sono accuratamente descritti e illustrati con pianetti a disegno. Un libro utile a chi intende intraprendere una simile avventura, o anche solo sognarla. Il viaggio, preceduto da un paio d&rsquo;anni di preparazione e da due traversate atlantiche &#8220;di prova&#8221;, inizia nel 2012 da St. Louis du Rhone (Francia) ed &egrave; tuttora in corso. La terza tappa si &egrave; conclusa nel 2015 in Nuova Zelanda.<\/p>\n<p>Edizione: 2016<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>il portolano raccontato<\/p>\n<p class=\"autore\"><span>Author: <\/span>nodari a.  sannini l.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Edizioni Il Frangente<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788898023608<\/p>\n","protected":false},"featured_media":121241,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,2729],"product_tag":[],"class_list":{"0":"post-94482","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-rose","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>refola - giro del mondo a tappe dal mediterraneo a panama - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"refola - giro del mondo a tappe dal mediterraneo a panama\" \/>\n<meta property=\"og:description\" content=\"Subtitle: il portolano raccontatoAuthor: nodari a. sannini l.Publisher: Edizioni Il FrangenteISBN: 9788898023608\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T03:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/refola-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"412\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\\\/\",\"name\":\"refola - giro del mondo a tappe dal mediterraneo a panama - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/refola-3.jpg\",\"datePublished\":\"2019-02-03T19:04:02+00:00\",\"dateModified\":\"2026-03-14T03:37:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/refola-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/refola-3.jpg\",\"width\":412,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"refola &#8211; giro del mondo a tappe dal mediterraneo a panama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788898023608\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"refola - giro del mondo a tappe dal mediterraneo a panama - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"refola - giro del mondo a tappe dal mediterraneo a panama","og_description":"Subtitle: il portolano raccontatoAuthor: nodari a. sannini l.Publisher: Edizioni Il FrangenteISBN: 9788898023608","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T03:37:54+00:00","og_image":[{"width":412,"height":598,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/refola-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/","name":"refola - giro del mondo a tappe dal mediterraneo a panama - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/refola-3.jpg","datePublished":"2019-02-03T19:04:02+00:00","dateModified":"2026-03-14T03:37:54+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/refola-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/refola-3.jpg","width":412,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/refola-giro-del-mondo-a-tappe-dal-mediterraneo-a-panama-nodari-a-sannini-l-9788898023608\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"refola &#8211; giro del mondo a tappe dal mediterraneo a panama"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788898023608","product_condition":"new"},"df_price":22,"df_sale_price":"","df_regular_price":22,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/refola-3-207x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/94482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=94482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/121241"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=94482"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=94482"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=94482"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=94482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}