{"id":94342,"date":"2019-02-03T20:05:03","date_gmt":"2019-02-03T19:05:03","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/"},"modified":"2026-03-14T04:33:25","modified_gmt":"2026-03-14T03:33:25","slug":"la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/","title":{"rendered":"la patente nautica entro e oltre le 12 miglia a vela e a motore"},"content":{"rendered":"<p>&#8220;La patente nautica entro e oltre le 12 miglia a vela e a motore&#8221; frutto della lunga esperienza marinaresca e didattica di Massimo Caimmi, affronta con estrema chiarezza tutti i temi teorici e, per quel che &egrave; possibile, pratici previsti dal vasto programma d&#8217;esame, che spazia dalla normativa alle caratteristiche della barca, dal carteggio al meteo, per finire con la conduzione dell&#8217;imbarcazione a vela e a motore.<\/p>\n<p>Il volume &egrave; ricco di schemi, grafici, definizioni e tabelle, cos&igrave; da rendere familiare il lessico marinaresco e immediatamente comprensibili regole e manovre.<\/p>\n<p>A chiusura del libro 360 test di verifica consentono un articolato e pratico ripasso dell&#8217;intero programma d&#8217;esame.<\/p>\n<p>Questa nuova edizione illustra le nuove modalit&agrave; di esame, le norme di protezione dell&#8217;ambiente marino, l&#8217;aggiornamento delle dotazioni di sicurezza (cassetta di pronto soccorso) e, in appendice, il Nuovo Codice della Nautica da diporto, secondo il DL n. 229 del 3\/11\/2017.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>manuale di preparazione all&#8217;esame<\/p>\n<p class=\"autore\"><span>Author: <\/span>caimmi m.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ulrico hoepli editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788820389321<\/p>\n","protected":false},"featured_media":156508,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2987],"product_tag":[],"class_list":{"0":"post-94342","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boat-license","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>la patente nautica entro e oltre le 12 miglia a vela e a motore - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"la patente nautica entro e oltre le 12 miglia a vela e a motore\" \/>\n<meta property=\"og:description\" content=\"Subtitle: manuale di preparazione all&#039;esameAuthor: caimmi m.Publisher: ulrico hoepli editoreISBN: 9788820389321\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T03:33:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lapatentenauticaentroeoltrecaimmi-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"587\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\\\/\",\"name\":\"la patente nautica entro e oltre le 12 miglia a vela e a motore - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lapatentenauticaentroeoltrecaimmi-3.jpg\",\"datePublished\":\"2019-02-03T19:05:03+00:00\",\"dateModified\":\"2026-03-14T03:33:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lapatentenauticaentroeoltrecaimmi-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lapatentenauticaentroeoltrecaimmi-3.jpg\",\"width\":420,\"height\":587},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"la patente nautica entro e oltre le 12 miglia a vela e a motore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788820389321\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"la patente nautica entro e oltre le 12 miglia a vela e a motore - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"la patente nautica entro e oltre le 12 miglia a vela e a motore","og_description":"Subtitle: manuale di preparazione all'esameAuthor: caimmi m.Publisher: ulrico hoepli editoreISBN: 9788820389321","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T03:33:25+00:00","og_image":[{"width":420,"height":587,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lapatentenauticaentroeoltrecaimmi-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;29,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/","name":"la patente nautica entro e oltre le 12 miglia a vela e a motore - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lapatentenauticaentroeoltrecaimmi-3.jpg","datePublished":"2019-02-03T19:05:03+00:00","dateModified":"2026-03-14T03:33:25+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lapatentenauticaentroeoltrecaimmi-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lapatentenauticaentroeoltrecaimmi-3.jpg","width":420,"height":587},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-patente-nautica-entro-e-oltre-le-12-miglia-a-vela-e-a-motore-caimmi-m-9788820389321\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"la patente nautica entro e oltre le 12 miglia a vela e a motore"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"29.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788820389321","product_condition":"new"},"df_price":29.9,"df_sale_price":"","df_regular_price":29.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lapatentenauticaentroeoltrecaimmi-3-215x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/94342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=94342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/156508"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=94342"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=94342"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=94342"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=94342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}