{"id":94037,"date":"2019-02-03T20:07:09","date_gmt":"2019-02-03T19:07:09","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/"},"modified":"2026-03-14T04:23:47","modified_gmt":"2026-03-14T03:23:47","slug":"reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/","title":{"rendered":"reticolati per carteggio (serie M) su parallelo 38\u00b0 N &#8211; latitudine da 33\u00b0 a 36\u00b0 N"},"content":{"rendered":"<p>Blocco da 10 fogli<\/p>\n<p>Scala: 1:300.000<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"editore\"><span>Manufacturer: <\/span>istituto idrografico della marina (IIM)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>IDRO1003<\/p>\n","protected":false},"featured_media":45495,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2457],"product_tag":[],"class_list":{"0":"post-94037","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-other-charts-istituto-idrografico-della-marina-iim","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>reticolati per carteggio (serie M) su parallelo 38\u00b0 N - latitudine da 33\u00b0 a 36\u00b0 N - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"reticolati per carteggio (serie M) su parallelo 38\u00b0 N - latitudine da 33\u00b0 a 36\u00b0 N\" \/>\n<meta property=\"og:description\" content=\"Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO1003\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T03:23:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"367\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;33,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\\\/\",\"name\":\"reticolati per carteggio (serie M) su parallelo 38\u00b0 N - latitudine da 33\u00b0 a 36\u00b0 N - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n.jpg\",\"datePublished\":\"2019-02-03T19:07:09+00:00\",\"dateModified\":\"2026-03-14T03:23:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n.jpg\",\"width\":367,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"reticolati per carteggio (serie M) su parallelo 38\u00b0 N &#8211; latitudine da 33\u00b0 a 36\u00b0 N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"33.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"IDRO1003\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"reticolati per carteggio (serie M) su parallelo 38\u00b0 N - latitudine da 33\u00b0 a 36\u00b0 N - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"reticolati per carteggio (serie M) su parallelo 38\u00b0 N - latitudine da 33\u00b0 a 36\u00b0 N","og_description":"Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO1003","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T03:23:47+00:00","og_image":[{"width":367,"height":500,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;33,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/","name":"reticolati per carteggio (serie M) su parallelo 38\u00b0 N - latitudine da 33\u00b0 a 36\u00b0 N - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n.jpg","datePublished":"2019-02-03T19:07:09+00:00","dateModified":"2026-03-14T03:23:47+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n.jpg","width":367,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/reticolati-per-carteggio-serie-m-su-parallelo-38-n-latitudine-da-33-a-36-n-idro1003\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"reticolati per carteggio (serie M) su parallelo 38\u00b0 N &#8211; latitudine da 33\u00b0 a 36\u00b0 N"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"33.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"IDRO1003","product_condition":"new"},"df_price":33,"df_sale_price":"","df_regular_price":33,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1003reticolatipercarteggioseriemsuparallelo38nlatitudineda33a36n-220x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/94037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=94037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/45495"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=94037"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=94037"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=94037"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=94037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}