{"id":93327,"date":"2019-02-03T19:46:03","date_gmt":"2019-02-03T18:46:03","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/bimbi-a-bordo-cestari-a-9788887913934\/"},"modified":"2026-03-14T05:58:09","modified_gmt":"2026-03-14T04:58:09","slug":"bimbi-a-bordo-andrea-cestari-9788887913934","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/","title":{"rendered":"bimbi a bordo"},"content":{"rendered":"<p>L&#8217;obbiettivo principale di questo libro &egrave; quello di dimostrare che la vita a bordo di una barca a vela &egrave; possibile, senza particolari sacrifici, anche per i bambini; che &egrave; possibile programmare lunghe navigazioni con la propria famiglia, anche se composta da figli piccoli. Il libro &egrave; corredato da&nbsp;schede esplicative e check list per non dimenticare nulla!<\/p>\n<p>Edizione: 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>come programmare la crociera con i figli<\/p>\n<p class=\"autore\"><span>Author: <\/span>andrea cestari<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>magenes editoriale<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788887913934<\/p>\n","protected":false},"featured_media":127102,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2769,2578],"product_tag":[],"class_list":{"0":"post-93327","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dropping-everything","7":"product_cat-books-sailing-cruising-and-regatta","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>bimbi a bordo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bimbi a bordo\" \/>\n<meta property=\"og:description\" content=\"Subtitle: come programmare la crociera con i figliAuthor: andrea cestariPublisher: magenes editorialeISBN: 9788887913934\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T04:58:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/bimbibordo-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"437\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/bimbi-a-bordo-andrea-cestari-9788887913934\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/bimbi-a-bordo-andrea-cestari-9788887913934\\\/\",\"name\":\"bimbi a bordo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/bimbi-a-bordo-andrea-cestari-9788887913934\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/bimbi-a-bordo-andrea-cestari-9788887913934\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/bimbibordo-5.jpg\",\"datePublished\":\"2019-02-03T18:46:03+00:00\",\"dateModified\":\"2026-03-14T04:58:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/bimbi-a-bordo-andrea-cestari-9788887913934\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/bimbi-a-bordo-andrea-cestari-9788887913934\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/bimbi-a-bordo-andrea-cestari-9788887913934\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/bimbibordo-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/bimbibordo-5.jpg\",\"width\":437,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/bimbi-a-bordo-andrea-cestari-9788887913934\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"bimbi a bordo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788887913934\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"bimbi a bordo - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"bimbi a bordo","og_description":"Subtitle: come programmare la crociera con i figliAuthor: andrea cestariPublisher: magenes editorialeISBN: 9788887913934","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T04:58:09+00:00","og_image":[{"width":437,"height":608,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/bimbibordo-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/","name":"bimbi a bordo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/bimbibordo-5.jpg","datePublished":"2019-02-03T18:46:03+00:00","dateModified":"2026-03-14T04:58:09+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/bimbibordo-5.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/bimbibordo-5.jpg","width":437,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/bimbi-a-bordo-andrea-cestari-9788887913934\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"bimbi a bordo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788887913934","product_condition":"new"},"df_price":14,"df_sale_price":"","df_regular_price":14,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/bimbibordo-5-216x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/93327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=93327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/127102"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=93327"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=93327"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=93327"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=93327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}