{"id":92873,"date":"2019-02-03T19:49:20","date_gmt":"2019-02-03T18:49:20","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/"},"modified":"2026-03-14T05:43:00","modified_gmt":"2026-03-14T04:43:00","slug":"venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/","title":{"rendered":"venti sfide per la coppa america"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Ugo Mursia &amp; C. del 1970 in ottimo stato di conservazione, collana &#8220;Biblioteca del Mare&#8221; 26 (Storia, regate, viaggi e avventure 13). In-8, legatura editoriale con copertina rigida telata blu e incisioni oro sul piatto anteriore e sul dorso; ex libris incollato sul risguardo in seconda, sovraccoperta in carta illustrata a colori con alette; 216 pp., con 22 fotografie fuori testo. Pagine ingiallite. Con volantino promozionale coevo.<\/strong><\/p>\n<p><strong>Traduzione di Silvia Minas.<\/strong><\/p>\n<p>Il prestigio della Coppa America &egrave; senza eguali nella storia delle regate per yacht a vela. Da quando la goletta America, attraversato l&#8217;Atlantico, vinse questo trofeo d&#8217;argento nel 1851 in una serie di regate contro i migliori yacht inglesi, la Coppa &egrave; stata portata negli Stati Uniti e vi &egrave; rimasta. Venti volte, nel corso di un secolo, gli sfidanti (inglesi, canadesi e australiani) hanno tentato invano di riconquistarla.<\/p>\n<p>Ma questi tentativi sono stati altrettanti esempi di yachting &#8220;al vertice&#8221;, di sport della vela a un livello unico. Per ogni sfida sono stati costruiti appositamente dei tipi di barche &#8220;estremi&#8221;, che comprendevano delle novit&agrave; decisive, e i migliori equipaggi hanno svolto un addestramento specifico e hanno impegnato tutte le loro capacit&agrave; marinare.<\/p>\n<p>La partecipazione a una sfida per la Coppa America, che coinvolge una spesa ingente, &egrave; al tempo stesso una manifestazione di passione sportiva e di alta specializzazione. Solo uno dei pi&ugrave; grandi nomi dello yachting mondiale, che ha avuto anche un&#8217;esperienza personale nella Coppa America, poteva tracciare degnamente, per gli intenditori e per i semplici appassionati di vela, la storia delle venti sfide.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>john h. illingworth<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1594390615<\/p>\n","protected":false},"featured_media":129038,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,2608],"product_tag":[],"class_list":{"0":"post-92873","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-reports-and-essays","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>venti sfide per la coppa america - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"venti sfide per la coppa america\" \/>\n<meta property=\"og:description\" content=\"Author: john h. illingworthPublisher: Ugo Mursia EditoreISBN: LDM1594390615\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T04:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"522\" \/>\n\t<meta property=\"og:image:height\" content=\"913\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;23,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\\\/\",\"name\":\"venti sfide per la coppa america - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-rotated.jpg\",\"datePublished\":\"2019-02-03T18:49:20+00:00\",\"dateModified\":\"2026-03-14T04:43:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-rotated.jpg\",\"width\":522,\"height\":913},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"venti sfide per la coppa america\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"23.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1594390615\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"venti sfide per la coppa america - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"venti sfide per la coppa america","og_description":"Author: john h. illingworthPublisher: Ugo Mursia EditoreISBN: LDM1594390615","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T04:43:00+00:00","og_image":[{"width":522,"height":913,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-rotated.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;23,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/","name":"venti sfide per la coppa america - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-rotated.jpg","datePublished":"2019-02-03T18:49:20+00:00","dateModified":"2026-03-14T04:43:00+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-rotated.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-rotated.jpg","width":522,"height":913},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venti-sfide-per-la-coppa-america-john-h-illingworth-ldm1594390615\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"venti sfide per la coppa america"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"23.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1594390615","product_condition":"new"},"df_price":23,"df_sale_price":"","df_regular_price":23,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venti-sfide-per-la-coppa-america-illingworth-mursia-2-172x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/92873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=92873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/129038"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=92873"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=92873"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=92873"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=92873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}