{"id":92501,"date":"2019-02-03T19:52:16","date_gmt":"2019-02-03T18:52:16","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/"},"modified":"2026-03-14T05:30:26","modified_gmt":"2026-03-14T04:30:26","slug":"manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/","title":{"rendered":"manuale di diritto della navigazione marittima, interna e aerea"},"content":{"rendered":"<p>Questo volume giunge alla diciannovesima edizione, che tiene conto della evoluzione normativa internazionale, comunitaria e interna. La presente edizione &egrave; aggiornata: al decreto legislativo 13 dicembre 2017, n. 232, recante disposizioni integrative e correttive al decreto legislativo 4 agosto 2016, n. 169, concernente le autorit&agrave; portuali; al decreto legislativo 3 novembre 2017, n. 229, recante revisione ed integrazione del decreto legislativo 18 luglio 2005, n. 171 &laquo;Codice della nautica da diporto&raquo;; al regolamento UE 2017\/386 della Commissione, del 6 marzo 2017, che modifica il regolamento di esecuzione (UE) n. 1207\/2011 che stabilisce requisiti di prestazione e interoperabilit&agrave; per la sorveglianza del cielo unico europeo; al regolamento UE 2017\/373 del della Commissione, del 1&deg; marzo 2017, che stabilisce i requisiti comuni per i fornitori di servizi di gestione del traffico aereo e di navigazione aerea e di altre funzioni della rete di gestione del traffico aereo e per la loro sorveglianza, che abroga il regolamento (CE) n. 482\/2008 e i regolamenti di esecuzione (UE) n. 1034\/2011, (UE) n. 1035\/2011 e (UE) 2016\/1377 e che modifica il regolamento (UE) n. 677\/2011; al regolamento (UE) 2017\/352 del Parlamento europeo e del Consiglio del 15 febbraio 2017, che istituisce un quadro normativo per la fornitura di servizi portuali e norme comuni in materia di trasparenza finanziaria dei porti; alla legge 1&deg; dicembre 2016, n. 230, recante modifiche al codice della navigazione in materia di responsabilit&agrave; dei piloti dei porti e disposizioni in materia di servizi tecnico-nautici; al decreto legislativo 29 ottobre 2016, n. 221, recante il riordino delle disposizioni legislative vigenti in materia di incentivi fiscali, previdenziali e contributivi in favore delle imprese marittime, a norma dell&#8217;articolo 24, comma 11, della legge 7 luglio 2016, n. 122; al decreto legislativo 17 ottobre 2016, n. 201, recante attuazione della direttiva 2014\/89\/ UE che istituisce un quadro per la pianificazione dello spazio marittimo; al decreto legislativo 4 agosto 2016, n. 169, recante la riorganizzazione, razionalizzazione e semplificazione della disciplina concernente le autorit&agrave; portuali di cui alla legge 28 gennaio 1994, n. 84, in attuazione dell&#8217;articolo 8, comma 1, lettera f), della legge 7 agosto 2015, n. 124; al decreto legislativo 7 gennaio 2016, n. 4, recante la attuazione della direttiva 2014\/100\/ UE che modifica la direttiva 2002\/59\/CE, relativa all&#8217;istituzione di un sistema comunitario di monitoraggio del traffico navale e dell&#8217;informazione. Il testo, redatto in forma chiara e scorrevole, si propone come valido strumento per esami, concorsi e tirocinio professionale nonch&eacute;, per la completezza della trattazione e la cura del linguaggio e della esposizione, come manuale di base per gli Istituti tecnologici ad indirizzo trasporti.<\/p>\n<p>Edizione: 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>aldo fiale &#8211; massimiliano grimaldi<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni simone<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788891416902<\/p>\n","protected":false},"featured_media":91191,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2629],"product_tag":[],"class_list":{"0":"post-92501","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-law","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>manuale di diritto della navigazione marittima, interna e aerea - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"manuale di diritto della navigazione marittima, interna e aerea\" \/>\n<meta property=\"og:description\" content=\"Author: aldo fiale - massimiliano grimaldiPublisher: edizioni simoneISBN: 9788891416902\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T04:30:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"702\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;24,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\\\/\",\"name\":\"manuale di diritto della navigazione marittima, interna e aerea - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1.jpg\",\"datePublished\":\"2019-02-03T18:52:16+00:00\",\"dateModified\":\"2026-03-14T04:30:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1.jpg\",\"width\":500,\"height\":702},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"manuale di diritto della navigazione marittima, interna e aerea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788891416902\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"manuale di diritto della navigazione marittima, interna e aerea - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"manuale di diritto della navigazione marittima, interna e aerea","og_description":"Author: aldo fiale - massimiliano grimaldiPublisher: edizioni simoneISBN: 9788891416902","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T04:30:26+00:00","og_image":[{"width":500,"height":702,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;24,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/","name":"manuale di diritto della navigazione marittima, interna e aerea - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1.jpg","datePublished":"2019-02-03T18:52:16+00:00","dateModified":"2026-03-14T04:30:26+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1.jpg","width":500,"height":702},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-di-diritto-della-navigazione-marittima-interna-e-aerea-aldo-fiale-massimiliano-grimaldi-9788891416902\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"manuale di diritto della navigazione marittima, interna e aerea"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"24.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788891416902","product_condition":"new"},"df_price":24,"df_sale_price":"","df_regular_price":24,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manuale-di-diritto-della-navigazione-marittima-interna-ed-aerea-simone-1-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/92501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=92501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/91191"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=92501"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=92501"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=92501"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=92501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}