{"id":92342,"date":"2019-02-03T19:53:25","date_gmt":"2019-02-03T18:53:25","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/"},"modified":"2026-03-14T05:24:56","modified_gmt":"2026-03-14T04:24:56","slug":"costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/","title":{"rendered":"costruzione e manovra delle barche e imbarcazioni a velatura latina"},"content":{"rendered":"<p>&#8220;Costruzione e manovra delle barche e imbarcazioni a velatura latina&#8221; &egrave; un&rsquo;opera di tipo manualistico, che offre tutte le indicazioni (piano, natura e campioni di legno, chiodatura, accastellamento e armamento) necessarie alla costruzione di tutti i piccoli bastimenti (battelli da lavoro, da pesca e &#8220;battelli sperone armati&#8221; da diporto) che frequentano la costa mediterranea, dallo stagno di Berre a Antibes. Le tavole (in scala 1\/25 e 1\/20) permettono la realizzazione di modelli di gran qualit&agrave;. La seconda parte dell&rsquo;opera tratta la manovra delle vele latine.<\/p>\n<p>Stampa su carta offset avorio.<\/p>\n<p>Rilegatura in piena tela blu&nbsp;navy con fettuccia.<\/p>\n<p>Titoli dorati sul dorso e sul piatto.<\/p>\n<p>Ristampa in fac-simile dell&rsquo;edizione originale del 1897.<\/p>\n<p>Edizione: 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>pesca &#8211; attrezzatura &#8211; manovra &#8211; diporto<\/p>\n<p class=\"autore\"><span>Author: <\/span>vence j.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ancre (architecture navale classique recherche edition)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791096873296<\/p>\n","protected":false},"featured_media":149246,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2784,3005,2578],"product_tag":[],"class_list":{"0":"post-92342","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boat-building","7":"product_cat-other-publications","8":"product_cat-books-sailing-cruising-and-regatta","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>costruzione e manovra delle barche e imbarcazioni a velatura latina - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"costruzione e manovra delle barche e imbarcazioni a velatura latina\" \/>\n<meta property=\"og:description\" content=\"Subtitle: pesca - attrezzatura - manovra - diportoAuthor: vence j.Publisher: ancre (architecture navale classique recherche edition)ISBN: 9791096873296\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T04:24:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"412\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;75,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\\\/\",\"name\":\"costruzione e manovra delle barche e imbarcazioni a velatura latina - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102.jpg\",\"datePublished\":\"2019-02-03T18:53:25+00:00\",\"dateModified\":\"2026-03-14T04:24:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102.jpg\",\"width\":412,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"costruzione e manovra delle barche e imbarcazioni a velatura latina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"75.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791096873296\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"costruzione e manovra delle barche e imbarcazioni a velatura latina - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"costruzione e manovra delle barche e imbarcazioni a velatura latina","og_description":"Subtitle: pesca - attrezzatura - manovra - diportoAuthor: vence j.Publisher: ancre (architecture navale classique recherche edition)ISBN: 9791096873296","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T04:24:56+00:00","og_image":[{"width":412,"height":595,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;75,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/","name":"costruzione e manovra delle barche e imbarcazioni a velatura latina - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102.jpg","datePublished":"2019-02-03T18:53:25+00:00","dateModified":"2026-03-14T04:24:56+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102.jpg","width":412,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/costruzione-e-manovra-delle-barche-e-imbarcazioni-a-velatura-latina-vence-j-9791096873296\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"costruzione e manovra delle barche e imbarcazioni a velatura latina"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"75.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9791096873296","product_condition":"new"},"df_price":75,"df_sale_price":"","df_regular_price":75,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/costruzioneemanovradellebarcheeimbarcazioniavelaturalatina-vence-20250527-131102-208x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/92342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=92342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/149246"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=92342"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=92342"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=92342"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=92342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}