{"id":91924,"date":"2019-02-03T19:56:35","date_gmt":"2019-02-03T18:56:35","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/"},"modified":"2026-03-14T05:10:31","modified_gmt":"2026-03-14T04:10:31","slug":"guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/","title":{"rendered":"guida dei fondi conservati presso l&#8217;archivio dell&#8217;ufficio storico della marina militare"},"content":{"rendered":"<p>La guida contiene una descrizione sintetica di tutti i fondi conservati presso l&rsquo;Archivio dell&rsquo;U.S.M.M. Per ogni fondo vengono fornite le seguenti informazioni: denominazione, consistenza, estremi cronologici, cenni storicoculturali sugli enti produttori delle carte, breve descrizione dell&rsquo;argomento trattato e della tipologia della documentazione. La pubblicazione della guida risponde all&rsquo;esigenza, sentita come necessaria, di permettere una fruizione migliore del patrimonio documentario da parte dei ricercatori.<\/p>\n<p>Edizione: 2004<\/p>\n<p>Costo del libro &euro; 24,00 + &euro; 7,00 per la consegna in libreria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>lazzerini c.  precone m.r.  venerosi pesciolini a.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ufficio storico della marina militare<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788898485666<\/p>\n","protected":false},"featured_media":129895,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3036],"product_tag":[],"class_list":{"0":"post-91924","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-other-essays","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>guida dei fondi conservati presso l&#039;archivio dell&#039;ufficio storico della marina militare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"guida dei fondi conservati presso l&#039;archivio dell&#039;ufficio storico della marina militare\" \/>\n<meta property=\"og:description\" content=\"Author: lazzerini c. precone m.r. venerosi pesciolini a.Publisher: ufficio storico della marina militareISBN: 9788898485666\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T04:10:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/guidadeifondiconservatipressolusmm-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"226\" \/>\n\t<meta property=\"og:image:height\" content=\"303\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;31,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\\\/\",\"name\":\"guida dei fondi conservati presso l'archivio dell'ufficio storico della marina militare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/guidadeifondiconservatipressolusmm-2.jpg\",\"datePublished\":\"2019-02-03T18:56:35+00:00\",\"dateModified\":\"2026-03-14T04:10:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/guidadeifondiconservatipressolusmm-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/guidadeifondiconservatipressolusmm-2.jpg\",\"width\":226,\"height\":303},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"guida dei fondi conservati presso l&#8217;archivio dell&#8217;ufficio storico della marina militare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"31.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788898485666\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"guida dei fondi conservati presso l'archivio dell'ufficio storico della marina militare - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"guida dei fondi conservati presso l'archivio dell'ufficio storico della marina militare","og_description":"Author: lazzerini c. precone m.r. venerosi pesciolini a.Publisher: ufficio storico della marina militareISBN: 9788898485666","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T04:10:31+00:00","og_image":[{"width":226,"height":303,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/guidadeifondiconservatipressolusmm-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;31,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/","name":"guida dei fondi conservati presso l'archivio dell'ufficio storico della marina militare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/guidadeifondiconservatipressolusmm-2.jpg","datePublished":"2019-02-03T18:56:35+00:00","dateModified":"2026-03-14T04:10:31+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/guidadeifondiconservatipressolusmm-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/guidadeifondiconservatipressolusmm-2.jpg","width":226,"height":303},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/guida-dei-fondi-conservati-presso-l-archivio-dell-ufficio-storico-della-marina-militare-lazzerini-c-precone-m-r-venerosi-pesciolini-a-9788898485666\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"guida dei fondi conservati presso l&#8217;archivio dell&#8217;ufficio storico della marina militare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"31.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788898485666","product_condition":"new"},"df_price":31,"df_sale_price":"","df_regular_price":31,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/guidadeifondiconservatipressolusmm-2-224x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/91924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=91924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/129895"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=91924"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=91924"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=91924"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=91924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}