{"id":91832,"date":"2019-02-03T19:57:24","date_gmt":"2019-02-03T18:57:24","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/"},"modified":"2026-03-14T05:07:16","modified_gmt":"2026-03-14T04:07:16","slug":"marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/","title":{"rendered":"marche (tascabili per viaggiare)"},"content":{"rendered":"<p>Fra nord e sud In viaggio da decenni tra Bolzano e Palermo, considero le Marche come una sorta di Italia in miniatura. Condivido quindi l&rsquo;opinione di un celebre giornalista italiano, Guido Piovene (1907-1974), che una volta ha definito le Marche il paesaggio pi&ugrave; tipico dell&rsquo;Italia. &Egrave; vero che lo scrisse nel 1957, quando il turismo di massa era ancora agli inizi e il panorama sulle belle acque azzurre dell&rsquo;Adriatico non era ancora stato alterato dal cemento grigio dei complessi alberghieri e da file interminabili di ombrelloni. Tuttavia, se si distoglie lo sguardo dagli scempi architettonici degli anni &lsquo;60 e &lsquo;70, nelle Marche ancora oggi si trova tutto quello che da secoli nel Bel Paese affascina in egual misura i viaggiatori appassionati di cultura, i vacanzieri in cerca di mare e spiagge e i turisti buongustai. Natura e architettura Questa regione all&#8217;inizio si estende pianeggiante come l&rsquo;Emilia-Romagna, poi diviene dolcemente ondulata come il Capo Vaticano calabrese, e ai piedi del Monte Conero presenta addirittura falesie a strapiombo sul mare come il Gargano pugliese. Agli amanti dell&rsquo;acqua e agli adoratori del sole offre spiagge sabbiose lunghe e larghe, ma anche romantiche calette rocciose. Nell&#8217;interno si resta incantati da un paesaggio di colline verde dorato di sapore toscano, ammantato di boschi, prati e vigneti, intercalati da campi di grano ondeggianti e uliveti dai riflessi d&rsquo;argento. Su tutto questo vegliano a ovest gli Appennini e a sud le cime innevate dei Monti Sibillini, che raggiungono i duemila metri. Questi ultimi fanno battere forte il cuore degli appassionati di botanica, e dagli amanti delle escursioni in montagna pretendono tanto quanto le Alpi dell&rsquo;Alto Adige, presentandosi in certi punti solitari come l&rsquo;Aspromonte calabrese. Nelle valli dei fiumi Metauro e Tronto, percorrendo la Via Flaminia e la Via Salaria si seguono le tracce dei carri degli antichi Romani e si oltrepassano le rovine di civilt&agrave; arcaiche. In cima ai colli si ergono chiese, conventi e castelli medioevali avvolti da leggende, nonch&eacute; citt&agrave; dall&#8217;architettura e dall&#8217;atmosfera affascinanti come Urbino, che &egrave; stata dichiarata patrimonio dell&rsquo;umanit&agrave; dall&#8217;Unesco ed &egrave; il complesso urbano meglio conservato del Rinascimento italiano. La pittoresca piazza centrale di Ascoli Piceno pu&ograve; gareggiare con il Campo di Siena, cos&igrave; come lo Sferisterio di Macerata pu&ograve; competere tranquillamente con l&rsquo;Arena di Verona, mentre il Santuario della Madonna di Loreto, al pari della Basilica di San Pietro a Roma, esercita un&rsquo;attrazione spirituale anche sui non credenti. Cultura e cucina In tutte le citt&agrave;, anche le pi&ugrave; piccole, vi attende almeno un museo, che sorprende con reperti archeologici spettacolari o dipinti di grande valore del periodo gotico, rinascimentale o contemporaneo. Altri spiegano ai visitatori tradizioni artigianali locali o narrano le vicende della vita di un loro figlio illustre. Nel terreno creativo delle Marche, infatti, crebbero giganti della cultura quali Raffaello, Rossini o Leopardi, fiorirono la commedia dell&rsquo;arte e l&rsquo;opera buffa e spuntarono teatri incantevoli che oggi lasciano letteralmente stupiti. Le Marche sono un paradiso culinario nel quale si pu&ograve; gustare ovunque del buon vino, rifocillarsi con frutti di mare e pesce appena presi o percepire nelle specialit&agrave; di carne, negli insaccati e nei formaggi, che gli animali da cui provengono sono stati allevati in modo sano. I marchigiani producono vini italiani di qualit&agrave; come il Verdicchio dei Castelli di Jesi e il Rosso Piceno, offrono un tartufo pregiato come quello del Piemonte, mentre con Ancona e San Benedetto del Tronto gestiscono due dei maggiori porti pescherecci del Paese. Inoltre producono ed esportano oli d&rsquo;oliva pregiati, pasta, carta, strumenti musicali, tessuti, calzature e mobili di design. Sono meno benestanti dei loro connazionali nel nord altamente industrializzato, ma in posizione migliore rispetto ai loro vicini del sud, con i quali condividono uno spiccato senso dell&rsquo;ospitalit&agrave;.<\/p>\n<p>288 pagine a colori con informazioni e proposte per ogni tipo di esigenza e necessit&agrave;, accuratamente descritte dagli autori che vivono sul posto. Ideale per le tue vacanze da 1 a tre settimane.<\/p>\n<p>Libro con mappa staccabile.<\/p>\n<p>Edizione: 2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>krus-bonazza a.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>dumont (guido tommasi editore)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788897749417<\/p>\n","protected":false},"featured_media":82217,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2398,2643],"product_tag":[],"class_list":{"0":"post-91832","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-street-and-tourist-maps","7":"product_cat-veneto-friuli-venezia-giulia-emilia-romagna-and-marche","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>marche (tascabili per viaggiare) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"marche (tascabili per viaggiare)\" \/>\n<meta property=\"og:description\" content=\"Author: krus-bonazza a.Publisher: dumont (guido tommasi editore)ISBN: 9788897749417\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T04:07:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/marchedumont2-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"392\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;17,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\\\/\",\"name\":\"marche (tascabili per viaggiare) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/marchedumont2-2.jpg\",\"datePublished\":\"2019-02-03T18:57:24+00:00\",\"dateModified\":\"2026-03-14T04:07:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/marchedumont2-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/marchedumont2-2.jpg\",\"width\":392,\"height\":609},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"marche (tascabili per viaggiare)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"17.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788897749417\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"marche (tascabili per viaggiare) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"marche (tascabili per viaggiare)","og_description":"Author: krus-bonazza a.Publisher: dumont (guido tommasi editore)ISBN: 9788897749417","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T04:07:16+00:00","og_image":[{"width":392,"height":609,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/marchedumont2-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;17,90","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/","name":"marche (tascabili per viaggiare) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/marchedumont2-2.jpg","datePublished":"2019-02-03T18:57:24+00:00","dateModified":"2026-03-14T04:07:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/marchedumont2-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/marchedumont2-2.jpg","width":392,"height":609},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/marche-tascabili-per-viaggiare-krus-bonazza-a-9788897749417\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"marche (tascabili per viaggiare)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"17.90","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788897749417","product_condition":"new"},"df_price":17.9,"df_sale_price":"","df_regular_price":17.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/marchedumont2-2-193x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/91832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=91832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/82217"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=91832"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=91832"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=91832"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=91832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}