{"id":89755,"date":"2019-02-03T19:41:53","date_gmt":"2019-02-03T18:41:53","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/"},"modified":"2026-03-14T06:18:05","modified_gmt":"2026-03-14T05:18:05","slug":"isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/","title":{"rendered":"isole di ventotene e santo stefano"},"content":{"rendered":"<p>&#8220;Isole di Ventotene e Santo Stefano&#8221; &egrave; un libro fotografico di grande formato su due piccole isole in mezzo al Tirreno, che hanno un patrimonio di meraviglie incredibilmente ricco. Le immagini di questo volume mostrano un paesaggio grandioso, un mare infinito. Ventotene si presenta bene con il suo porto antico scavato dai romani nel tufo, il suo paese colorato, i suoi vicoli, il suo piccolo museo carico di storia. L&rsquo;isola di Santo Stefano &egrave; disabitata, con il carcere borbonico, un&rsquo;architettura particolare, inquietante ma di grande fascino. Poi le immagini scendono sott&#8217;acqua e ci mostrano barracuda, creature del mare, una biologia molto varia, coloratissima. Il relitto del Santa Lucia e la sua tragica storia &egrave; raccontata e illustrata da Roberto Rinaldi, uno tra i pi&ugrave; bravi fotografi d&rsquo;Italia e del mondo.<\/p>\n<p>Costo del libro &euro; 45,00 + &euro; 7,00 per la consegna in libreria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>area marina protetta<\/p>\n<p class=\"autore\"><span>Author: <\/span>folco quilici  luca tamagnini  roberto rinaldi  fernando spina<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>photoatlante<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>8886967055<\/p>\n","protected":false},"featured_media":135450,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3110],"product_tag":[],"class_list":{"0":"post-89755","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-italy-picture-books-tourism","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>isole di ventotene e santo stefano - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"isole di ventotene e santo stefano\" \/>\n<meta property=\"og:description\" content=\"Subtitle: area marina protettaAuthor: folco quilici luca tamagnini roberto rinaldi fernando spinaPublisher: photoatlanteISBN: 8886967055\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T05:18:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"553\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;52,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\\\/\",\"name\":\"isole di ventotene e santo stefano - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4.jpg\",\"datePublished\":\"2019-02-03T18:41:53+00:00\",\"dateModified\":\"2026-03-14T05:18:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4.jpg\",\"width\":540,\"height\":553},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"isole di ventotene e santo stefano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"52.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"8886967055\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"isole di ventotene e santo stefano - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"isole di ventotene e santo stefano","og_description":"Subtitle: area marina protettaAuthor: folco quilici luca tamagnini roberto rinaldi fernando spinaPublisher: photoatlanteISBN: 8886967055","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T05:18:05+00:00","og_image":[{"width":540,"height":553,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;52,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/","name":"isole di ventotene e santo stefano - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4.jpg","datePublished":"2019-02-03T18:41:53+00:00","dateModified":"2026-03-14T05:18:05+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4.jpg","width":540,"height":553},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/isole-di-ventotene-e-santo-stefano-folco-quilici-luca-tamagnini-roberto-rinaldi-fernando-spina-8886967055\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"isole di ventotene e santo stefano"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"52.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"8886967055","product_condition":"new"},"df_price":52,"df_sale_price":"","df_regular_price":52,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isole-di-ventotene-e-santo-stefano-quilici-tamagnnin-4-293x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/89755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=89755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/135450"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=89755"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=89755"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=89755"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=89755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}