{"id":89279,"date":"2019-02-03T19:45:13","date_gmt":"2019-02-03T18:45:13","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/storia-delle-battaglie-sul-mare-da-fr-g-9788862882293\/"},"modified":"2026-03-14T06:02:03","modified_gmt":"2026-03-14T05:02:03","slug":"storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/","title":{"rendered":"storia delle battaglie sul mare"},"content":{"rendered":"<p>Un saggio appassionante che si propone di selezionare, raccontare e analizzare le 10 battaglie sul mare pi&ugrave; decisive della storia, soffermandosi su ogni evento bellico&nbsp;e inquadrandolo, al contempo, in un pi&ugrave; ampio contesto strategico e tecnico. La prima parte &egrave; dedicata alle battaglie combattute dalle navi a remi e a vela, dove l&rsquo;avanzamento tecnologico &egrave; lento a procedere. A Salamina (480 a.C.), Azio (31 a.C.) e Lepanto (1571) protagoniste sono navi a remi evolutesi in oltre due millenni, dalla trireme alla galea. Lepanto vede, tuttavia, affermarsi per la prima volta il ruolo della polvere da sparo: innovazione che, applicata al galeone cinquecentesco spinto dal vento grazie all&rsquo;evoluzione delle attrezzature veliche, segner&agrave; le battaglie navali fondamentali di tre secoli, da quella combattuta a Gravelines (1588), nel Canale della Manica, sino al trionfo della Royal Navy britannica a Trafalgar (1805). La seconda parte &egrave; caratterizzata da una pi&ugrave; marcata influenza dell&rsquo;evoluzione tecnologica: lo scontro di Hampton Roads (1862) viene a marcare una rivoluzione, con il duello tra navi spinte da macchine a vapore, armate con cannoni ospitati in torri rotanti e protette da spesse corazze di ferro. A Tsushima (1905) e allo Jutland (1916) le grandi corazzate sono ormai le dominatrici del mare: possono colpire a lunga distanza e sono illuminate dall&rsquo;energia elettrica, pur rivelandosi vulnerabili a torpediniere e sommergibili. A Midway (1942) al naviglio si aggiunge la minaccia portata dagli aerei imbarcati sulle portaerei, nuove regine delle flotte. Infine, alle Falkland (1982) gli scontri sono segnati dalle nuove dotazioni hi-tech, come jet a decollo verticale, missili e microchip elettronici. All&rsquo;orizzonte gli ammiragli del XXI Secolo gi&agrave; intravedono l&rsquo;impiego di armi laser e scenari da guerre stellari, con missili balistici e sistemi d&rsquo;arma imbarcati destinati a bloccare nello spazio tali minacce.<\/p>\n<p>Edizione: 2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>da salamina alle falkland<\/p>\n<p class=\"autore\"><span>Author: <\/span>giuliano da fr\u00e8<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Casa Editrice Odoya<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862882293<\/p>\n","protected":false},"featured_media":150294,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3036],"product_tag":[],"class_list":{"0":"post-89279","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-other-essays","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>storia delle battaglie sul mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"storia delle battaglie sul mare\" \/>\n<meta property=\"og:description\" content=\"Subtitle: da salamina alle falklandAuthor: giuliano da fr\u00e8Publisher: Casa Editrice OdoyaISBN: 9788862882293\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T05:02:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiadellebattagliesulmare-20250620-132232.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"447\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;24,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\\\/\",\"name\":\"storia delle battaglie sul mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storiadellebattagliesulmare-20250620-132232.jpg\",\"datePublished\":\"2019-02-03T18:45:13+00:00\",\"dateModified\":\"2026-03-14T05:02:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storiadellebattagliesulmare-20250620-132232.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storiadellebattagliesulmare-20250620-132232.jpg\",\"width\":447,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"storia delle battaglie sul mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862882293\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"storia delle battaglie sul mare - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"storia delle battaglie sul mare","og_description":"Subtitle: da salamina alle falklandAuthor: giuliano da fr\u00e8Publisher: Casa Editrice OdoyaISBN: 9788862882293","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T05:02:03+00:00","og_image":[{"width":447,"height":595,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiadellebattagliesulmare-20250620-132232.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;24,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/","name":"storia delle battaglie sul mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiadellebattagliesulmare-20250620-132232.jpg","datePublished":"2019-02-03T18:45:13+00:00","dateModified":"2026-03-14T05:02:03+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiadellebattagliesulmare-20250620-132232.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiadellebattagliesulmare-20250620-132232.jpg","width":447,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-delle-battaglie-sul-mare-giuliano-da-fre-9788862882293\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"storia delle battaglie sul mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"24.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788862882293","product_condition":"new"},"df_price":24,"df_sale_price":"","df_regular_price":24,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiadellebattagliesulmare-20250620-132232-225x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/89279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=89279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/150294"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=89279"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=89279"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=89279"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=89279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}