{"id":88894,"date":"2020-12-22T19:26:25","date_gmt":"2020-12-22T18:26:25","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/i-borghi-pi-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/"},"modified":"2026-03-14T07:40:30","modified_gmt":"2026-03-14T06:40:30","slug":"i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/","title":{"rendered":"i borghi pi\u00f9 belli del mediterraneo"},"content":{"rendered":"<p>Il Mediterraneo non &egrave; solo splendore di mare e isole, ma anche villaggi, borghi, piccoli centri dove &egrave; scritta l&rsquo;origine della nostra civilt&agrave;. &Egrave; un mare antico, come lo chiamava Ungaretti, l&rsquo;eco di una voce che viene dalle profondit&agrave; del tempo, con molte patrie autonome &ndash; l&rsquo;Egeo, l&rsquo;Adriatico, lo Ionio, il Tirreno &ndash; e le civilt&agrave; scomparse che lo hanno attraversato dall&rsquo;epopea omerica alla fine dell&rsquo;impero ottomano. Fenici, etruschi, greci, romani, bizantini, arabi, normanni e altri popoli rivivono, in queste pagine, nelle tracce lasciate in un monumento, in un&rsquo;opera d&rsquo;arte.<\/p>\n<p>Sono 163 le localit&agrave; che dispiegano la loro magia nella nuova edizione di questa guida, dove quasi tutti i paesi del Mediterraneo sono rappresentati. Il salto di un delfino, un giardino pieno d&rsquo;uccelli, i golfi tranquilli, una Madonna bruna, un isolato monastero, il vento di maestrale, i paesi di pietra o imbiancati di calce, arroccati in altura o distesi di fronte all&rsquo;acqua: &egrave; nei centri minori, pi&ugrave; che nelle citt&agrave; affollate, che il Mediterraneo conserva il suo infinito fascino. In ogni borgo si cerca la poesia della pietra, la stradina lastricata, la torre diroccata, la crepa dove fiorisce il cappero, il muro di buganvillee, il gatto steso al sole, in una parola: il passaggio segreto verso l&rsquo;Altrove.<\/p>\n<p>Edizione: 2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>l&#8217;eterna seduzione del mare nostrum e del suo entroterra raccontata attraverso 163 localit\u00e0 tutte da scoprire<\/p>\n<p class=\"autore\"><span>Author: <\/span>claudio bacilieri<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>rubbettino<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788849863123<\/p>\n","protected":false},"featured_media":154555,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3106,2635],"product_tag":[],"class_list":{"0":"post-88894","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-europe-and-mediterranean-sea-tourist-guides","7":"product_cat-generals","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>i borghi pi\u00f9 belli del mediterraneo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"i borghi pi\u00f9 belli del mediterraneo\" \/>\n<meta property=\"og:description\" content=\"Subtitle: l&#039;eterna seduzione del mare nostrum e del suo entroterra raccontata attraverso 163 localit\u00e0 tutte da scoprireAuthor: claudio bacilieriPublisher: rubbettinoISBN: 9788849863123\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T06:40:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/borghi-piu-belli-del-mediterraneo-bacilieri-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"549\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;20,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\\\/\",\"name\":\"i borghi pi\u00f9 belli del mediterraneo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/borghi-piu-belli-del-mediterraneo-bacilieri-4.jpg\",\"datePublished\":\"2020-12-22T18:26:25+00:00\",\"dateModified\":\"2026-03-14T06:40:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/borghi-piu-belli-del-mediterraneo-bacilieri-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/borghi-piu-belli-del-mediterraneo-bacilieri-4.jpg\",\"width\":549,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"i borghi pi\u00f9 belli del mediterraneo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"20.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788849863123\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"i borghi pi\u00f9 belli del mediterraneo - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"i borghi pi\u00f9 belli del mediterraneo","og_description":"Subtitle: l'eterna seduzione del mare nostrum e del suo entroterra raccontata attraverso 163 localit\u00e0 tutte da scoprireAuthor: claudio bacilieriPublisher: rubbettinoISBN: 9788849863123","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T06:40:30+00:00","og_image":[{"width":549,"height":900,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/borghi-piu-belli-del-mediterraneo-bacilieri-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;20,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/","name":"i borghi pi\u00f9 belli del mediterraneo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/borghi-piu-belli-del-mediterraneo-bacilieri-4.jpg","datePublished":"2020-12-22T18:26:25+00:00","dateModified":"2026-03-14T06:40:30+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/borghi-piu-belli-del-mediterraneo-bacilieri-4.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/borghi-piu-belli-del-mediterraneo-bacilieri-4.jpg","width":549,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-borghi-piu-belli-del-mediterraneo-claudio-bacilieri-9788849863123\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"i borghi pi\u00f9 belli del mediterraneo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"20.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788849863123","product_condition":"new"},"df_price":20,"df_sale_price":"","df_regular_price":20,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/borghi-piu-belli-del-mediterraneo-bacilieri-4-183x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/88894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=88894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/154555"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=88894"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=88894"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=88894"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=88894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}