{"id":88061,"date":"2019-02-03T19:31:30","date_gmt":"2019-02-03T18:31:30","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/"},"modified":"2026-03-14T07:11:00","modified_gmt":"2026-03-14T06:11:00","slug":"tutti-al-mare-allegri-pastelli-aa-vv-9788851131562","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/","title":{"rendered":"tutti al mare! (allegri pastelli)"},"content":{"rendered":"<p>E&#8217; tempo di vacanze. Paletta, secchiello, costume e via, tutti al mare! Usa i pastelli per colorare i disegni e divertiti a riconoscere i giochi da fare in spiaggia e tanti animali del mare.<\/p>\n<p>Libro con 12 mini pastelli colorati per piccole manine!<\/p>\n<p>Et&agrave; di lettura: 3+<\/p>\n<p>Edizione: 2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>de agostini libri<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788851131562<\/p>\n","protected":false},"featured_media":77856,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2616],"product_tag":[],"class_list":{"0":"post-88061","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-activity-books","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tutti al mare! (allegri pastelli) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tutti al mare! (allegri pastelli)\" \/>\n<meta property=\"og:description\" content=\"Author: aa.vv.Publisher: de agostini libriISBN: 9788851131562\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T06:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tuttialmareallegripastelli-deagostini-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;5,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\\\/\",\"name\":\"tutti al mare! (allegri pastelli) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tuttialmareallegripastelli-deagostini-2.jpg\",\"datePublished\":\"2019-02-03T18:31:30+00:00\",\"dateModified\":\"2026-03-14T06:11:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tuttialmareallegripastelli-deagostini-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tuttialmareallegripastelli-deagostini-2.jpg\",\"width\":440,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"tutti al mare! (allegri pastelli)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"5.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788851131562\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tutti al mare! (allegri pastelli) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"tutti al mare! (allegri pastelli)","og_description":"Author: aa.vv.Publisher: de agostini libriISBN: 9788851131562","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T06:11:00+00:00","og_image":[{"width":440,"height":594,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tuttialmareallegripastelli-deagostini-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;5,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/","name":"tutti al mare! (allegri pastelli) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tuttialmareallegripastelli-deagostini-2.jpg","datePublished":"2019-02-03T18:31:30+00:00","dateModified":"2026-03-14T06:11:00+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tuttialmareallegripastelli-deagostini-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tuttialmareallegripastelli-deagostini-2.jpg","width":440,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tutti-al-mare-allegri-pastelli-aa-vv-9788851131562\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"tutti al mare! (allegri pastelli)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"5.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788851131562","product_condition":"new"},"df_price":5.9,"df_sale_price":"","df_regular_price":5.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tuttialmareallegripastelli-deagostini-2-222x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/88061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=88061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/77856"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=88061"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=88061"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=88061"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=88061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}