{"id":87534,"date":"2019-02-03T19:34:57","date_gmt":"2019-02-03T18:34:57","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/"},"modified":"2026-03-14T06:52:42","modified_gmt":"2026-03-14T05:52:42","slug":"francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/","title":{"rendered":"francia mediterranea"},"content":{"rendered":"<p>Il portolano <em>Francia mediterranea<\/em> descrive<strong> la costa della Francia mediterranea partendo da Port Vendres<\/strong>, al confine con la Spagna, <strong>per risalire fino a Menton <\/strong>al confine con l&rsquo;Italia.<\/p>\n<p>La <strong>Costa Azzurra ospita un numero cospicuo di porti e marina ben attrezzati<\/strong>, noti a livello internazionale. Per coloro che amano gli ancoraggi la scelta &egrave; veramente ampia: in particolare sono da non perdere le <strong>calanques della Provenza<\/strong>, splendide insenature serrate tra alte pareti rocciose che scendono a picco sul mare, un vero gioiello della natura. Un capitolo &egrave; dedicato alla<strong> navigazione nei canali interni<\/strong>, un autentico dedalo di vie d&rsquo;acque che offrono paesaggi indubbiamente affascinanti e inconsueti.<\/p>\n<p>L&rsquo;introduzione illustra l&rsquo;area nel suo insieme, con dettagli sui servizi per il diporto, fauna e flora, cenni storici e un&rsquo;ampia sezione dedicata al clima e alla meteorologia.<\/p>\n<p>Ogni capitolo contiene <strong>dettagliate informazioni di pilotaggio<\/strong>, <strong>eventuali pericoli<\/strong>, <strong>segnalamenti marittimi<\/strong>, <strong>note specifiche sulla meteorologia<\/strong>, <strong>le possibili rotte e consigli utili <\/strong>da parte di un marinaio con una pluridecennale esperienza in tutto il Mediterraneo. Tutti gli approdi e gli ancoraggi sono corredati dal relativo pianetto, molto utile per l&rsquo;atterraggio, e alcuni sono anche corredati di fotografie a colori. Non mancano i piani generali che riportano aree pi&ugrave; ampie di navigazione.<\/p>\n<p>Questo portolano fornisce <strong>tutti gli strumenti necessari per pianificare in sicurezza<\/strong> una crociera lungo questo splendido tratto di costa mediterranea, meta di un turismo nautico internazionale.&nbsp;<\/p>\n<p><strong>247 porti e ancoraggi &#8211; 201 piani &#8211; 116 foto<\/strong><\/p>\n<p>Edizione: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>da port vendres a menton<\/p>\n<p class=\"autore\"><span>Author: <\/span>rod heikell &#8211; lucinda heikell<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Edizioni Il Frangente<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788885719828<\/p>\n","protected":false},"featured_media":162126,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2705],"product_tag":[],"class_list":{"0":"post-87534","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-coe","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>francia mediterranea - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"francia mediterranea\" \/>\n<meta property=\"og:description\" content=\"Subtitle: da port vendres a mentonAuthor: rod heikell - lucinda heikellPublisher: Edizioni Il FrangenteISBN: 9788885719828\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T05:52:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"597\" \/>\n\t<meta property=\"og:image:height\" content=\"831\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;67,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\\\/\",\"name\":\"francia mediterranea - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5.jpg\",\"datePublished\":\"2019-02-03T18:34:57+00:00\",\"dateModified\":\"2026-03-14T05:52:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5.jpg\",\"width\":597,\"height\":831},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"francia mediterranea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"67.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788885719828\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"francia mediterranea - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"francia mediterranea","og_description":"Subtitle: da port vendres a mentonAuthor: rod heikell - lucinda heikellPublisher: Edizioni Il FrangenteISBN: 9788885719828","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T05:52:42+00:00","og_image":[{"width":597,"height":831,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;67,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/","name":"francia mediterranea - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5.jpg","datePublished":"2019-02-03T18:34:57+00:00","dateModified":"2026-03-14T05:52:42+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5.jpg","width":597,"height":831},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/francia-mediterranea-rod-heikell-lucinda-heikell-9788885719828\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"francia mediterranea"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"67.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788885719828","product_condition":"new"},"df_price":67,"df_sale_price":"","df_regular_price":67,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/francia-mediterranea-rod-heikell-lucinda-heikell-frangente-5-216x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/87534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=87534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/162126"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=87534"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=87534"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=87534"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=87534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}