{"id":87250,"date":"2019-02-03T19:17:26","date_gmt":"2019-02-03T18:17:26","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-delfino-e-delf11\/"},"modified":"2026-03-14T08:35:00","modified_gmt":"2026-03-14T07:35:00","slug":"carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/","title":{"rendered":"carta &#8211; mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985)"},"content":{"rendered":"<p>Riproduzione di una delle carte nautiche artistiche di Emilio Delfino, che rappresentano un naturale punto di incontro tra le sue lunghe esperienze marinare, il desiderio di fissare le memorie dei suoi viaggi e le ormai affinate tecniche grafiche e pittoriche. Si tratta di opere eseguite con meticolosa cura e alla maniera dei cartografi del Cinquecento: i particolari di pregio sono i rombi e le rose dei venti, il nome delle localit&agrave; in scrittura semigotica, le vedute delle citt&agrave;, le battaglie navali in miniatura e le bandiere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 70&#215;50<\/p>\n<p class=\"autore\"><span>Author: <\/span>emilio delfino<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>emilio delfino cartografo<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>DELF11<\/p>\n","protected":false},"featured_media":123444,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2919],"product_tag":[],"class_list":{"0":"post-87250","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-prints-on-italy","7":"product_shipping_class-packaging","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>carta - mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"carta - mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 70x50Author: emilio delfinoManufacturer: emilio delfino cartografoISBN: DELF11\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T07:35:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"752\" \/>\n\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;70,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\\\/\",\"name\":\"carta - mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3.jpg\",\"datePublished\":\"2019-02-03T18:17:26+00:00\",\"dateModified\":\"2026-03-14T07:35:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3.jpg\",\"width\":752,\"height\":556},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"carta &#8211; mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"70.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"DELF11\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"carta - mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"carta - mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985)","og_description":"Subtitle: cm 70x50Author: emilio delfinoManufacturer: emilio delfino cartografoISBN: DELF11","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T07:35:00+00:00","og_image":[{"width":752,"height":556,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;70,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/","name":"carta - mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3.jpg","datePublished":"2019-02-03T18:17:26+00:00","dateModified":"2026-03-14T07:35:00+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3.jpg","width":752,"height":556},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/carta-mare-ligure-da-ventimiglia-a-moneglia-e-i-litorali-di-arenzano-e-cogoleto-1985-emilio-delfino-delf11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"carta &#8211; mare ligure da ventimiglia a moneglia e i litorali di arenzano e cogoleto (1985)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"70.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"DELF11","product_condition":"new"},"df_price":70,"df_sale_price":"","df_regular_price":70,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mareliguredaventimigliaamonegliaeilitoralidiarenzanoecogoleto-delfino-3-300x222.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/87250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=87250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/123444"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=87250"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=87250"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=87250"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=87250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}