{"id":86899,"date":"2023-07-27T20:19:17","date_gmt":"2023-07-27T18:19:17","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/la-vera-storia-del-pirata-long-john-silver-larsson-b-9788870910759\/"},"modified":"2026-03-14T08:23:20","modified_gmt":"2026-03-14T07:23:20","slug":"la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/","title":{"rendered":"la vera storia del pirata long john silver"},"content":{"rendered":"<p><strong>Ci sono libri che danno pura gioia, facendo vibrare dentro di noi tutte le corde del nostro amore per la lettura<\/strong>: il racconto trascinante unito a temi che ci toccano nel profondo, la suspense e l&rsquo;avventura e un sottile gioco letterario che stimola la nostra complicit&agrave;, una documentata ricostruzione storica e il fascino di personaggi pi&ugrave; grandi del reale, nati gi&agrave; immortali.<\/p>\n<p>&Egrave; quel che capita con il romanzo di Bj&ouml;rn Larsson: <strong>ci ritroviamo adulti a leggere una storia di pirati con lo stesso gusto dell&rsquo;infanzia<\/strong>, riscoprendo quella capacit&agrave; di sognare che ci davano i porti affollati di vascelli, le taverne fumose, i tesori, gli arrembaggi, le tempeste improvvise e le insidie delle bonacce, come anche il semplice incanto del mare e la sfida libertaria di ribelli contro il cinismo dei potenti. In pi&ugrave; con la sorpresa di vederci restituito, in tutta la sua ambigua attrazione e vitalit&agrave;, uno dei personaggi che davano a quell&rsquo;infanzia l&rsquo;emozione della paura: <strong>chi racconta in prima persona &egrave; Long John Silver<\/strong>, il temibile pirata con una gamba sola dell&rsquo;<em>Isola del Tesoro<\/em>, fatto sparire da Stevenson nel nulla per riapparirci ora vivo e ricco nel 1742 in Madagascar, intento a scrivere le sue memorie. E non &egrave; solo a quell&rsquo;<em>e poi?<\/em>&nbsp;che ci veniva sempre da chiedere alla fine delle storie che risponde Larsson, &egrave; al prima, al durante, al dietro: <strong>com&rsquo;era il mondo all&rsquo;epoca della pirateria, i legami con il commercio ufficiale, la tratta degli schiavi, il contrabbando, le atroci condizioni dei marinai, i soprusi dei capitani, il codice egualitario dei pirati, le loro efferatezze e quelle contro cui si ribellavano, le motivazioni e le ingenuit&agrave; dei grandi &ldquo;gentiluomini di ventura&rdquo;.<\/strong><\/p>\n<p>Ma <strong>&egrave; a un personaggio letterario che &egrave; affidato il compito di rivelare la &ldquo;verit&agrave;&rdquo;<\/strong>, un personaggio cosciente di esistere solo nelle parole, che dialoga in un pub di Londra con Defoe fornendogli notizie per la sua storia della pirateria, che risponde a Jim Hawkins dopo aver letto <em>L&rsquo;Isola del Tesoro<\/em>, e che, in quel continuo gioco di rimandi, indaga sul rapporto tra <strong>realt&agrave; e invenzione, sete di vivere e bisogno di immortalit&agrave;, solitudine e libert&agrave;<\/strong>, con la consapevolezza che non esiste altra vera vita di quella che raccontiamo a noi stessi.<\/p>\n<p><strong>Postfazione di Roberto Mussapi.<\/strong><\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>bjorn larsson<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>iperborea<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788870910759<\/p>\n","protected":false},"featured_media":138333,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3061,2967,2809],"product_tag":[],"class_list":{"0":"post-86899","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-narrative-books-navigation-history-pirates","7":"product_cat-novels-classics-of-sea-literature","8":"product_cat-novels","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>la vera storia del pirata long john silver - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"la vera storia del pirata long john silver\" \/>\n<meta property=\"og:description\" content=\"Author: bjorn larssonPublisher: iperboreaISBN: 9788870910759\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T07:23:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\\\/\",\"name\":\"la vera storia del pirata long john silver - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3.jpg\",\"datePublished\":\"2023-07-27T18:19:17+00:00\",\"dateModified\":\"2026-03-14T07:23:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3.jpg\",\"width\":500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"la vera storia del pirata long john silver\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788870910759\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"la vera storia del pirata long john silver - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"la vera storia del pirata long john silver","og_description":"Author: bjorn larssonPublisher: iperboreaISBN: 9788870910759","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T07:23:20+00:00","og_image":[{"width":500,"height":1000,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/","name":"la vera storia del pirata long john silver - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3.jpg","datePublished":"2023-07-27T18:19:17+00:00","dateModified":"2026-03-14T07:23:20+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3.jpg","width":500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-vera-storia-del-pirata-long-john-silver-bjorn-larsson-9788870910759\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"la vera storia del pirata long john silver"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788870910759","product_condition":"new"},"df_price":19,"df_sale_price":"","df_regular_price":19,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/vera-storia-del-pirata-long-john-silver-larsson-edizione-25-anni-3-150x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/86899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=86899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/138333"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=86899"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=86899"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=86899"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=86899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}