{"id":86370,"date":"2019-02-03T19:22:00","date_gmt":"2019-02-03T18:22:00","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/"},"modified":"2026-03-14T08:07:08","modified_gmt":"2026-03-14T07:07:08","slug":"storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/","title":{"rendered":"storia &amp; storie della fotocinematografia subacquea italiana"},"content":{"rendered":"<p>In questo volume, per la prima volta in Italia, Alberto Romeo, noto fotosub ed appassionato studioso della storia della fotocinematografia subacquea, ha raccolto circa 150 biografie e ritratti di altrettanti protagonisti della scena della fotografia e cinematografia subacquea italiana, dai primordi fino a coloro che hanno iniziato negli anni &#8217;80 e&nbsp;che, quindi, oggi sono nel pieno della loro maturazione tecnica ed artistica. Le biografie non sono mai un freddo elenco delle attivit&agrave; o dei premi vinti dai protagonisti, ma raccontano storie, le storie vissute da loro stessi nel mondo della foto-cinematografia subacquea. Il volume ha comportato circa 5 anni di ricerche; gli avvenimenti narrati sono controllati e appresi dalla viva voce degli stessi protagonisti o dei loro amici pi&ugrave; stretti o, ancora, vissuti in prima persona dall&rsquo;autore. Con orgoglio Alberto Romeo pu&ograve; affermare che in questo volume, da leggere pi&ugrave; che da guardare, sono presenti moltissime notizie non note o mai pubblicate, riguardanti la storia della foto-cinematografia subacquea italiana.<\/p>\n<p>Costo del libro &euro; 25,00 + &euro; 7,00 per la consegna in libreria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>biografie dei protagonisti visti da vicino<\/p>\n<p class=\"autore\"><span>Author: <\/span>romeo a.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ireco<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>538246334<\/p>\n","protected":false},"featured_media":162799,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2586],"product_tag":[],"class_list":{"0":"post-86370","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-diving-photography-and-video-recording","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>storia &amp; storie della fotocinematografia subacquea italiana - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"storia &amp; storie della fotocinematografia subacquea italiana\" \/>\n<meta property=\"og:description\" content=\"Subtitle: biografie dei protagonisti visti da vicinoAuthor: romeo a.Publisher: irecoISBN: 538246334\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T07:07:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiaestoriedellafotocinematografiasubacquea-romeo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"596\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;32,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\\\/\",\"name\":\"storia &amp; storie della fotocinematografia subacquea italiana - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storiaestoriedellafotocinematografiasubacquea-romeo.jpg\",\"datePublished\":\"2019-02-03T18:22:00+00:00\",\"dateModified\":\"2026-03-14T07:07:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storiaestoriedellafotocinematografiasubacquea-romeo.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storiaestoriedellafotocinematografiasubacquea-romeo.jpg\",\"width\":420,\"height\":596},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"storia &amp; storie della fotocinematografia subacquea italiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"32.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"538246334\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"storia &amp; storie della fotocinematografia subacquea italiana - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"storia &amp; storie della fotocinematografia subacquea italiana","og_description":"Subtitle: biografie dei protagonisti visti da vicinoAuthor: romeo a.Publisher: irecoISBN: 538246334","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T07:07:08+00:00","og_image":[{"width":420,"height":596,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiaestoriedellafotocinematografiasubacquea-romeo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;32,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/","name":"storia &amp; storie della fotocinematografia subacquea italiana - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiaestoriedellafotocinematografiasubacquea-romeo.jpg","datePublished":"2019-02-03T18:22:00+00:00","dateModified":"2026-03-14T07:07:08+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiaestoriedellafotocinematografiasubacquea-romeo.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiaestoriedellafotocinematografiasubacquea-romeo.jpg","width":420,"height":596},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storia-storie-della-fotocinematografia-subacquea-italiana-romeo-a-538246334\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"storia &amp; storie della fotocinematografia subacquea italiana"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"32.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"538246334","product_condition":"new"},"df_price":32,"df_sale_price":"","df_regular_price":32,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storiaestoriedellafotocinematografiasubacquea-romeo-211x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/86370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=86370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/162799"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=86370"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=86370"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=86370"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=86370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}