{"id":85485,"date":"2019-02-03T19:11:57","date_gmt":"2019-02-03T18:11:57","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/titanic-1912-caterino-a-9788895051345\/"},"modified":"2026-03-14T08:58:28","modified_gmt":"2026-03-14T07:58:28","slug":"titanic-1912-caterino-a-9788895051345","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/","title":{"rendered":"titanic 1912"},"content":{"rendered":"<p>Questo libro viene pubblicato in occasione del centenario dell&#8217;affondamento del &#8220;Titanic&#8221; per fare il punto sulle conoscenze al riguardo, dopo quasi un trentennio dal ritrovamento del relitto da parte di Robert Ballard. Il testo, scritto da un autorevole studioso di storia navale, &egrave; preciso nei contenuti, piacevole nella lettura e&nbsp;corredato da&nbsp;una serie di aneddoti curiosi di grande interesse documentario. L&#8217;apparato illustrativo, frutto di un&#8217;attenta ricerca in archivi, biblioteche e musei sia pubblici sia privati, aiuta a comprendere meglio la complessit&agrave; tecnica di una nave cos&igrave; possente e lussuosa da caratterizzare un&#8217;epoca e a rivivere l&#8217;atmosfera di coloro che viaggiarono per la prima e ultima volta sul transatlantico &#8220;inaffondabile&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la vera storia della nave inaffondabile<\/p>\n<p class=\"autore\"><span>Author: <\/span>caterino a.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>portolano<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788895051345<\/p>\n","protected":false},"featured_media":132411,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3059],"product_tag":[],"class_list":{"0":"post-85485","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-essays-books-navigation-history-passenger-ships","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>titanic 1912 - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"titanic 1912\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la vera storia della nave inaffondabileAuthor: caterino a.Publisher: portolanoISBN: 9788895051345\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T07:58:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/titanic1912tre-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"429\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;25,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/titanic-1912-caterino-a-9788895051345\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/titanic-1912-caterino-a-9788895051345\\\/\",\"name\":\"titanic 1912 - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/titanic-1912-caterino-a-9788895051345\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/titanic-1912-caterino-a-9788895051345\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/titanic1912tre-1.jpg\",\"datePublished\":\"2019-02-03T18:11:57+00:00\",\"dateModified\":\"2026-03-14T07:58:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/titanic-1912-caterino-a-9788895051345\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/titanic-1912-caterino-a-9788895051345\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/titanic-1912-caterino-a-9788895051345\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/titanic1912tre-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/titanic1912tre-1.jpg\",\"width\":429,\"height\":603},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/titanic-1912-caterino-a-9788895051345\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"titanic 1912\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"25.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788895051345\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"titanic 1912 - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"titanic 1912","og_description":"Subtitle: la vera storia della nave inaffondabileAuthor: caterino a.Publisher: portolanoISBN: 9788895051345","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T07:58:28+00:00","og_image":[{"width":429,"height":603,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/titanic1912tre-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;25,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/","name":"titanic 1912 - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/titanic1912tre-1.jpg","datePublished":"2019-02-03T18:11:57+00:00","dateModified":"2026-03-14T07:58:28+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/titanic1912tre-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/titanic1912tre-1.jpg","width":429,"height":603},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/titanic-1912-caterino-a-9788895051345\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"titanic 1912"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"25.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788895051345","product_condition":"new"},"df_price":25,"df_sale_price":"","df_regular_price":25,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/titanic1912tre-1-213x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/85485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=85485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/132411"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=85485"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=85485"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=85485"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=85485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}