{"id":85484,"date":"2019-02-03T19:11:57","date_gmt":"2019-02-03T18:11:57","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/"},"modified":"2026-03-14T08:58:26","modified_gmt":"2026-03-14T07:58:26","slug":"manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/","title":{"rendered":"manuale federale di apnea volume 1 (fipsas)"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\"><span>Manuale con un approccio fresco e non convenzionale, che dedica <strong>particolare attenzione agli aspetti pi&ugrave; pratici e alla semplicit&agrave; espositiva<\/strong>.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\"><span><strong> Dedicato a chi si avvicina per la prima volta<\/strong> a questa meravigliosa attivit&agrave; fatta di aria e di acqua, fornisce<strong> tanti consigli<\/strong> e grande <strong>cura per gli aspetti operativi<\/strong> in un&#8217;ottica volutamente emozionale.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\"><span>In un tuffo virtuale si ripercorre <strong>tutto ci&ograve; che un novello apneista deve fare<\/strong>, evidenziando ci&ograve; che per la sua sicurezza non deve fare.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\"><span>Edizione: 2018<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;margin: 0cm 0cm 0pt\"><span>Ristampa: 2022<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>a cura di silvio mercadante &#8211; fabio portella<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>editrice la mandragora<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788875864484<\/p>\n","protected":false},"featured_media":103492,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2584],"product_tag":[],"class_list":{"0":"post-85484","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-diving-apnea-and-snorkeling","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>manuale federale di apnea volume 1 (fipsas) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"manuale federale di apnea volume 1 (fipsas)\" \/>\n<meta property=\"og:description\" content=\"Author: a cura di silvio mercadante - fabio portellaPublisher: editrice la mandragoraISBN: 9788875864484\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T07:58:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manualefederalediapneavol1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"602\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\\\/\",\"name\":\"manuale federale di apnea volume 1 (fipsas) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/manualefederalediapneavol1-3.jpg\",\"datePublished\":\"2019-02-03T18:11:57+00:00\",\"dateModified\":\"2026-03-14T07:58:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/manualefederalediapneavol1-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/manualefederalediapneavol1-3.jpg\",\"width\":602,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"manuale federale di apnea volume 1 (fipsas)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788875864484\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"manuale federale di apnea volume 1 (fipsas) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"manuale federale di apnea volume 1 (fipsas)","og_description":"Author: a cura di silvio mercadante - fabio portellaPublisher: editrice la mandragoraISBN: 9788875864484","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T07:58:26+00:00","og_image":[{"width":602,"height":600,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manualefederalediapneavol1-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/","name":"manuale federale di apnea volume 1 (fipsas) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manualefederalediapneavol1-3.jpg","datePublished":"2019-02-03T18:11:57+00:00","dateModified":"2026-03-14T07:58:26+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manualefederalediapneavol1-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manualefederalediapneavol1-3.jpg","width":602,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/manuale-federale-di-apnea-volume-1-fipsas-a-cura-di-silvio-mercadante-fabio-portella-9788875864484\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"manuale federale di apnea volume 1 (fipsas)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788875864484","product_condition":"new"},"df_price":22,"df_sale_price":"","df_regular_price":22,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/manualefederalediapneavol1-3-300x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/85484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=85484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/103492"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=85484"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=85484"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=85484"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=85484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}