{"id":85483,"date":"2019-02-03T19:11:57","date_gmt":"2019-02-03T18:11:57","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/"},"modified":"2026-03-14T08:58:16","modified_gmt":"2026-03-14T07:58:16","slug":"whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/","title":{"rendered":"whales &amp; dolphins of the north american pacific"},"content":{"rendered":"<p>Whales and Dolphins of the North American Pacific is the most comprehensive photographic guide to the marine mammals of the North American Pacific (Baja California, Mexico to South East Alaska), covering all 38 species of cetacean (whales, dolphins and porpoises), six species of seals and sea lions, and the sea otter.<\/p>\n<p>&#8220;Whales and Dolphins of the North American Pacific&#8221; covers each species&#8217; key identification features and includes information on behaviour, status and distribution. Colour distribution maps and full-colour artwork accompanies the text for each species. The book&#8217;s 38 remarkable colour plates depict typical views of cetaceans at sea, including images of some species never previously published.<\/p>\n<p>&#8220;Whales and Dolphins of the North American Pacific&#8221; provides extensive information on where, when and how to go whalewatching and a guide to the best places to watch, including four accounts of outstanding days on the water. There are additional chapters on the geography, climate and oceanography of the North American Pacific.<\/p>\n<p>Edition: 2007<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>including seals and other marine mammals<\/p>\n<p class=\"autore\"><span>Author: <\/span>cresswell g.  walker d.  pusser t.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>harbour<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9781550174090<\/p>\n","protected":false},"featured_media":80493,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2622],"product_tag":[],"class_list":{"0":"post-85483","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-marine-mammals","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>whales &amp; dolphins of the north american pacific - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"whales &amp; dolphins of the north american pacific\" \/>\n<meta property=\"og:description\" content=\"Subtitle: including seals and other marine mammalsAuthor: cresswell g. walker d. pusser t.Publisher: harbourISBN: 9781550174090\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T07:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"432\" \/>\n\t<meta property=\"og:image:height\" content=\"301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;21,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\\\/\",\"name\":\"whales &amp; dolphins of the north american pacific - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1.jpg\",\"datePublished\":\"2019-02-03T18:11:57+00:00\",\"dateModified\":\"2026-03-14T07:58:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1.jpg\",\"width\":432,\"height\":301},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"whales &amp; dolphins of the north american pacific\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"21.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9781550174090\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"whales &amp; dolphins of the north american pacific - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"whales &amp; dolphins of the north american pacific","og_description":"Subtitle: including seals and other marine mammalsAuthor: cresswell g. walker d. pusser t.Publisher: harbourISBN: 9781550174090","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T07:58:16+00:00","og_image":[{"width":432,"height":301,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;21,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/","name":"whales &amp; dolphins of the north american pacific - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1.jpg","datePublished":"2019-02-03T18:11:57+00:00","dateModified":"2026-03-14T07:58:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1.jpg","width":432,"height":301},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/whales-dolphins-of-the-north-american-pacific-cresswell-g-walker-d-pusser-t-9781550174090\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"whales &amp; dolphins of the north american pacific"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"21.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9781550174090","product_condition":"new"},"df_price":21,"df_sale_price":21,"df_regular_price":30,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/whalesanddolphinsofthenorthamericanpacific-cresswellwalkerpusser-1-300x209.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/85483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=85483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/80493"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=85483"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=85483"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=85483"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=85483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}