{"id":84821,"date":"2019-02-03T19:06:42","date_gmt":"2019-02-03T18:06:42","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/l-arte-e-la-scienza-delle-vele-whidden-t-levitt-m-9788865945704\/"},"modified":"2026-03-14T09:30:56","modified_gmt":"2026-03-14T08:30:56","slug":"l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/","title":{"rendered":"l&#8217;arte e la scienza delle vele"},"content":{"rendered":"<p>A venticinque anni dalla sua prima uscita, la <strong>nuova edizione di un vero classico<\/strong>. <em>Tom Whidden<\/em>, l&rsquo;uomo al comando della <em>North Sails<\/em>, e <em>Michael Levitt<\/em>, tornano sui loro passi a riesaminare quel lavoro, dando conto dello <strong>straordinario salto tecnologico avvenuto<\/strong>.<\/p>\n<p>Dai <strong>nuovi sistemi di utilizzo dei materiali<\/strong> di ultima generazione, ai <strong>principi scientifici<\/strong> alla base della navigazione a vela e alla <strong>rivoluzione computazionale<\/strong>, fino a un&rsquo;analisi accurata delle <strong>migliori tecniche di conduzione<\/strong> della barca nelle varie andature.Questo non &egrave; <em>L&rsquo;arte e la scienza delle vele<\/em> dei vostri genitori, scritto da <em>Tom Whidden<\/em> e <em>Michael Levitt<\/em> e pubblicato nel 1990. Venticinque anni possono fare una grande differenza! Oggi esistono vele realizzate in un unico pannello, modellate sopra stampi tridimensionali, nell&rsquo;esatta forma definitiva che assumeranno nel vento. I piani velici delle barche, sia da regata che da crociera, si sono radicalmente evoluti verso armi frazionati, rande square-top e fiocchi non sovrapposti.<\/p>\n<p>Si parte dalla <strong>storia della veleria moderna<\/strong> con <em>Ted Hood<\/em> e<em> Lowell North<\/em>, l&rsquo;artista e lo scienziato, e si giunge ad affrontare la questione della circolazione, come nella prima edizione, ma passando per una strada diversa: tentando, per la prima volta in assoluto, una quantificazione dei suoi effetti. Perch&eacute; e dove il vento, interagendo con un piano velico, accelera o rallenta. La <strong>teoria della circolazione<\/strong> &egrave; nota agli studiosi di aerodinamica da almeno un secolo ed &egrave; argomento di discussione tra i velisti dal 1973, quando il compianto <em>Arvel Gentry<\/em> present&ograve; al mondo della nautica le sue teorie. <em>Gentry <\/em>era ingegnere aerodinamico alla <em>Boeing <\/em>durante la settimana e velista nei weekend. E le teorie secondo cui un aeroplano pu&ograve; volare contrastavano con quelle secondo le quali una barca pu&ograve; risalire il vento.<\/p>\n<p><em>Whidden<\/em> e <em>Levitt<\/em> utilizzano spiegazioni come la circolazione per <strong>rispondere a diverse domande<\/strong>:<\/p>\n<ul>\n<li>Perch&eacute; gli armi frazionati, le rande square-top e i fiocchi non sovrapposti hanno finito per predominare.<\/li>\n<li>Come e perch&eacute; lo svergolamento della balumina pu&ograve; rivelarsi il migliore alleato del trimmer.<\/li>\n<li>Perch&eacute; il progettista navale posiziona albero, chiglia e timone in modo tale da generare una tendenza orziera.<\/li>\n<li>Perch&eacute; la &ldquo;safe-leeward position&rdquo; &egrave; vantaggiosa rispetto a tutta la flotta degli avversari.<\/li>\n<li>Perch&eacute; il miracolo della bolina non consiste nel fatto che ci sia cos&igrave; tanta portanza quanto cos&igrave; poca resistenza.<\/li>\n<\/ul>\n<p>&Egrave; presente un&rsquo;<strong>analisi approfondita delle meraviglie dell&rsquo;uso dei materiali nella fabbricazione delle vele<\/strong>, non gi&agrave; solo dei materiali stessi. Gli ultimi tre capitoli costituiscono poi una <strong>guida all&rsquo;utilizzo di rande, vele di prua e spinnaker<\/strong> che permetter&agrave; sicuramente ai lettori di ottenere le migliori prestazioni dalle loro barche.<\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>tom whidden &#8211; michael levitt<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Nutrimenti Mare (Nutrimenti)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791255481447<\/p>\n","protected":false},"featured_media":161388,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2755],"product_tag":[],"class_list":{"0":"post-84821","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-rigging-and-sails","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l&#039;arte e la scienza delle vele - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;arte e la scienza delle vele\" \/>\n<meta property=\"og:description\" content=\"Author: tom whidden - michael levittPublisher: Nutrimenti Mare (Nutrimenti)ISBN: 9791255481447\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T08:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/arte-e-la-scienza-delle-vele-whidden-levitt-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"598\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;28,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\\\/\",\"name\":\"l'arte e la scienza delle vele - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/arte-e-la-scienza-delle-vele-whidden-levitt-1.jpg\",\"datePublished\":\"2019-02-03T18:06:42+00:00\",\"dateModified\":\"2026-03-14T08:30:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/arte-e-la-scienza-delle-vele-whidden-levitt-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/arte-e-la-scienza-delle-vele-whidden-levitt-1.jpg\",\"width\":598,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"l&#8217;arte e la scienza delle vele\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"28.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791255481447\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l'arte e la scienza delle vele - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"l'arte e la scienza delle vele","og_description":"Author: tom whidden - michael levittPublisher: Nutrimenti Mare (Nutrimenti)ISBN: 9791255481447","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T08:30:56+00:00","og_image":[{"width":598,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/arte-e-la-scienza-delle-vele-whidden-levitt-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;28,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/","name":"l'arte e la scienza delle vele - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/arte-e-la-scienza-delle-vele-whidden-levitt-1.jpg","datePublished":"2019-02-03T18:06:42+00:00","dateModified":"2026-03-14T08:30:56+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/arte-e-la-scienza-delle-vele-whidden-levitt-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/arte-e-la-scienza-delle-vele-whidden-levitt-1.jpg","width":598,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-arte-e-la-scienza-delle-vele-tom-whidden-michael-levitt-9791255481447\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"l&#8217;arte e la scienza delle vele"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"28.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791255481447","product_condition":"new"},"df_price":28,"df_sale_price":"","df_regular_price":28,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/arte-e-la-scienza-delle-vele-whidden-levitt-1-256x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/84821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=84821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/161388"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=84821"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=84821"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=84821"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=84821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}