{"id":64402,"date":"2019-02-03T19:00:10","date_gmt":"2019-02-03T18:00:10","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/"},"modified":"2026-03-14T10:05:55","modified_gmt":"2026-03-14T09:05:55","slug":"1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/","title":{"rendered":"1000 quiz e 100 esercizi di carteggio per la patente nautica"},"content":{"rendered":"<p>Pensato per la preparazione all&#8217;esame per la patente nautica, in particolare presso le Capitanerie di Porto che sulla base del Decreto Ministeriale del 4 ottobre 2013 (G.U. n. 271 del 19.11.2013) in materia di Esami per conseguimento patenti nautiche hanno introdotto la metodica a quiz, questo volume presenta una chiara organizzazione delle domande e dei problemi di carteggio oggetto delle varie tipologie di prove. Il volume presenta 1000 quiz, tutti forniti di soluzione, relativi a:<br \/>&#8211; quiz di base riguardanti tutti i tipi di esame;<br \/>&#8211; quiz di carteggio nautico riguardanti tutti i tipi di esame;<br \/>&#8211; quiz di integrazione relativi alla patente nautica senza limiti di miglia;<br \/>&#8211; quiz di vela per la patente di vela.<\/p>\n<p>Segue una parte teorica in cui sono raccolti definizioni, simboli, abbreviazioni, calcoli di base e schemi che riassumono i concetti di prora, rilevamento e corrente con le formule che ne derivano. Sono, inoltre, trattati i primi elementi di cinematica radar in modo da avere il supporto utile a risolvere graficamente i problemi che riguardano il moto relativo fra due o pi&ugrave; navi. Al termine di questa parte sono proposti 100 esercizi di carteggio condotti sulle carte nautiche 5\/D e 42\/D. Per ogni problema, unitamente alla soluzione, viene indicata passo passo la sequenza risolutiva, in modo che siano evidenti i passaggi e la logica esecutiva da applicare. Chiudono il volume due prove simulate d&#8217;esame, una per la patente entro le 12 miglia dalla costa e l&#8217;altra per la patente senza limitazione, sulle quali testare la propria preparazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>con prove d&#8217;esame simulate<\/p>\n<p class=\"autore\"><span>Author: <\/span>caimmi m.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ulrico hoepli editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788820370398<\/p>\n","protected":false},"featured_media":126549,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2987],"product_tag":[],"class_list":{"0":"post-64402","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boat-license","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1000 quiz e 100 esercizi di carteggio per la patente nautica - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1000 quiz e 100 esercizi di carteggio per la patente nautica\" \/>\n<meta property=\"og:description\" content=\"Subtitle: con prove d&#039;esame simulateAuthor: caimmi m.Publisher: ulrico hoepli editoreISBN: 9788820370398\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T09:05:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1000quiz100esercizidicarteggiopatentenautica-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"597\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\\\/\",\"name\":\"1000 quiz e 100 esercizi di carteggio per la patente nautica - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/1000quiz100esercizidicarteggiopatentenautica-1.jpg\",\"datePublished\":\"2019-02-03T18:00:10+00:00\",\"dateModified\":\"2026-03-14T09:05:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/1000quiz100esercizidicarteggiopatentenautica-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/1000quiz100esercizidicarteggiopatentenautica-1.jpg\",\"width\":440,\"height\":597},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1000 quiz e 100 esercizi di carteggio per la patente nautica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788820370398\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1000 quiz e 100 esercizi di carteggio per la patente nautica - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"1000 quiz e 100 esercizi di carteggio per la patente nautica","og_description":"Subtitle: con prove d'esame simulateAuthor: caimmi m.Publisher: ulrico hoepli editoreISBN: 9788820370398","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T09:05:55+00:00","og_image":[{"width":440,"height":597,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1000quiz100esercizidicarteggiopatentenautica-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/","name":"1000 quiz e 100 esercizi di carteggio per la patente nautica - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1000quiz100esercizidicarteggiopatentenautica-1.jpg","datePublished":"2019-02-03T18:00:10+00:00","dateModified":"2026-03-14T09:05:55+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1000quiz100esercizidicarteggiopatentenautica-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1000quiz100esercizidicarteggiopatentenautica-1.jpg","width":440,"height":597},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/1000-quiz-e-100-esercizi-di-carteggio-per-la-patente-nautica-caimmi-m-9788820370398\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"1000 quiz e 100 esercizi di carteggio per la patente nautica"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788820370398","product_condition":"new"},"df_price":22.9,"df_sale_price":"","df_regular_price":22.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/1000quiz100esercizidicarteggiopatentenautica-1-221x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/64402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=64402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/126549"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=64402"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=64402"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=64402"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=64402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}