{"id":63723,"date":"2019-02-03T19:02:42","date_gmt":"2019-02-03T18:02:42","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/le-requin-1750-boudriot-j-berti-h-9782903179656\/"},"modified":"2026-03-14T09:48:49","modified_gmt":"2026-03-14T08:48:49","slug":"le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/","title":{"rendered":"le requin (1750) del costruttore maiorchino joseph caubet &#8211; sciabecchi di 24 cannoni"},"content":{"rendered":"<p>Questa pubblicazione analizza diversi bastimenti che navigavano sulle coste della Provenza e quelli utilizzati a Tolone dalla Marina Reale Francese, con l&#8217;aggiunta di quelle navi che costituivano la versione commerciale dello sciabecco. Le fonti sono esclusivamente documenti d&rsquo;epoca, da cui sono state scartate tutte le informazioni secondarie. Le feluche, i brigantini, le galeotte a remi, le galere, le tartane, le barche latine, le polacche, i pinchi e, infine, gli sciabecchi vengono esaminati in ordine cronologico.<\/p>\n<p>La parte dedicata allo sciabecco Requin &egrave; basata su una paziente ricerca ci ha permesso agli autori di raccogliere molte informazioni, tra cui i piani d&rsquo;epoca dello sciabecco, molti dati esaurienti sulle manovre e la storia completa del bastimento, dagli esordi in tempo di pace alle campagne corsare durante la Guerra dei sette anni, fino alla campagna in squadra sotto il comando di De Bompard nel 1762.<\/p>\n<p>Cofanetto telato rigido con sovraccoperta in carta con alette contentente:<\/p>\n<ul>\n<li>brossura in francese di 153 pagine formato 24&#215;31:<\/li>\n<\/ul>\n<ol>\n<li style=\"list-style-type: none\">\n<ol>\n<li>Studio delle navi del mediterraneo che hanno frequentato il nostro litorale mediterraneo.<\/li>\n<li>Studio degli sciabecchi.<\/li>\n<li>Gli sciabecchi nella Marina Reale 1750-1779.<\/li>\n<li>Lo sciabecco Requin: descrizione, cronistoria, crociera del Requin nel 1762.<\/li>\n<li>Commento dettagliato con tutte le spiegazioni utili sulle tavole in scala 1:48.<\/li>\n<li>Commento di 21 foto del modello d&rsquo;epoca del Requin.<\/li>\n<li>Regole sull&rsquo;armamento degli sciabecchi.<\/li>\n<li>Nomenclatura.<\/li>\n<li>Commento di 13 foto del dettaglio dell&rsquo;armamento.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<ul>\n<li>Raccolta di 23 tavole:<\/li>\n<\/ul>\n<ol>\n<li style=\"list-style-type: none\">\n<ol>\n<li>22 tavole in scala 1:48 che descrivono il dettaglio della carpenteria, delle manovre, degli accessori dell&rsquo;accastellamento e il disegno di tutte le ordinate e di tutti i dettagli della struttura della poppa e della prua.<\/li>\n<li>La tavola con il piano di costruzione sia in scala 1:48 sia in scala 1:72.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<ul>\n<li>Traduzione in italiano della brossura a cura di Franco Gregorio.<\/li>\n<\/ul>\n<p>Lingue: Italiano e Francese.<\/p>\n<p>Edizione: 2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>bastimenti mediterranei, sciabecchi della marina reale e monografia<\/p>\n<p class=\"autore\"><span>Author: <\/span>jean boudriot &#8211; hubert berti<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ancre (architecture navale classique recherche edition)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9782903179656<\/p>\n","protected":false},"featured_media":160922,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3003],"product_tag":[],"class_list":{"0":"post-63723","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-books-modeling","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>le requin (1750) del costruttore maiorchino joseph caubet - sciabecchi di 24 cannoni - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"le requin (1750) del costruttore maiorchino joseph caubet - sciabecchi di 24 cannoni\" \/>\n<meta property=\"og:description\" content=\"Subtitle: bastimenti mediterranei, sciabecchi della marina reale e monografiaAuthor: jean boudriot - hubert bertiPublisher: ancre (architecture navale classique recherche edition)ISBN: 9782903179656\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T08:48:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/requin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"245\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;200,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\\\/\",\"name\":\"le requin (1750) del costruttore maiorchino joseph caubet - sciabecchi di 24 cannoni - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/requin.jpg\",\"datePublished\":\"2019-02-03T18:02:42+00:00\",\"dateModified\":\"2026-03-14T08:48:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/requin.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/requin.jpg\",\"width\":245,\"height\":314},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"le requin (1750) del costruttore maiorchino joseph caubet &#8211; sciabecchi di 24 cannoni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"200.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9782903179656\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"le requin (1750) del costruttore maiorchino joseph caubet - sciabecchi di 24 cannoni - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"le requin (1750) del costruttore maiorchino joseph caubet - sciabecchi di 24 cannoni","og_description":"Subtitle: bastimenti mediterranei, sciabecchi della marina reale e monografiaAuthor: jean boudriot - hubert bertiPublisher: ancre (architecture navale classique recherche edition)ISBN: 9782903179656","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T08:48:49+00:00","og_image":[{"width":245,"height":314,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/requin.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;200,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/","name":"le requin (1750) del costruttore maiorchino joseph caubet - sciabecchi di 24 cannoni - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/requin.jpg","datePublished":"2019-02-03T18:02:42+00:00","dateModified":"2026-03-14T08:48:49+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/requin.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/requin.jpg","width":245,"height":314},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-requin-1750-del-costruttore-maiorchino-joseph-caubet-sciabecchi-di-24-cannoni-jean-boudriot-hubert-berti-9782903179656\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"le requin (1750) del costruttore maiorchino joseph caubet &#8211; sciabecchi di 24 cannoni"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"200.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9782903179656","product_condition":"new"},"df_price":200,"df_sale_price":"","df_regular_price":200,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/requin-234x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/63723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=63723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/160922"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=63723"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=63723"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=63723"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=63723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}