{"id":63358,"date":"2019-02-03T19:04:43","date_gmt":"2019-02-03T18:04:43","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/racconti-dei-mari-del-sud-jack-london-9788899898748\/"},"modified":"2026-03-14T09:38:52","modified_gmt":"2026-03-14T08:38:52","slug":"racconti-dei-mari-del-sud-jack-london-9788899898748","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/","title":{"rendered":"racconti dei mari del sud"},"content":{"rendered":"<p>La vena marinaresca e avventurosa di London si sposa in questi appassionanti racconti con l&rsquo;osservazione pi&ugrave; cruda del nuovo colonialismo occidentale: sullo sfondo di paradisi tropicali dalle acque cristalline e dalla vegetazione lussureggiante, London ha la capacit&agrave; di catapultarci nella vita reale di quelle isole lontane.<br \/>Cos&igrave; ci troviamo in mezzo a terribili uragani, su velieri squassati dal vento, poi naufraghi in balia dei pescecani; vediamo soccombere missionari esaltati sotto la clava (e i denti) di selvaggi cannibali, a loro volta vessati, torturati e uccisi da sadici agenti dell&rsquo;onnipresente Compagnia del Sapone Raggio-di-Luna, parodia della storica Compagnia delle Indie Orientali.<br \/>Ogni volta il punto di vista cambia: London non si accontenta di raccontare, London vuole che noi viviamo e ci impersoniamo in tutti i ruoli possibili nella realt&agrave; delle colonie, facendo vacillare i presupposti su cui siamo abituati a basare il nostro giudizio sul bene e sul male.<\/p>\n<p>Quando London si imbarca sullo Snark, barca che si era fatto appositamente costruire, si ripromette di scrivere mille parole ogni giorno e sostanzialmente ci riuscir&agrave;. Si era molto indebitato e aveva chiesto anticipi agli editori.<\/p>\n<p>I mesi trascorsi nelle isole dei Mari del Sud fornirono a Jack nuovo materiale. L&rsquo;ambiente naturale e la vita primitiva lo entusiasmarono. Dalle isole Salomone scrisse a Sterling: &#8220;Questa &egrave; la parte pi&ugrave; primitiva del mondo. Caccia alle teste, cannibalismo e assassinio sono elementi predominanti. Quando siamo nelle peggiori isole del gruppo siamo sempre armati, di giorno e di notte, e di notte &egrave; necessaria la sentinella&#8221;. Seduto sul ponte, nei pomeriggi caldi leggeva a volte a Charmian, la moglie, e all&rsquo;equipaggio quello che aveva scritto al mattino.<\/p>\n<p>Dalle Hawaii si spostano verso le Isole Marchesi, passando per l&rsquo;Isola Vailima che era stata il rifugio di Stevenson e visitando quanto rimaneva della Valle di Typee di Melville. Da l&igrave; poi va a Tahiti e a Papeete, nel gennaio del 1908; trova ad aspettarlo la posta di tre mesi: non sono belle notizie, le sue finanze sono in difficolt&agrave;. Rientra a San Francisco e cerca per l&rsquo;ennesima volta di tappare le falle pi&ugrave; gravi. Per sua fortuna sono in uscita &#8220;Martin Eden&#8221; e &#8220;Il tallone di ferro&#8221;.<br \/>Tornato sullo Snark, riprende il viaggio: la Polinesia, poi le Isole Fiji, poi verso le Salomone.<\/p>\n<p>I &#8220;Racconti dei Mari del Sud&#8221; (South Sea Tales), che traggono ispirazione in gran parte dal viaggio compiuto sullo Snark, furono pubblicati nel 1911 dall&rsquo;Editore Macmillan.<\/p>\n<p>La bella traduzione originale &egrave; stata revisionata in alcuni aspetti datati del linguaggio e resa pi&ugrave; scorrevole e attuale.<\/p>\n<p>Edizione: 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>jack london<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>tarka edizioni srl<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788899898748<\/p>\n","protected":false},"featured_media":125619,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2961,2805],"product_tag":[],"class_list":{"0":"post-63358","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chronicles-logbooks-and-travel-reports","7":"product_cat-logbooks-and-travel-reports","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>racconti dei mari del sud - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"racconti dei mari del sud\" \/>\n<meta property=\"og:description\" content=\"Author: jack londonPublisher: tarka edizioni srlISBN: 9788899898748\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T08:38:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/raccontideimaridelsud-londontarka-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"405\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/racconti-dei-mari-del-sud-jack-london-9788899898748\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/racconti-dei-mari-del-sud-jack-london-9788899898748\\\/\",\"name\":\"racconti dei mari del sud - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/racconti-dei-mari-del-sud-jack-london-9788899898748\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/racconti-dei-mari-del-sud-jack-london-9788899898748\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/raccontideimaridelsud-londontarka-4.jpg\",\"datePublished\":\"2019-02-03T18:04:43+00:00\",\"dateModified\":\"2026-03-14T08:38:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/racconti-dei-mari-del-sud-jack-london-9788899898748\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/racconti-dei-mari-del-sud-jack-london-9788899898748\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/racconti-dei-mari-del-sud-jack-london-9788899898748\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/raccontideimaridelsud-londontarka-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/raccontideimaridelsud-londontarka-4.jpg\",\"width\":405,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/racconti-dei-mari-del-sud-jack-london-9788899898748\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"racconti dei mari del sud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788899898748\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"racconti dei mari del sud - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"racconti dei mari del sud","og_description":"Author: jack londonPublisher: tarka edizioni srlISBN: 9788899898748","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T08:38:52+00:00","og_image":[{"width":405,"height":599,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/raccontideimaridelsud-londontarka-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/","name":"racconti dei mari del sud - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/raccontideimaridelsud-londontarka-4.jpg","datePublished":"2019-02-03T18:04:43+00:00","dateModified":"2026-03-14T08:38:52+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/raccontideimaridelsud-londontarka-4.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/raccontideimaridelsud-londontarka-4.jpg","width":405,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/racconti-dei-mari-del-sud-jack-london-9788899898748\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"racconti dei mari del sud"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788899898748","product_condition":"new"},"df_price":16,"df_sale_price":"","df_regular_price":16,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/raccontideimaridelsud-londontarka-4-203x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/63358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=63358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/125619"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=63358"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=63358"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=63358"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=63358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}