{"id":62645,"date":"2022-01-24T16:35:53","date_gmt":"2022-01-24T15:35:53","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/apnea-luca-cari-virginia-piccolillo-9788804749097\/"},"modified":"2026-03-14T02:53:26","modified_gmt":"2026-03-14T01:53:26","slug":"apnea-luca-cari-virginia-piccolillo-9788804749097","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/","title":{"rendered":"apnea"},"content":{"rendered":"<p>Albi. Andre. Bartolo. Beppe. Bronco. Lallo. Massi. Trap. Sono i soprannomi degli <strong>otto pompieri saliti a bordo della <\/strong><em><strong>Costa Concordia<\/strong><\/em> mentre imbarcava acqua dopo un inchino suicida a soli novanta metri dall&#8217;isola del Giglio, all&#8217;altezza degli scogli della Gabbianara. <strong>Era il 13 gennaio 2012<\/strong>, ultima tappa della crociera <em>Profumo d&#8217;agrumi<\/em>.<\/p>\n<p>In <em>Apnea<\/em>, per la prima volta, la tragedia della <em>Concordia <\/em>viene raccontata dalla viva voce di chi ha strappato a morte certa centinaia di persone ferite, intrappolate, smarrite e in molti casi abbandonate a loro stesse durante le manovre di evacuazione.<\/p>\n<p>Nessuno di quei vigili del fuoco altamente specializzati vuole oggi sentirsi chiamare eroe, perch&eacute; chi fa quel mestiere &egrave; allenato nel corpo e nella mente ad affrontare situazioni drammatiche e lo vive come la normalit&agrave;. Eppure leggendo le gesta di questi uomini, resi ciechi dal buio della notte e frustati dal mare mosso, &egrave; evidente che hanno compiuto qualcosa di eccezionale, di totalmente al di fuori della norma.<\/p>\n<p>Mentre l&#8217;enorme scafo della <em>Concordia<\/em> scivolava verso il fondo del mare con scricchiolii e spaventosi tonfi, in completo blackout e inclinata sul lato di dritta, gli otto pompieri <strong>hanno dato anima, cuore e braccia per individuare e soccorrere tutti i sopravvissuti<\/strong> che non erano riusciti a mettersi in salvo dopo l&#8217;ordine di abbandonare la nave.<\/p>\n<p><strong>Sempre in squadra, lavorando senza tregua, senza rifiatare un solo istante, ricorrendo anche alla fantasia<\/strong> di fronte agli ostacoli imprevedibili, <strong>trascinando di peso persone<\/strong> immobilizzate e terrorizzate, Albi, Andre, Bartolo, Beppe, Bronco, Lallo, Massi e Trap hanno soccorso, aiutato e liberato gli involontari prigionieri del disastro nautico, fermandosi solo quando il loro comandante ha decretato la fine dell&#8217;operazione.<\/p>\n<p>A distanza di dieci anni dall&#8217;evento gli otto co-protagonisti, insieme al loro comandante, <strong>svelano cosa &egrave; successo veramente dentro le viscere della <\/strong><em><strong>Costa Concordia<\/strong><\/em>, una citt&agrave; galleggiante che trasportava oltre quattromila persone fra passeggeri e personale di bordo. <strong>Un racconto corale coinvolgente, emozionante, tremendamente vero<\/strong>, che fino a ora &egrave; rimasto silenziosamente custodito soltanto nei loro cuori, in un&#8217;apnea della memoria.<\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>costa concordia &#8211; 8 vigili del fuoco e l&#8217;impresa mai raccontata<\/p>\n<p class=\"autore\"><span>Author: <\/span>luca cari &#8211; virginia piccolillo<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>mondadori libri<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788804749097<\/p>\n","protected":false},"featured_media":132083,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3059],"product_tag":[],"class_list":{"0":"post-62645","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-essays-books-navigation-history-passenger-ships","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>apnea - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"apnea\" \/>\n<meta property=\"og:description\" content=\"Subtitle: costa concordia - 8 vigili del fuoco e l&#039;impresa mai raccontataAuthor: luca cari - virginia piccolilloPublisher: mondadori libriISBN: 9788804749097\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:53:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"764\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/apnea-luca-cari-virginia-piccolillo-9788804749097\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/apnea-luca-cari-virginia-piccolillo-9788804749097\\\/\",\"name\":\"apnea - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/apnea-luca-cari-virginia-piccolillo-9788804749097\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/apnea-luca-cari-virginia-piccolillo-9788804749097\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1.jpg\",\"datePublished\":\"2022-01-24T15:35:53+00:00\",\"dateModified\":\"2026-03-14T01:53:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/apnea-luca-cari-virginia-piccolillo-9788804749097\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/apnea-luca-cari-virginia-piccolillo-9788804749097\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/apnea-luca-cari-virginia-piccolillo-9788804749097\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1.jpg\",\"width\":500,\"height\":764},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/apnea-luca-cari-virginia-piccolillo-9788804749097\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"apnea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788804749097\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"apnea - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"apnea","og_description":"Subtitle: costa concordia - 8 vigili del fuoco e l'impresa mai raccontataAuthor: luca cari - virginia piccolilloPublisher: mondadori libriISBN: 9788804749097","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:53:26+00:00","og_image":[{"width":500,"height":764,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/","name":"apnea - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1.jpg","datePublished":"2022-01-24T15:35:53+00:00","dateModified":"2026-03-14T01:53:26+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1.jpg","width":500,"height":764},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/apnea-luca-cari-virginia-piccolillo-9788804749097\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"apnea"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788804749097","product_condition":"new"},"df_price":18,"df_sale_price":"","df_regular_price":18,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/apnea-costa-concordia-8-vigili-del-fuoco-e-l-impresa-mai-raccontata-cari-piccolillo-mondadori-1-196x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/62645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=62645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/132083"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=62645"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=62645"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=62645"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=62645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}