{"id":62470,"date":"2022-04-29T12:42:47","date_gmt":"2022-04-29T10:42:47","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/"},"modified":"2026-03-14T02:47:08","modified_gmt":"2026-03-14T01:47:08","slug":"i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/","title":{"rendered":"i lavori di ricupero della r. n. leonardo da vinci (1920)"},"content":{"rendered":"<p><strong>Il 2 Agosto 1916 affonda ribaltandosi, nel porto di Taranto, la nuovissima corazzata da 24.000 tonnellate Leonardo da Vinci<\/strong>, vittima di un <strong>presunto sabotaggio<\/strong> che intrappoler&agrave; <strong>249 uomini<\/strong>.<\/p>\n<p>Il locale Regio Arsenale Militare Marittimo viene incaricato di <strong>affrontare un recupero mai affrontato prima per imponenza e difficolt&agrave;<\/strong>, dando inizio a un&rsquo;<strong>avventura eccezionale di quasi due anni e mezzo<\/strong> che l&rsquo;Ing. Odoardo Giannelli, T. Colonnello del Genio Navale della Regia Marina, racconta agilmente nella sua relazione che all&rsquo;epoca fu punto di riferimento per le Marine di tutto il mondo.<\/p>\n<p>La relazione &ldquo;I lavori di ricupero della R. N. Leonardo da Vinci&rdquo; del T. Col. del Genio Navale Ing. Odoardo Giannelli &egrave; quindi un <strong>documento tecnico di altissimo spessore e ricchissimo di dati, schemi, con una minuziosa analisi dei costi<\/strong>. Ma non &egrave; solo questo, in quanto il lettore attento riuscir&agrave; anche a prendere atto della <strong>elevata professionalit&agrave;, forte determinazione e senso di appartenenza di tutti coloro che hanno partecipato all&rsquo;impresa<\/strong>. Qualit&agrave; queste che sono risultate determinanti per il successo di un&rsquo;operazione, che presentava cos&igrave; enormi difficolt&agrave;, da suscitare tante preoccupazioni e da indurre molti a dubitare sull&rsquo;esito finale.<\/p>\n<p><strong>Edita pochi mesi prima del raddrizzamento<\/strong> della corazzata nel Mar Piccolo (che ha ispirato anche il recupero della Costa Concordia), avvenuto nel successivo Febbraio 1921, <strong>la relazione di questa complessa impresa evidenzia il ruolo fondamentale del rinomato ingegno italiano<\/strong> in una operazione portata felicemente a termine nel Settembre 1919, tra la grande commozione generale e la bandiera nazionale che garriva a poppa.<\/p>\n<p><strong>Ristampa anastatica dell&#8217;originale<\/strong>, composta da <strong>156 fogli<\/strong> con inserite nel testo <strong>34 fotografie d&#8217;epoca<\/strong> e <strong>31 disegni tecnici di cui 24 tavole fuori formato<\/strong>, integrata da 34 nuove pagine.<\/p>\n<p><strong>Edizione limitata<\/strong> in 200 copie numerate.&nbsp;<\/p>\n<p><strong>Copia numero 54.<\/strong><\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>relazione del t. colonnello del genio navale ing. odoardo giannelli capo dell&#8217;ufficio lavori ricupero r. n. leonardo da vinci<\/p>\n<p class=\"autore\"><span>Author: <\/span>a cura di faustolo rambelli &#8211; alessandro scuotto<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>editrice la mandragora<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788875866747<\/p>\n","protected":false},"featured_media":134098,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3055,3086],"product_tag":[],"class_list":{"0":"post-62470","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-miscellaneous","7":"product_cat-shipwrecks","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>i lavori di ricupero della r. n. leonardo da vinci (1920) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"i lavori di ricupero della r. n. leonardo da vinci (1920)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: relazione del t. colonnello del genio navale ing. odoardo giannelli capo dell&#039;ufficio lavori ricupero r. n. leonardo da vinciAuthor: a cura di faustolo rambelli - alessandro scuottoPublisher: editrice la mandragoraISBN: 9788875866747\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:47:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"513\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;130,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\\\/\",\"name\":\"i lavori di ricupero della r. n. leonardo da vinci (1920) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6.jpg\",\"datePublished\":\"2022-04-29T10:42:47+00:00\",\"dateModified\":\"2026-03-14T01:47:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6.jpg\",\"width\":513,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"i lavori di ricupero della r. n. leonardo da vinci (1920)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"130.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788875866747\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"i lavori di ricupero della r. n. leonardo da vinci (1920) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"i lavori di ricupero della r. n. leonardo da vinci (1920)","og_description":"Subtitle: relazione del t. colonnello del genio navale ing. odoardo giannelli capo dell'ufficio lavori ricupero r. n. leonardo da vinciAuthor: a cura di faustolo rambelli - alessandro scuottoPublisher: editrice la mandragoraISBN: 9788875866747","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:47:08+00:00","og_image":[{"width":513,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;130,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/","name":"i lavori di ricupero della r. n. leonardo da vinci (1920) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6.jpg","datePublished":"2022-04-29T10:42:47+00:00","dateModified":"2026-03-14T01:47:08+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6.jpg","width":513,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-a-cura-di-faustolo-rambelli-alessandro-scuotto-9788875866747\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"i lavori di ricupero della r. n. leonardo da vinci (1920)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"130.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788875866747","product_condition":"new"},"df_price":130,"df_sale_price":"","df_regular_price":130,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lavori-di-ricupero-della-r-n-leonardo-da-vinci-1920-giannelli-rambelli-scuotto-6-220x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/62470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=62470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/134098"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=62470"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=62470"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=62470"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=62470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}