{"id":62434,"date":"2022-05-24T18:28:30","date_gmt":"2022-05-24T16:28:30","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/"},"modified":"2026-03-14T02:44:13","modified_gmt":"2026-03-14T01:44:13","slug":"hornblower-ammiraglio-cecil-scott-forester-9788817162791","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/","title":{"rendered":"hornblower ammiraglio"},"content":{"rendered":"<div class=\"cc-content-text cc-clamp cc-clamp--7 cc-open\">\n<p>Dopo una trentennale carriera nella Marina Britannica, <strong>Horatio Hornblower ha ottenuto il grado di Ammiraglio<\/strong> e viene inviato nei Caraibi, in qualit&agrave; di comandante in capo delle navi e dei vascelli di Sua Maest&agrave; nelle Indie Occidentali. Ma prima di arrivarci, a New Orleans, <strong>dovr&agrave; affrontare una cospirazione di esuli francesi <\/strong>guidati dal generale Cambronne <strong>che intende liberare Napoleone <\/strong>in esilio a Sant&#8217;Elena. La sua missione nei Caraibi &egrave; costellata di sfide e pericoli: dalle <strong>navi cariche di schiavi<\/strong> che tenta di fermare fino ai <strong>pirati <\/strong>che infestano le coste del Sud America. Dando sempre prova delle caratteristiche che ne hanno fatto un eroe indimenticabile delle storie di marina (acume, coraggio, senso dell&#8217;onore)<strong> l&#8217;Ammiraglio andr&agrave; incontro al suo destino di grandezza<\/strong>, forte del rispetto di quelli che combattono sotto di lui. E quando, al termine del suo comando, Hornblower potr&agrave; infine dirigersi verso casa in compagnia della moglie Barbara, <strong>la natura lo metter&agrave; di fronte a un&#8217;ultima terribile prova<\/strong>, in cui dovr&agrave; dimostrare tutto il suo coraggio e la sua abnegazione per salvarsi insieme alla donna che ama.<\/p>\n<p>Edizione: 2022<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>l&#8217;ultima avventura<\/p>\n<p class=\"autore\"><span>Author: <\/span>cecil scott forester<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>bur (rizzoli)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788817162791<\/p>\n","protected":false},"featured_media":130886,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3042,2809],"product_tag":[],"class_list":{"0":"post-62434","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-narrative-modern-era","7":"product_cat-novels","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>hornblower ammiraglio - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"hornblower ammiraglio\" \/>\n<meta property=\"og:description\" content=\"Subtitle: l&#039;ultima avventuraAuthor: cecil scott foresterPublisher: bur (rizzoli)ISBN: 9788817162791\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:44:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\\\/\",\"name\":\"hornblower ammiraglio - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4.jpg\",\"datePublished\":\"2022-05-24T16:28:30+00:00\",\"dateModified\":\"2026-03-14T01:44:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4.jpg\",\"width\":500,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"hornblower ammiraglio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788817162791\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"hornblower ammiraglio - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"hornblower ammiraglio","og_description":"Subtitle: l'ultima avventuraAuthor: cecil scott foresterPublisher: bur (rizzoli)ISBN: 9788817162791","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:44:13+00:00","og_image":[{"width":500,"height":768,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/","name":"hornblower ammiraglio - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4.jpg","datePublished":"2022-05-24T16:28:30+00:00","dateModified":"2026-03-14T01:44:13+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4.jpg","width":500,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/hornblower-ammiraglio-cecil-scott-forester-9788817162791\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"hornblower ammiraglio"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788817162791","product_condition":"new"},"df_price":14,"df_sale_price":"","df_regular_price":14,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/hornblower-ammiraglio-l-ultima-avventura-cecil-scott-forester-bur-4-195x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/62434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=62434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/130886"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=62434"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=62434"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=62434"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=62434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}