{"id":62257,"date":"2022-07-16T18:08:41","date_gmt":"2022-07-16T16:08:41","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/"},"modified":"2026-03-14T02:25:46","modified_gmt":"2026-03-14T01:25:46","slug":"da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/","title":{"rendered":"da poppa a prua"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Nistri-Lischi Editore del 1970 in ottimo stato di conservazione, collana diretta da Mauro Mancini &ldquo;Il Tagliamare&rdquo; 8. In-8, brossura illustrata a colori (con evidenti segni del tempo); 232 pp. ingiallite, con 44 tavole in nero fuori testo.<\/strong><\/p>\n<p>Dalla quarta di copertina:&nbsp;<em>Dobbiamo riportare alla dignit&agrave; dell&#8217;uomo comune un linguaggio che i timidi considerano spesso un dialetto segreto.<\/em><\/p>\n<p><em>Pensiamo che sino a quando in Italia si creder&agrave; nell&#8217;esistenza del&nbsp;<\/em>Pappafico&nbsp;<em>o si chiamer&agrave;&nbsp;<\/em>Tolda&nbsp;<em>il ponte di una nave e i suoi fianchi&nbsp;<\/em>Babordo<em> e&nbsp;<\/em>Tribordo<em>, fino a che dura questa musica, rimarremo tutti dei falsi marinai, un popolo&nbsp;<\/em>marittimo&nbsp;<em>per costrizione geografica e senza credenze.<\/em><\/p>\n<p><em>Non ci siamo persi in ricerche etimologiche o in nobilitanti prospezioni lessicali, ma siamo andati al sodo inventariando un patrimonio di parole. L&#8217;inventario porta con s&eacute; significati vivi e senza distrazioni. Occorreva cominciare da qui.<\/em><\/p>\n<p><em>Eccovi infatti una lingua bellissima.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>dizionario nautico<\/p>\n<p class=\"autore\"><span>Author: <\/span>pompeo aloisi de larderel<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>nistri-lischi editori<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1657987720<\/p>\n","protected":false},"featured_media":121502,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2628,2606],"product_tag":[],"class_list":{"0":"post-62257","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dictionaries-encyclopedias-and-vocabularies","7":"product_cat-encyclopedias-atlases-and-handbooks","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>da poppa a prua - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"da poppa a prua\" \/>\n<meta property=\"og:description\" content=\"Subtitle: dizionario nauticoAuthor: pompeo aloisi de larderelPublisher: nistri-lischi editoriISBN: LDM1657987720\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"551\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;10,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\\\/\",\"name\":\"da poppa a prua - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970.jpg\",\"datePublished\":\"2022-07-16T16:08:41+00:00\",\"dateModified\":\"2026-03-14T01:25:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970.jpg\",\"width\":551,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"da poppa a prua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"10.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1657987720\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"da poppa a prua - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"da poppa a prua","og_description":"Subtitle: dizionario nauticoAuthor: pompeo aloisi de larderelPublisher: nistri-lischi editoriISBN: LDM1657987720","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:25:46+00:00","og_image":[{"width":551,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;10,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/","name":"da poppa a prua - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970.jpg","datePublished":"2022-07-16T16:08:41+00:00","dateModified":"2026-03-14T01:25:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970.jpg","width":551,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/da-poppa-a-prua-pompeo-aloisi-de-larderel-ldm1657987720\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"da poppa a prua"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"10.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1657987720","product_condition":"new"},"df_price":10,"df_sale_price":"","df_regular_price":10,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/da-poppa-a-prua-dizionario-nautico-pompeo-aloisi-de-larderel-nistri-lischi-1970-236x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/62257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=62257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/121502"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=62257"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=62257"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=62257"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=62257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}