{"id":61171,"date":"2022-07-04T16:24:31","date_gmt":"2022-07-04T14:24:31","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-ldm1656944669\/"},"modified":"2026-03-14T02:29:57","modified_gmt":"2026-03-14T01:29:57","slug":"relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/","title":{"rendered":"relazioni di viaggio e lettere di cristoforo colombo (1493-1506)"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Valentino Bompiani &amp; C. del 1941 (Anno XIX dell&#8217;era fascista) in ottimo stato di conservazione, collana &ldquo;Grandi ritorni&rdquo; 86 (Romanzi, autobiografie, memorie, mamoriali e documenti). In-8, legatura editoriale telata grigia (con tracce di fioritura al taglio superiore e al piatto posteriore) c<\/strong><strong>on incisioni arancio al piatto anteriore e al dorso; sovraccoperta in carta (visibilmente scolorita e logora ai tagli) illustrata in nero con alette (con lievi tracce di nastro adesivo); 376 pp., con annotazioni a matita ed ex libris di Emilio Delfino al risguardo anteriore, frontespirzio illustrato e stampato in nero e in rosso; con cartolina promozionale coeva, alcune illustrazioni in nero nel testo e alcune tavole in nero fuori testo.<\/strong><\/p>\n<p><strong>A cura di Rinaldo Caddeo.<\/strong><\/p>\n<p><strong>Introduzione di Rinaldo Caddeo.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore:&nbsp;<em>A quel mirabile documento che &egrave; il&nbsp;<\/em>Giornale di bordo<em>, da noi pubblicato l&#8217;anno scorso, facciamo seguire questo libro che contiene: 1. le relazioni di Colombo sui tre successivi viaggi da lui compiuti che condussero alla scoperta di Cuba e Giamaica, delle piccole Antille, della zona del Panama; 2. le relazioni sincrone di altri autori; 3. le lettere di Colombo sui suoi viaggi e sulle sue disavventure private, e i suoi due testamenti.<\/em><\/p>\n<p><em>Se colla prima parte del&nbsp;<\/em>Giornale&nbsp;<em>che narra la scoperta del primo Mondo la figura del Navigatore campeggia in tutta la sua grandezza imponendosi agli uomini, agli elementi e quasi diremmo al destino, nelle parti che si riferiscono agli altri viaggi, nelle lettere e nelle relazioni sincrone di altri autori si rivela un nuovo impressionante aspetto dell&#8217;Eroe, la sua dolorosa, angosciata e tormentata umanit&agrave;. Quanta incomprensione intorno a lui, di sovrani, di magnati, di prelati, di marinai! Quando invidia per gli onori ed i vantaggi concessigli, per la qualit&agrave; di straniero, per l&#8217;alta coscienza del dovere che lo fa inflessibile verso gli altri come verso se stesso! Le evidenti reazioni alle quali, suo malgrado, &egrave; indotto dalla enormit&agrave; delle offese di cui &egrave; vittima, i gridi incontenibili dell&#8217;anima esulcerata, la tortura delle carni distrutte dalla fatica e dalla dedizione completa al dovere assunto, si manifestano in Colombo con tale comunicativa evidenza da darci brividi di sofferenza quasi fisica.<\/em><\/p>\n<p><em>Queste pagine che possono ben dirsi ignorate dal pubblico perch&egrave; o non mai tradotte in italiano o confinate inopere riservate agli eruditi, e che perci&ograve; debbono essere considerate come nuove, costituiranno, ne siamo certi, una vera rivelazione: rivelazione di uno spirito eccelso e nobilissimo al quale non tanto il compimento di uno dei pi&ugrave; importanti fatti che la storia conosca quanto la sopportazione di un ineffabile dolore conferisce un motivo di autentica e luminosa grandezza.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>bompiani<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1656944669<\/p>\n","protected":false},"featured_media":129139,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815,3026,2805,2607],"product_tag":[],"class_list":{"0":"post-61171","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anthologies-and-letters","7":"product_cat-christopher-columbus","8":"product_cat-logbooks-and-travel-reports","9":"product_cat-narrative","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>relazioni di viaggio e lettere di cristoforo colombo (1493-1506) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"relazioni di viaggio e lettere di cristoforo colombo (1493-1506)\" \/>\n<meta property=\"og:description\" content=\"Author: aa.vv.Publisher: bompianiISBN: LDM1656944669\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:29:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"502\" \/>\n\t<meta property=\"og:image:height\" content=\"764\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;35,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\\\/\",\"name\":\"relazioni di viaggio e lettere di cristoforo colombo (1493-1506) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10.jpg\",\"datePublished\":\"2022-07-04T14:24:31+00:00\",\"dateModified\":\"2026-03-14T01:29:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10.jpg\",\"width\":502,\"height\":764},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"relazioni di viaggio e lettere di cristoforo colombo (1493-1506)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"35.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1656944669\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"relazioni di viaggio e lettere di cristoforo colombo (1493-1506) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"relazioni di viaggio e lettere di cristoforo colombo (1493-1506)","og_description":"Author: aa.vv.Publisher: bompianiISBN: LDM1656944669","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:29:57+00:00","og_image":[{"width":502,"height":764,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;35,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/","name":"relazioni di viaggio e lettere di cristoforo colombo (1493-1506) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10.jpg","datePublished":"2022-07-04T14:24:31+00:00","dateModified":"2026-03-14T01:29:57+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10.jpg","width":502,"height":764},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-aa-vv-ldm1656944669\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"relazioni di viaggio e lettere di cristoforo colombo (1493-1506)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"35.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1656944669","product_condition":"new"},"df_price":35,"df_sale_price":"","df_regular_price":35,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/relazioni-di-viaggio-e-lettere-di-cristoforo-colombo-1493-1506-bompiani-10-197x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/61171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=61171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/129139"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=61171"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=61171"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=61171"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=61171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}