{"id":61144,"date":"2022-07-02T17:38:56","date_gmt":"2022-07-02T15:38:56","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/"},"modified":"2026-03-14T02:30:08","modified_gmt":"2026-03-14T01:30:08","slug":"salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/","title":{"rendered":"salmoni castori e lontre"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Longanesi &amp; C. del 1979 in ottimo stato di conservazione, collezione &ldquo;La vostra via sportiva&rdquo; 63. In-8, legatura editoriale telata blu con impressioni oro al dorso; sovraccoperta in carta (ingiallita e con qualche segno del tempo) illustrata a colori con alette; 304 pp., con ex libris a penna al risguardo anteriore, 24 illustrazioni e 4 cartine in nero e 129 fotografie a colori nel testo.<\/strong><\/p>\n<p><strong>Traduzione di Anna Silva.<\/strong><\/p>\n<p>Dalla quarta di copertina: <em>Tre nuove appassionanti avventure degli uomini della&nbsp;<\/em>Calypso<em>. La prima ha come scena una sperduta isola dell&#8217;Alasca e come eroe il salmone rosso. Guidati da sensi misteriosi e spinti avanti dalla forza implacabile dell&#8217;istinto, questi superbi pesci tornano al torrente natio dopo molti anni trascorsi nell&#8217;oceano. Nulla li ferma, nella loro corsa verso un tragico destino: perpetuare la specie e poi morire. Il secondo episodio si svolge nel Grande Nord canadese. In una capanna costruita con le loro stesse mani, Cousteau e i suoi compagni trascorrono un intero inverno nel paese dei castori. Questi ingegneri del mondo animale, che scavano canali e gallerie sotterranee, costruiscono capanne di rami e frasche ed elevano dighe sui fiumi, costituiscono un altro mistero della natura. I salmoni sono dei semplici automi, dei robot biologici programmati per l&#8217;evoluzione: &egrave; questo il caso anche dei castori oppure possiamo intravedere, presso questi roditori, un principio d&#8217;intelligenza? Con la lontra di mare, studiata sia in Alasca sia in California, non vi sono pi&ugrave; dubbi: &egrave; un&#8217;autentica intelligenza animale quella che i sub della&nbsp;<\/em>Calypso<em> incontrano. Bella, scaltra, dotata della pi&ugrave; preziosa pelliccia del mondo, affettuosa, scherzosa, felice di vivere e pacifica, essa &egrave; una delle rare specie che sanno servirsi di utensili&#8230; Il comandante Cousteau e la sua &eacute;quipe, attraverso questi tre esempi, hanno inteso studiare una&nbsp;<\/em>ascesa verso l&#8217;intelligenza<em>. Ma per loro &egrave; stata anche l&#8217;occasione per sorprendere molti altri animali in libert&agrave; (orsi, aquile, lupi, civette delle nevi, volpi, foche, otarie, orche, uccelli marini) e per tracciare un bilancio ecologico delle regioni percorse.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>jacques-yves cousteau &#8211; yves paccalet<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>longanesi <\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1656776335<\/p>\n","protected":false},"featured_media":135835,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,2997,2589,2608],"product_tag":[],"class_list":{"0":"post-61144","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-narrative-narrative-and-essays","8":"product_cat-books-diving-literature","9":"product_cat-reports-and-essays","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>salmoni castori e lontre - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"salmoni castori e lontre\" \/>\n<meta property=\"og:description\" content=\"Author: jacques-yves cousteau - yves paccaletPublisher: longanesi ISBN: LDM1656776335\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:30:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"525\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;35,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\\\/\",\"name\":\"salmoni castori e lontre - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi.jpg\",\"datePublished\":\"2022-07-02T15:38:56+00:00\",\"dateModified\":\"2026-03-14T01:30:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi.jpg\",\"width\":525,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"salmoni castori e lontre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"35.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1656776335\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"salmoni castori e lontre - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"salmoni castori e lontre","og_description":"Author: jacques-yves cousteau - yves paccaletPublisher: longanesi ISBN: LDM1656776335","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:30:08+00:00","og_image":[{"width":525,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;35,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/","name":"salmoni castori e lontre - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi.jpg","datePublished":"2022-07-02T15:38:56+00:00","dateModified":"2026-03-14T01:30:08+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi.jpg","width":525,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-ldm1656776335\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"salmoni castori e lontre"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"35.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1656776335","product_condition":"new"},"df_price":35,"df_sale_price":"","df_regular_price":35,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/salmoni-castori-e-lontre-jacques-yves-cousteau-yves-paccalet-longanesi-225x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/61144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=61144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/135835"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=61144"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=61144"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=61144"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=61144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}