{"id":61124,"date":"2022-07-02T16:41:36","date_gmt":"2022-07-02T14:41:36","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/"},"modified":"2026-03-14T02:30:18","modified_gmt":"2026-03-14T01:30:18","slug":"tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/","title":{"rendered":"tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau)"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Longanesi &amp; C. del 1973 in perfetto stato di conservazione, collezione &ldquo;La vostra via sportiva&rdquo; 33. In-8, legatura editoriale telata blu con incisioni oro al dorso; sovraccoperta in carta illustrata a colori con alette; 304 pp., con 37 illustrazioni in nero, 8 cartine in nero e 116 fotografie a colori nel testo.<\/strong><\/p>\n<p><strong>Traduzione di Elena Bona.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore:&nbsp;<em>Il comandante Cousteau con una squadra rinnovata di scienziati avventurosi e di sub, con grande rischio personale, esplora tre dei fenomeni sottomarini pi&ugrave; straordinari, aggiungendo con questa narrazione un altro best-seller ai cinque titoli gi&agrave; pubblicati. Nell&#8217;arcipelago delle Galapagos, dove nacquero le teorie di Darwin, i sommozzatori scoprono i segreti dell&#8217;iguana marina, una gigantesca lucertola, per cos&igrave; dire, capace a volont&agrave; di sospendere i battiti del proprio cuore. mentre &egrave; nelle profondit&agrave; oceaniche. La seconda avventura riguarda il lago Titicaca che come tutti sanno &egrave; il pi&ugrave; alto al mondo e dai fondali finora sconosciuti, dove si crede giacciano ancora i tesori degli inca. Infine Cousteau e i suoi uomini si spingono nelle misteriose&nbsp;<\/em>buche azzurre<em> dell&#8217;Honduras britannico e delle Bahama, un enorme anello di coralli, composto di gallerie senza uscita, di labirinti e di abissi che possono inghiottire per sempre gli esploratori.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>galapagos &#8211; titicaca &#8211; buche azzurre<\/p>\n<p class=\"autore\"><span>Author: <\/span>jacques-yves cousteau &#8211; philippe diol\u00e9<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>longanesi <\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1656772895<\/p>\n","protected":false},"featured_media":127043,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815,2805,2997,2589,2608],"product_tag":[],"class_list":{"0":"post-61124","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anthologies-and-letters","7":"product_cat-logbooks-and-travel-reports","8":"product_cat-narrative-narrative-and-essays","9":"product_cat-books-diving-literature","10":"product_cat-reports-and-essays","12":"first","13":"outofstock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: galapagos - titicaca - buche azzurreAuthor: jacques-yves cousteau - philippe diol\u00e9Publisher: longanesi ISBN: LDM1656772895\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:30:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;45,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\\\/\",\"name\":\"tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3.jpg\",\"datePublished\":\"2022-07-02T14:41:36+00:00\",\"dateModified\":\"2026-03-14T01:30:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3.jpg\",\"width\":500,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"45.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1656772895\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau)","og_description":"Subtitle: galapagos - titicaca - buche azzurreAuthor: jacques-yves cousteau - philippe diol\u00e9Publisher: longanesi ISBN: LDM1656772895","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:30:18+00:00","og_image":[{"width":500,"height":744,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;45,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/","name":"tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3.jpg","datePublished":"2022-07-02T14:41:36+00:00","dateModified":"2026-03-14T01:30:18+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3.jpg","width":500,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tre-avventure-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656772895\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"tre avventure (le esplorazioni sottomarine di Jacques-Yves Cousteau)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"45.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1656772895","product_condition":"new"},"df_price":45,"df_sale_price":"","df_regular_price":45,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tre-avventure-galapagos-titicaca-buche-azzurre-jacques-yves-cousteau-philippe-diole-longanesi-1973-3-202x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/61124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=61124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/127043"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=61124"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=61124"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=61124"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=61124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}